{"id":101498,"date":"2019-04-23T12:18:42","date_gmt":"2019-04-23T15:18:42","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=101498"},"modified":"2019-04-23T12:18:42","modified_gmt":"2019-04-23T15:18:42","slug":"mortal-kombat-11-como-ativar-o-mercy-durante-as-lutas","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/mortal-kombat-11-como-ativar-o-mercy-durante-as-lutas\/","title":{"rendered":"Mortal Kombat 11: Como ativar o MERCY durante as lutas"},"content":{"rendered":"<h5 style=\"text-align: center;\">Mortal Kombat 11 trouxe um aspecto cl\u00e1ssico da franquia de volta, e os jogadores est\u00e3o explorando ele<\/h5>\n<p>Enfim <strong>Mortal Kombat 11<\/strong> est\u00e1 entre n\u00f3s, e diversos segredos sobre o game est\u00e3o surgindo. Sejam relacionados ao modo Kripta, ou at\u00e9 mesmo as lutas convencionais, ainda h\u00e1 muito o que ser desbravado pelos jogadores. E isso inclui a nova modalidade Mercy, que tem deixado os lutadores de &#8220;<em>cabelo em p\u00e9<\/em>&#8221; tentando descobrir sua finalidade.<\/p><div id=\"combo-1707753386\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Como declarado previamente pela NetherRealm Studios, a denominada &#8220;<em>segunda chance<\/em>&#8221; para o oponente cont\u00e9m alguns segredos s\u00f3rdidos. Mas infelizmente s\u00e3o poucos que conseguem ativar com propriedade a miseric\u00f3rdia do game.<\/p>\n<p>Dito isso, n\u00f3s do Combo Infinito revelamos a sequ\u00eancia necess\u00e1ria para realizar o Mercy no jogo. Esta ent\u00e3o ser\u00e1 executada sob as seguintes condi\u00e7\u00f5es:<\/p>\n<ul>\n<li>\u00c9 necess\u00e1rio que o jogador esteja pr\u00f3ximo de realizar um Fatality (durante a tela que diz FINISH HIM\/HER)<\/li>\n<li>Neste momento, a uma dist\u00e2ncia M\u00c9DIA, basta <strong>segurar<\/strong> <strong>L2<\/strong> (no caso do PS4) ou <strong>LT<\/strong> (no caso do XOne) e apertar <strong>BAIXO tr\u00eas vezes<\/strong>.<\/li>\n<\/ul>\n<p>Com os requisitos preenchidos e o comando feito propriamente, seu advers\u00e1rio &#8211; quase morto &#8211; recuperar\u00e1 parte da vida e voltar\u00e1 ao combate. No entanto, isso tamb\u00e9m desbloqueia Brutalities \u00fanicos para os lutadores, acarretando em uma possibilidade de tentativa nesta segunda chance.<\/p><div id=\"combo-1233961843\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Ainda n\u00e3o sabemos qual o escopo que envolve o modo Mercy, mas no momento, ao menos sabemos como realiza-lo.<\/p>\n<p>Em conclus\u00e3o, Mortal Kombat 11 j\u00e1 est\u00e1 dispon\u00edvel com vers\u00f5es para Xbox One, PS4, PC e Nintendo Switch.<\/p>\n<hr \/>\n<p>Fonte: <a href=\"https:\/\/comicbook.com\/gaming\/2019\/04\/23\/mortal-kombat-11-how-to-show-mercy\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>ComicBook<\/strong><\/a><\/p><div id=\"combo-1322535140\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-2362677887\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Mortal Kombat 11 trouxe um aspecto cl\u00e1ssico da franquia de volta, e os jogadores est\u00e3o explorando ele Enfim Mortal Kombat 11 est\u00e1 entre n\u00f3s, e diversos segredos sobre o game est\u00e3o surgindo. Sejam relacionados ao modo Kripta, ou at\u00e9 mesmo as lutas convencionais, ainda h\u00e1 muito o que ser desbravado pelos jogadores. E isso inclui [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":101500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,50,10258,25,12298,36,5,2612,241,49,8],"tags":[27620,27619,27618,444,227,8999,26937,26936,4075,20017,24055,27208,20018,26935,16881,24053,26938,24399,24056,24565,26493,24398,16910,24094,27207,26730,6962,24054,26421,26728,1155,5889,3840,26190,24092,24093,27205,27206,26729],"class_list":["post-101498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-nintendo-2","category-nintendo-switch","category-pcgames","category-plataformas","category-playstation","category-ps4","category-steam-pcgames","category-todas","category-xbox","category-xboxone","tag-como-fazer-mercy","tag-como-fazer-mercy-mk11","tag-como-fazer-mercy-mortal-kombat-11","tag-ed-boon","tag-fatality","tag-jogo-de-luta","tag-kripta-mk11","tag-krypt","tag-mk","tag-mk-11","tag-mk-11-historia","tag-mk-shaolin-monks","tag-mk-xi","tag-mk11-shang-tsung","tag-mortal-kombat-11","tag-mortal-kombat-11-historia","tag-mortal-kombat-11-kripta","tag-mortal-kombat-11-mercy","tag-mortal-kombat-11-personagens","tag-mortal-kombat-11-shang-tsung","tag-mortal-kombat-3-ultimate-ps2-golpes-e-fatalities","tag-mortal-kombat-mercy","tag-mortal-kombat-shaolin-monks","tag-mortal-kombat-shaolin-monks-2","tag-mortal-kombat-shaolin-monks-remaster","tag-mortal-kombat-toasty","tag-mortal-kombat-x-novidades","tag-mortal-kombat-xi-historia","tag-mortal-kombat-xl-noticias","tag-mortal-kombat-xl-novidades","tag-netherrealm","tag-netherrealm-studios","tag-novo-mortal-kombat","tag-shang-tsung-mk11","tag-shaolin-monks","tag-shaolin-monks-2","tag-shaolin-monks-ps2","tag-shaolin-monks-remaster","tag-ultimate-mortal-kombat-3-snes-rom"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mortal Kombat 11: Como ativar o MERCY durante as lutas - Combo Infinito<\/title>\n<meta name=\"description\" content=\"O rec\u00e9m-chegado Mortal Kombat 11 trouxe consigo grandes elementos cl\u00e1ssicos da franquia, e dentre eles, tivemos o retorno do Mercy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/mortal-kombat-11-como-ativar-o-mercy-durante-as-lutas\/\" \/>\n<meta name=\"author\" content=\"Guru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/mortal-kombat-11-como-ativar-o-mercy-durante-as-lutas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mortal Kombat 11: Como ativar o MERCY durante as lutas\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mortal Kombat 11: Como ativar o MERCY durante as lutas - Combo Infinito","description":"O rec\u00e9m-chegado Mortal Kombat 11 trouxe consigo grandes elementos cl\u00e1ssicos da franquia, e dentre eles, tivemos o retorno do Mercy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/mortal-kombat-11-como-ativar-o-mercy-durante-as-lutas\/","author":"Guru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/mortal-kombat-11-como-ativar-o-mercy-durante-as-lutas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Mortal Kombat 11: Como ativar o MERCY durante as lutas"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/101498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=101498"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/101498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/101500"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=101498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=101498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=101498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}