{"id":10188,"date":"2014-05-12T01:48:34","date_gmt":"2014-05-12T04:48:34","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=10188"},"modified":"2016-06-25T22:07:25","modified_gmt":"2016-06-26T01:07:25","slug":"ea-vai-encerrar-o-suporte-online-de-mais-de-50-titulos-em-junho","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/ea-vai-encerrar-o-suporte-online-de-mais-de-50-titulos-em-junho\/","title":{"rendered":"EA vai encerrar o suporte online de mais de 50 t\u00edtulos em junho"},"content":{"rendered":"<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-10191 alignnone\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho.jpg\" alt=\"EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho\" width=\"896\" height=\"504\" data-wp-pid=\"10191\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/05\/EA-vai-encerrar-o-suporte-online-de-mais-de-50-t\u00edtulos-em-junho-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p>Cinquenta t\u00edtulos dentre as\u00a0numerosas franquias e plataformas &#8211; <strong>Battlefield 2<\/strong> e <strong>Crysis 2<\/strong> para <strong>PC<\/strong> &#8211; v\u00e3o\u00a0ficar offline no dia 30 de junho devido ao baixo n\u00famero de jogadores on-line, de acordo com uma atualiza\u00e7\u00e3o de servi\u00e7o da <a href=\"http:\/\/www.ea.com\/1\/service-updates\" target=\"_blank\"><strong>EA na\u00a0p\u00e1gina de suporte<\/strong><\/a><strong>.<\/strong><\/p><div id=\"combo-2836398029\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">&#8220;<em>Mas como os jogos s\u00e3o substitu\u00eddos com os t\u00edtulos mais recentes, o n\u00famero de jogadores que ainda aprecia os jogos mais antigos\u00a0diminui consideravelmente\u00a0&#8211; geralmente menos de 1%\u00a0de todos os jogadores on-line em todos os t\u00edtulos da EA &#8211; onde ele n\u00e3o \u00e9 mais vi\u00e1vel para continuar\u00a0a fazer\u00a0manuten\u00e7\u00f5es\u00a0desses jogos e mant\u00ea-los funcionando<\/em>&#8220;, diz o an\u00fancio. &#8220;<em>Preferimos que o\u00a0trabalho duro da nossa equipe de engenharia de TI\u00a0mantenha o foco para\u00a0uma experi\u00eancia positiva nos outros 99 por cento dos clientes que jogam nossos t\u00edtulos\u00a0mais populares.<\/em>&#8220;<\/p>\n<p style=\"text-align: justify;\">A Tecnologia\u00a0<strong>GameSpy<\/strong>, um servi\u00e7o que fornece aos jogadores funcionalidades como <em>leaderboards<\/em> e <em>matchmaking<\/em> a muitos t\u00edtulos, anunciou em abril que iria desligar seus\u00a0servi\u00e7os de hospedagem em 31 de maio. Foi inicialmente estabelecido que <strong>Star Wars: Battlefront 2<\/strong> e <strong>Star Wars: Empire at War &#8211; Gold Embale<\/strong>, tamb\u00e9m listados abaixo, cessariam opera\u00e7\u00f5es oficiais <em>on-line<\/em> quando o GameSpy for\u00a0desligado,\u00a0no entanto, foi confirmado recentemente que esses games continuar\u00e3o a funcionar gra\u00e7as ao apoio de terceiros.<\/p>\n<p style=\"text-align: justify;\">A lista completa dos t\u00edtulos programados para ficar offline em 30 de Junho s\u00e3o:<\/p><div id=\"combo-823774795\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<ul>\n<li>Battlefield 1942 para\u00a0PC e\u00a0Mac (incluindo expans\u00f5es)<\/li>\n<li>Battlefield 2 para\u00a0PC (incluindo expans\u00f5es)<\/li>\n<li>Battlefield 2: Modern Combat para\u00a0PlayStation 2<\/li>\n<li>Battlefield 2142 para\u00a0\u00a0PC e Mac (incluindo expans\u00f5es)<\/li>\n<li>Battlefield Vietnam para\u00a0PC<\/li>\n<li>Bejeweled 2 para Wii<\/li>\n<li>Bulletstorm para\u00a0PlayStation 3<\/li>\n<li>Command &amp; Conquer 3: Tiberium Wars para\u00a0PC e\u00a0Mac (incluindo expans\u00f5es)<\/li>\n<li>Command &amp; Conquer: Generals for PC e\u00a0Mac (incluindo expans\u00f5es)<\/li>\n<li>Command &amp; Conquer: Red Alert 3 para\u00a0PC e Mac<\/li>\n<li>Crysis 2 para\u00a0PC<\/li>\n<li>Crysis para\u00a0PC<\/li>\n<li>Crysis Wars para\u00a0PC<\/li>\n<li>Dracula \u2013 Undead Awakening para Wii<\/li>\n<li>Dragon Sakura para\u00a0Nintendo DS<\/li>\n<li>EA Sports 06 para\u00a0PC<\/li>\n<li>F1 2002 para\u00a0PC<\/li>\n<li>FIFA Soccer 08 (KOR) para Wii<\/li>\n<li>FIFA Soccer 08 para Nintendo DS<\/li>\n<li>FIFA Soccer 09 para\u00a0Nintendo DS<\/li>\n<li>FIFA Soccer 10 para\u00a0Nintendo DS<\/li>\n<li>FIFA Street 3 para\u00a0Nintendo DS<\/li>\n<li>Full Spectrum Warrior: Ten Hammers para\u00a0PlayStation 2<\/li>\n<li>Global Operations para\u00a0PC<\/li>\n<li>GREEN DAY: ROCK BAND para Wii<\/li>\n<li>James Bond: Nightfire para\u00a0PC<\/li>\n<li>Madden NFL 08 para\u00a0Nintendo DS<\/li>\n<li>Madden NFL 09 para\u00a0Nintendo DS<\/li>\n<li>Master of Orion III para\u00a0PC<\/li>\n<li>Medal of Honor: Allied Assault for PC e\u00a0Mac (inclui expans\u00f5es)<\/li>\n<li>MySims Party para\u00a0\u00a0Wii<\/li>\n<li>MySims Racing para\u00a0Nintendo DS<\/li>\n<li>MySims SkyHeroes para Wii e\u00a0DS<\/li>\n<li>NASCAR Sim Racing para\u00a0PC<\/li>\n<li>NASCAR Thunder 2003 para\u00a0PC<\/li>\n<li>NASCAR Thunder 2004 para\u00a0PC<\/li>\n<li>Need for Speed: Hot Pursuit 2 para\u00a0PC<\/li>\n<li>Need for Speed: ProStreet para\u00a0Nintendo DS<\/li>\n<li>Need for Speed: Undercover para\u00a0Nintendo DS<\/li>\n<li>Neverwinter Nights 2 para\u00a0PC e\u00a0Mac<\/li>\n<li>Neverwinter Nights para\u00a0PC, Mac e\u00a0Linux (inclui expans\u00f5es)<\/li>\n<li>SimCity Creator para\u00a0Wii<\/li>\n<li>Skate It para\u00a0Nintendo DS<\/li>\n<li>Sneezies para Wii<\/li>\n<li>Spore Creatures para\u00a0Nintendo DS<\/li>\n<li>Spore Hero Arena para\u00a0Nintendo DS<\/li>\n<li>Star Wars: Battlefront para\u00a0PC e\u00a0PlayStation 2<\/li>\n<li>Star Wars: Battlefront II para\u00a0PC e\u00a0PlayStation 2<\/li>\n<li>THE BEATLES: ROCK BAND para Wii<\/li>\n<li>Tiger Woods PGA Tour 08 para\u00a0Nintendo DS<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Acredito que os mais saudosistas podem ficar enfurecidos com essa not\u00edcia, mas a EA,\u00a0mercadologicamente falando, est\u00e1 no caminho certo. A grana e o suor que os caras v\u00e3o economizar,\u00a0podem ser muito significativos para que os t\u00edtulos mais novos e populares sejam melhor assistidos.<\/p>\n<p style=\"text-align: justify;\">E voc\u00eas meus caros <strong>Combonautas<\/strong>, o que acharam dessa not\u00edcia? Acham a atitude da EA correta? Ou acreditam que isso \u00e9 abandono de causa? Comentem suas ideias.<\/p>\n<div id=\"combo-33853174\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Cinquenta t\u00edtulos dentre as\u00a0numerosas franquias e plataformas &#8211; Battlefield 2 e Crysis 2 para PC &#8211; v\u00e3o\u00a0ficar offline no dia 30 de junho devido ao baixo n\u00famero de jogadores on-line, de acordo com uma atualiza\u00e7\u00e3o de servi\u00e7o da EA na\u00a0p\u00e1gina de suporte. &#8220;Mas como os jogos s\u00e3o substitu\u00eddos com os t\u00edtulos mais recentes, o n\u00famero [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298],"tags":[85,3664,3665,388,2844,3663,1417,73,54],"class_list":["post-10188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","tag-ea","tag-ea-encerra-atividades-online-de-jogos-antigos","tag-ea-encerra-suporte-online-de-50-jogos","tag-ea-games","tag-electronic-arts","tag-gamespy","tag-jogos-da-ea","tag-mac","tag-pc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EA vai encerrar o suporte online de mais de 50 t\u00edtulos em junho - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/ea-vai-encerrar-o-suporte-online-de-mais-de-50-titulos-em-junho\/\" \/>\n<meta name=\"author\" content=\"Alepitekus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/ea-vai-encerrar-o-suporte-online-de-mais-de-50-titulos-em-junho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EA vai encerrar o suporte online de mais de 50 t\u00edtulos em junho\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EA vai encerrar o suporte online de mais de 50 t\u00edtulos em junho - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/ea-vai-encerrar-o-suporte-online-de-mais-de-50-titulos-em-junho\/","author":"Alepitekus","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/ea-vai-encerrar-o-suporte-online-de-mais-de-50-titulos-em-junho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"EA vai encerrar o suporte online de mais de 50 t\u00edtulos em junho"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/10188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=10188"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/10188\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/10191"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=10188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=10188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=10188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}