{"id":12613,"date":"2014-07-29T16:09:55","date_gmt":"2014-07-29T19:09:55","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=12613"},"modified":"2016-06-25T22:04:15","modified_gmt":"2016-06-26T01:04:15","slug":"epic-games-lancou-um-video-mostrando-o-proximo-unreal-tournament","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/epic-games-lancou-um-video-mostrando-o-proximo-unreal-tournament\/","title":{"rendered":"Epic Games lan\u00e7ou um v\u00eddeo mostrando o pr\u00f3ximo Unreal Tournament"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-12614\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament.jpg\" alt=\"Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament\" width=\"896\" height=\"504\" data-wp-pid=\"12614\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/07\/Epic-Games-lancou-um-video-mostrando-o-proximo-Unreal-Tournament-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a>A maioria dos jogadores ter\u00e1\u00a0boas lembran\u00e7as de <strong>Unreal Tournament<\/strong>, e como <strong>Call Of Duty<\/strong> a cada ano demanda um shooter arcade cl\u00e1ssico, a <strong>Epic Games<\/strong> resolveu fazer um pequeno demonstrativo do seu pr\u00f3prio t\u00edtulo em produ\u00e7\u00e3o.<\/p><div id=\"combo-3704357851\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">A desenvolvedora lan\u00e7ou um v\u00eddeo demonstrando a jogabilidade, as etapas de cria\u00e7\u00e3o do game, e muita divers\u00e3o dentro do escrit\u00f3rio, enquanto testam o novo t\u00edtulo, que est\u00e1 no estado digamos &#8220;<em>alpha<\/em>&#8221; &#8211; jog\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">Essa demonstra\u00e7\u00e3o parece trazer de volta tudo o que viamos e gost\u00e1vamos na franquia contando com aquelas armas absurdamente potentes e malucas.<\/p>\n<p style=\"text-align: justify;\">Este \u00e9 o primeiro v\u00eddeo\u00a0que foi visto do jogo &#8211; fora alguns prot\u00f3tipos b\u00e1sicos\u00a0&#8211; uma vez que o desenvolvedor est\u00e1 optando por uma nova abordagem no desenvolvimento de <strong>Unreal Tournament<\/strong>. Os cen\u00e1rios ainda est\u00e3o bem crus, n\u00e3o tendo nenhum detalhe, apenas mesmo a colis\u00e3o para poderem ser feitos os testes.<\/p><div id=\"combo-2248063716\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">\u00c9 importante ressaltar que os f\u00e3s e\u00a0as comunidades estar\u00e3o envolvidos no processo todo.<\/p>\n<p style=\"text-align: justify;\">Recordar\u00a0Unreal \u00e9 voltar no t\u00fanel do tempo e lembrar de\u00a0\u00f3timos momentos. Era um jogo bem ousado e trouxe conceitos de <em>multiplayer<\/em> que s\u00e3o usados at\u00e9 hoje. Aguardo ansiosamente pela nova edi\u00e7\u00e3o. Assistam o v\u00eddeo logo abaixo e tirem suas pr\u00f3prias conclus\u00f5es.<\/p>\n<p style=\"text-align: justify;\">E a\u00ed meus caros, o que acharam dessa demonstra\u00e7\u00e3o? Eram f\u00e3s de Unreal Tournment? Comentem!<\/p><div id=\"combo-4090258197\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><iframe title=\"Unreal Tournament Team Deathmatch\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/P0FKjMhqEJI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-2869204969\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>A maioria dos jogadores ter\u00e1\u00a0boas lembran\u00e7as de Unreal Tournament, e como Call Of Duty a cada ano demanda um shooter arcade cl\u00e1ssico, a Epic Games resolveu fazer um pequeno demonstrativo do seu pr\u00f3prio t\u00edtulo em produ\u00e7\u00e3o. A desenvolvedora lan\u00e7ou um v\u00eddeo demonstrando a jogabilidade, as etapas de cria\u00e7\u00e3o do game, e muita divers\u00e3o dentro do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298],"tags":[2281,3636,4581,4583,4584,4585,4582],"class_list":["post-12613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","tag-epic-games","tag-unreal","tag-unreal-tournament","tag-unreal-tournament-gameplay","tag-unreal-tournament-jogabilidade","tag-unreal-tournament-primeiro-vislumbre","tag-video-unreal-tournament"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Epic Games lan\u00e7ou um v\u00eddeo mostrando o pr\u00f3ximo Unreal Tournament - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/epic-games-lancou-um-video-mostrando-o-proximo-unreal-tournament\/\" \/>\n<meta name=\"author\" content=\"Alepitekus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/epic-games-lancou-um-video-mostrando-o-proximo-unreal-tournament\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Epic Games lan\u00e7ou um v\u00eddeo mostrando o pr\u00f3ximo Unreal Tournament\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Epic Games lan\u00e7ou um v\u00eddeo mostrando o pr\u00f3ximo Unreal Tournament - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/epic-games-lancou-um-video-mostrando-o-proximo-unreal-tournament\/","author":"Alepitekus","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/epic-games-lancou-um-video-mostrando-o-proximo-unreal-tournament\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Epic Games lan\u00e7ou um v\u00eddeo mostrando o pr\u00f3ximo Unreal Tournament"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/12613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=12613"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/12613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/12614"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=12613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=12613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=12613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}