{"id":135683,"date":"2021-07-10T13:25:20","date_gmt":"2021-07-10T16:25:20","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=135683"},"modified":"2021-07-10T13:25:20","modified_gmt":"2021-07-10T16:25:20","slug":"pokemon-go-fatura-mais-de-us-5-bilhoes-cinco-anos-apos-lancamento","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/pokemon-go-fatura-mais-de-us-5-bilhoes-cinco-anos-apos-lancamento\/","title":{"rendered":"Pok\u00e9mon GO fatura mais de US$ 5 BILH\u00d5ES, cinco anos ap\u00f3s lan\u00e7amento"},"content":{"rendered":"<h5 style=\"text-align: center;\">Pok\u00e9mon GO se tornou um fen\u00f4meno digital desde o lan\u00e7amento, e j\u00e1 rendeu bilh\u00f5es em receita<\/h5>\n<p>Lan\u00e7ado em 2016, <strong>Pok\u00e9mon GO<\/strong> se tornou um dos maiores fen\u00f4menos respons\u00e1veis por revitalizar a franquia. Com a proposta m\u00f3vel de capturar criaturas conforme o jogador &#8220;<em>explora o mundo real<\/em>&#8220;, o game foi capaz de atrair n\u00e3o somente os f\u00e3s de longa data da franquia, como tamb\u00e9m abriu margem para que mais pessoas se apaixonassem por esse universo.<\/p><div id=\"combo-286463793\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>E se por um lado a experi\u00eancia para os consumidores tem rendido momentos divertidos, do outro, o t\u00edtulo certamente continua rendendo rios de dinheiros. Especificamente falando em valores, at\u00e9 o momento, Pok\u00e9mon GO j\u00e1 faturou mais de <strong>US$ 5 Bilh\u00f5es<\/strong> ao longo de sua vida \u00fatil. De acordo com as estat\u00edsticas cedidas pelo <strong>Sensor Tower<\/strong>, o game acumulou uma fortuna hom\u00e9rica em torno de m\u00faltiplos pa\u00edses, tendo os Estados Unidos como sua principal fonte de investimento.<\/p>\n<p>Neste caso, os estadunidenses fazem parte do pilar que investem dinheiro real no game. Segundo os n\u00fameros fornecidos, os <strong>EUA<\/strong> acumulam cerca de US$ 1.9 bilh\u00f5es at\u00e9 o momento. Em seguida, temos o <strong>Jap\u00e3o<\/strong> representando 32% da renda. E em terceiro, a <strong>Alemanha<\/strong> se destaca com cerca de 5.4% do valor total.<\/p>\n<p>Em seus 5 anos de vida \u00fatil, Pok\u00e9mon GO j\u00e1 acumula mais de 632 milh\u00f5es de downloads. No que diz respeito aos dispositivos usados, contas do Google Play representam o maior valor gasto &#8211; cerca de $2.7 bilh\u00f5es &#8211; enquanto usu\u00e1rios da App Store acumulam $2.4 bilh\u00f5es.<\/p><div id=\"combo-3080458740\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Nesse bolo de estat\u00edsticas, o <strong>Brasil<\/strong> corresponde ao segundo pa\u00eds que mais instalou o game, enquanto a India ocupa a terceira posi\u00e7\u00e3o. \u00c9 interessante notar que, mesmo em fun\u00e7\u00e3o da pandemia global, o investimento em torno de Pok\u00e9mon GO n\u00e3o cessou ao redor do mundo.<\/p>\n<p>Fonte: <a href=\"https:\/\/sensortower.com\/blog\/pokemon-go-five-billion-revenue\" target=\"_blank\" rel=\"noopener\"><strong>Sensor Tower<\/strong> (estat\u00edsticas detalhadas de Pok\u00e9mon GO)<\/a><\/p>\n<h5>Em seguida, confira outras not\u00edcias do mundo dos games:<\/h5>\n<ul>\n<li><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/pokemon-unite-o-moba-de-pokemon-ganha-janela-de-lancamento-e-trailer\/\" target=\"_blank\" rel=\"noopener\">Pok\u00e9mon Unite, o novo MOBA da franquia, j\u00e1 possui data de lan\u00e7amento!<\/a><\/li>\n<li><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/nintendo-brasileiros-estao-pedindo-mais-jogos-da-empresa-em-portugues\/\" target=\"_blank\" rel=\"noopener\">F\u00e3s da Nintendo clamam por mais jogos localizados para o Brasil<\/a><\/li>\n<\/ul>\n<div id=\"combo-1149509993\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Pok\u00e9mon GO se tornou um fen\u00f4meno digital desde o lan\u00e7amento, e j\u00e1 rendeu bilh\u00f5es em receita Lan\u00e7ado em 2016, Pok\u00e9mon GO se tornou um dos maiores fen\u00f4menos respons\u00e1veis por revitalizar a franquia. Com a proposta m\u00f3vel de capturar criaturas conforme o jogador &#8220;explora o mundo real&#8220;, o game foi capaz de atrair n\u00e3o somente os [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":135684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,18,16,12293,12294,12298,241],"tags":[72268,12744,1099,9852,72267,72266],"class_list":["post-135683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-android","category-apple-ios","category-games","category-mobile","category-plataformas","category-todas","tag-baixar-pokemon-go","tag-dicas-pokemon-go","tag-pokemon","tag-pokemon-go","tag-pokemon-go-download","tag-pokemon-go-renda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pok\u00e9mon GO fatura mais de US$ 5 BILH\u00d5ES, cinco anos ap\u00f3s lan\u00e7amento - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Depois de 5 anos no mercado, Pok\u00e9mon GO j\u00e1 faturou mais de 5 bilh\u00f5es de d\u00f3lares. Confira mais detalhes e outras estat\u00edsticas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/pokemon-go-fatura-mais-de-us-5-bilhoes-cinco-anos-apos-lancamento\/\" \/>\n<meta name=\"author\" content=\"Lucas Guru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/pokemon-go-fatura-mais-de-us-5-bilhoes-cinco-anos-apos-lancamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pok\u00e9mon GO fatura mais de US$ 5 BILH\u00d5ES, cinco anos ap\u00f3s lan\u00e7amento\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pok\u00e9mon GO fatura mais de US$ 5 BILH\u00d5ES, cinco anos ap\u00f3s lan\u00e7amento - Combo Infinito","description":"Depois de 5 anos no mercado, Pok\u00e9mon GO j\u00e1 faturou mais de 5 bilh\u00f5es de d\u00f3lares. Confira mais detalhes e outras estat\u00edsticas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/pokemon-go-fatura-mais-de-us-5-bilhoes-cinco-anos-apos-lancamento\/","author":"Lucas Guru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/pokemon-go-fatura-mais-de-us-5-bilhoes-cinco-anos-apos-lancamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Pok\u00e9mon GO fatura mais de US$ 5 BILH\u00d5ES, cinco anos ap\u00f3s lan\u00e7amento"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/135683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=135683"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/135683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/135684"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=135683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=135683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=135683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}