{"id":139020,"date":"2021-10-20T13:19:08","date_gmt":"2021-10-20T16:19:08","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=139020"},"modified":"2021-10-20T13:19:08","modified_gmt":"2021-10-20T16:19:08","slug":"resident-evil-4-vr-nao-tera-o-modo-mercenarios-e-campanha-de-ada-em-seu-lancamento","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-4-vr-nao-tera-o-modo-mercenarios-e-campanha-de-ada-em-seu-lancamento\/","title":{"rendered":"Resident Evil 4 VR n\u00e3o ter\u00e1 o modo Mercen\u00e1rios e campanha de Ada em seu lan\u00e7amento"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em><span style=\"font-weight: 400;\">Uma vers\u00e3o com muitas remo\u00e7\u00f5es<\/span><\/em><\/h5>\n<p><span style=\"font-weight: 400;\">Em um comunicado um porta-voz do <\/span><b>Facebook <\/b><span style=\"font-weight: 400;\">revelou que os modos <\/span><b>Mercenaries<\/b><span style=\"font-weight: 400;\">, <\/span><b>Separate Ways<\/b><span style=\"font-weight: 400;\"> e <\/span><b>Assignment Ada<\/b><span style=\"font-weight: 400;\"> n\u00e3o estar\u00e3o na vers\u00e3o <\/span><b>VR <\/b><span style=\"font-weight: 400;\">de <\/span><b>Resident Evil 4<\/b><span style=\"font-weight: 400;\">, que chegar\u00e1 amanh\u00e3, de forma exclusiva, ao <\/span><b>Oculus Quest 2<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><div id=\"combo-3422043978\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><span style=\"font-weight: 400;\">Sem dar mais detalhes sobre o motivo desta remo\u00e7\u00e3o, ficamos \u00e0 merc\u00ea de uma justificativa para tal exclus\u00e3o. De todo modo, n\u00e3o ser\u00e1 apenas os modos cl\u00e1ssicos de Resident Evil 4 que estar\u00e3o de fora. Assim, alguns di\u00e1logos originais de <\/span><b>Leon<\/b><span style=\"font-weight: 400;\">, <\/span><b>Ashley <\/b><span style=\"font-weight: 400;\">e <\/span><b>Luis Sera<\/b><span style=\"font-weight: 400;\"> foram removidos para tornar a vers\u00e3o VR mais moderna e livre de problema devido a natureza dos respectivos di\u00e1logos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os f\u00e3s, por sua vez, est\u00e3o confusos do porqu\u00ea de tanta remo\u00e7\u00e3o de conte\u00fados. Sem d\u00favidas, o grande motivo de todas estas altera\u00e7\u00f5es \u00e9 a presen\u00e7a do Facebook por tr\u00e1s do projeto. Afinal, o Oculus Quest 2 \u00e9 do Facebook.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em suma, Resident Evil 4 VR chega amanh\u00e3 (21) para o Oculus Quest 2. Por fim, acompanhe tudo que rola no mundo dos games <a href=\"https:\/\/www.comboinfinito.com.br\/principal\/category\/games\/\" target=\"_blank\" rel=\"noopener\">clicando aqui<\/a>.<\/span><\/p><div id=\"combo-2745447822\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><span style=\"font-weight: 400;\">Fonte: <\/span><a href=\"https:\/\/www.ign.com\/articles\/resident-evil-4-vr-missing-modes\" target=\"_blank\" rel=\"noopener\"><b>IGN<\/b><\/a><\/p>\n<p><b>Mais not\u00edcias:<\/b><\/p>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-4-vr-tem-seus-primeiros-16-minutos-de-gameplay-revelados\/\" target=\"_blank\" rel=\"noopener\">Resident Evil 4 VR tem seus primeiros 16 minutos de gameplay revelados<\/a><\/p><div id=\"combo-2852571780\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/valve-revela-sistema-de-compatibilidade-para-jogos-no-steam-deck\/\" target=\"_blank\" rel=\"noopener\">Valve revela sistema de compatibilidade para jogos no Steam Deck<\/a><\/p>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/god-of-war-e-anunciado-para-pc-e-pre-venda-ja-esta-disponivel-confira\/\" target=\"_blank\" rel=\"noopener\">God of War \u00e9 anunciado para PC e pr\u00e9-venda j\u00e1 est\u00e1 dispon\u00edvel \u2013 Confira!<\/a><\/p>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/square-enix-abre-novo-estudio-com-foco-em-jogos-mobile-gratuitos\/\" target=\"_blank\" rel=\"noopener\">Square Enix abre novo est\u00fadio com foco em jogos mobile gratuitos<\/a><\/p>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/sherlock-holmes-chapter-one-trailer-detalha-como-personagem-conseguira-captar-pistas-no-ambiente\/\" target=\"_blank\" rel=\"noopener\">Sherlock Holmes: Chapter One \u2013 Trailer detalha como personagem conseguir\u00e1 captar pistas no ambiente<\/a><\/p>\n<div id=\"combo-4056133463\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Uma vers\u00e3o com muitas remo\u00e7\u00f5es Em um comunicado um porta-voz do Facebook revelou que os modos Mercenaries, Separate Ways e Assignment Ada n\u00e3o estar\u00e3o na vers\u00e3o VR de Resident Evil 4, que chegar\u00e1 amanh\u00e3, de forma exclusiva, ao Oculus Quest 2. Sem dar mais detalhes sobre o motivo desta remo\u00e7\u00e3o, ficamos \u00e0 merc\u00ea de uma [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":139021,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,241],"tags":[52,74620,549,66547],"class_list":["post-139020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-todas","tag-capcom","tag-esident-evil-4-vr","tag-facebook","tag-oculus-quest-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resident Evil 4 VR n\u00e3o ter\u00e1 o modo Mercen\u00e1rios e campanha de Ada em seu lan\u00e7amento<\/title>\n<meta name=\"description\" content=\"Resident Evil 4 VR n\u00e3o ter\u00e1 os modos Mercenaries, Separate Ways e Assignment Ada por motivos ainda desconhecidos. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-4-vr-nao-tera-o-modo-mercenarios-e-campanha-de-ada-em-seu-lancamento\/\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Ant\u00f4nio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/resident-evil-4-vr-nao-tera-o-modo-mercenarios-e-campanha-de-ada-em-seu-lancamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resident Evil 4 VR n\u00e3o ter\u00e1 o modo Mercen\u00e1rios e campanha de Ada em seu lan\u00e7amento\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resident Evil 4 VR n\u00e3o ter\u00e1 o modo Mercen\u00e1rios e campanha de Ada em seu lan\u00e7amento","description":"Resident Evil 4 VR n\u00e3o ter\u00e1 os modos Mercenaries, Separate Ways e Assignment Ada por motivos ainda desconhecidos. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-4-vr-nao-tera-o-modo-mercenarios-e-campanha-de-ada-em-seu-lancamento\/","author":"Jo\u00e3o Ant\u00f4nio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-4-vr-nao-tera-o-modo-mercenarios-e-campanha-de-ada-em-seu-lancamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Resident Evil 4 VR n\u00e3o ter\u00e1 o modo Mercen\u00e1rios e campanha de Ada em seu lan\u00e7amento"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/139020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=139020"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/139020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/139021"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=139020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=139020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=139020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}