{"id":140842,"date":"2021-12-09T09:46:38","date_gmt":"2021-12-09T12:46:38","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=140842"},"modified":"2021-12-09T09:46:38","modified_gmt":"2021-12-09T12:46:38","slug":"cemiterio-maldito-guillermo-del-toro-fala-sobre-desejo-de-adaptar-novo-filme","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/cemiterio-maldito-guillermo-del-toro-fala-sobre-desejo-de-adaptar-novo-filme\/","title":{"rendered":"Cemit\u00e9rio Maldito: Guillermo del Toro fala sobre desejo de adaptar novo filme"},"content":{"rendered":"<h5 style=\"text-align: center;\">\u201cComo pai, agora eu entendo melhor do que jamais entenderia\u201d<\/h5>\n<p><strong>Cemit\u00e9rio Maldito,<\/strong> um dos principais livros de <strong>Stephen King<\/strong> pode ganhar uma nova adapta\u00e7\u00e3o, isso se depender de <strong>Guillermo del Toro. <\/strong><\/p><div id=\"combo-2221001762\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com o diretor, agora que ele \u00e9 pai, ele entende o livro muito mais. Ali\u00e1s, abaixo podemos conferir o que ele falou sobre o seu desejo:<\/p>\n<blockquote><p><em>\u201cVoc\u00ea sabe, o romance que eu teria matado para adaptar, e eu sei que h\u00e1 duas vers\u00f5es dele, e ainda acho que talvez em um universo perturbado eu consiga faz\u00ea-lo novamente um dia \u00e9 \u2018Cemit\u00e9rio Maldito\u2019. Porque n\u00e3o s\u00f3 tem as melhores linhas finais, mas tamb\u00e9m me assustou quando eu era jovem. Como pai, agora eu entendo melhor do que jamais entenderia, e isso me assusta. Cem vezes mais. \u201c<\/em><\/p><\/blockquote>\n<p>Vale lembrar que Cemit\u00e9rio Maldito, de 1983, j\u00e1 ganhou outras adapta\u00e7\u00f5es.<\/p>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-140843\" src=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito.jpg\" alt=\"Cemit\u00e9rio Maldito\" width=\"896\" height=\"504\" data-wp-pid=\"140843\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Cemiterio-Maldito-150x84.jpg 150w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<h5>Sinopse do livro<\/h5>\n<blockquote><p><em>\u201cO livro que inspirou o filme O cemit\u00e9rio maldito. Louis Creed, um jovem m\u00e9dico de Chicago, acredita que encontrou seu lugar em uma pequena cidade do Maine. A boa casa, o trabalho na universidade e a felicidade da esposa e dos filhos lhe trazem a certeza de que fez a melhor escolha. Num dos primeiros passeios pela regi\u00e3o, conhecem um cemit\u00e9rio no bosque pr\u00f3ximo \u00e0 sua casa. Ali, gera\u00e7\u00f5es de crian\u00e7as enterraram seus animais de estima\u00e7\u00e3o. <\/em><\/p>\n<p><em>Mas, para al\u00e9m dos pequenos t\u00famulos, h\u00e1 um outro cemit\u00e9rio. Uma terra maligna que atrai pessoas com promessas sedutoras. Um universo dominado por for\u00e7as estranhas capazes de tornar real o que sempre pareceu imposs\u00edvel. A princ\u00edpio, Louis Creed se diverte com as hist\u00f3rias fantasmag\u00f3ricas do vizinho Crandall. No entanto, quando o gato de sua filha Eillen morre atropelado e, subitamente, retorna \u00e0 vida, ele percebe que h\u00e1 coisas que nem mesmo a sua ci\u00eancia pode explicar. Que mist\u00e9rios esconde o cemit\u00e9rio dos bichos? Ter\u00e1 o homem o direito de interferir no mundo dos mortos? Em busca das respostas, Louis Creed \u00e9 levado por uma trama sobrenatural em que o limite entre a vida e a morte \u00e9 inexistente. E, quando descobre a verdade, percebe que ela \u00e9 muito pior que seus mais terr\u00edveis pesadelos. Pior que a pr\u00f3pria morte &#8211; e infinitamente mais poderosa.\u201d<\/em><\/p><\/blockquote>\n<p>Fonte: <a href=\"https:\/\/collider.com\/guillermo-del-toro-pet-sematary-adaptation-comments\/\" target=\"_blank\" rel=\"noopener\"><strong>Collider<\/strong><\/a><\/p><div id=\"combo-4288256362\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><strong>Confira mais sobre o assunto:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/10-piores-filmes-inspirados-em-video-games\/\" target=\"_blank\" rel=\"noopener\"><strong>10 PIORES filmes inspirados em video-games<\/strong><\/a><\/li>\n<\/ul>\n<div id=\"combo-2968891555\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cComo pai, agora eu entendo melhor do que jamais entenderia\u201d Cemit\u00e9rio Maldito, um dos principais livros de Stephen King pode ganhar uma nova adapta\u00e7\u00e3o, isso se depender de Guillermo del Toro. De acordo com o diretor, agora que ele \u00e9 pai, ele entende o livro muito mais. Ali\u00e1s, abaixo podemos conferir o que ele falou [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":140844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12310,9525,241],"tags":[25690,5171,12525],"class_list":["post-140842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cinema","category-cinema-series-tv","category-todas","tag-cemiterio-maldito","tag-guillermo-del-toro","tag-stephen-king"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cemit\u00e9rio Maldito: Guillermo del Toro fala sobre desejo de adaptar novo filme - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Cemit\u00e9rio Maldito, um dos principais livros de Stephen King pode ganhar uma nova adapta\u00e7\u00e3o, isso se depender de Guillermo del Toro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/cemiterio-maldito-guillermo-del-toro-fala-sobre-desejo-de-adaptar-novo-filme\/\" \/>\n<meta name=\"author\" content=\"Filipe Salom\u00e3o\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/cemiterio-maldito-guillermo-del-toro-fala-sobre-desejo-de-adaptar-novo-filme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cemit\u00e9rio Maldito: Guillermo del Toro fala sobre desejo de adaptar novo filme\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cemit\u00e9rio Maldito: Guillermo del Toro fala sobre desejo de adaptar novo filme - Combo Infinito","description":"Cemit\u00e9rio Maldito, um dos principais livros de Stephen King pode ganhar uma nova adapta\u00e7\u00e3o, isso se depender de Guillermo del Toro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/cemiterio-maldito-guillermo-del-toro-fala-sobre-desejo-de-adaptar-novo-filme\/","author":"Filipe Salom\u00e3o","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/cemiterio-maldito-guillermo-del-toro-fala-sobre-desejo-de-adaptar-novo-filme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Cemit\u00e9rio Maldito: Guillermo del Toro fala sobre desejo de adaptar novo filme"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/140842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=140842"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/140842\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/140844"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=140842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=140842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=140842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}