{"id":140948,"date":"2021-12-13T15:45:52","date_gmt":"2021-12-13T18:45:52","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=140948"},"modified":"2021-12-13T15:45:52","modified_gmt":"2021-12-13T18:45:52","slug":"the-batman-trailer-japones-e-revelado","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/the-batman-trailer-japones-e-revelado\/","title":{"rendered":"The Batman: Trailer Japon\u00eas \u00e9 revelado"},"content":{"rendered":"<h5 style=\"text-align: center;\">Confira um pouco de Alfred, Mulher-Gato e Charada<\/h5>\n<p><strong>The Batman<\/strong> trar\u00e1 um elenco formid\u00e1vel e repleto de personagens conhecidos, ali\u00e1s, o trailer japon\u00eas do longa nos trouxe um pouco de <strong>Alfred, Mulher-Gato e Charada.<\/strong> Portanto, antes de mais nada, confira o trailer abaixo:<\/p><div id=\"combo-368377210\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><iframe title=\"\u6620\u753b\u300eTHE BATMAN\uff0d\u30b6\u30fb\u30d0\u30c3\u30c8\u30de\u30f3\uff0d\u300f\u65e5\u672c\u7248\u4e88\u544a 2022\u5e743\u670811\u65e5\uff08\u91d1\uff09\u516c\u958b\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/ImEaPpJhvrs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>Enfim, quem curtiu o trailer?<\/p>\n<h5>Sinopse:<\/h5>\n<p>Uma viagem ao cora\u00e7\u00e3o do submundo de Gotham<\/p>\n<blockquote><p><em>\u201cDa Warner Bros. Pictures chega The Batman, de Matt Reeves, estrelado por Robert Pattinson no papel duplo de detetive vigilante de Gotham City e seu alter ego, o recluso bilion\u00e1rio Bruce Wayne.<\/em><\/p>\n<p><em>Dois anos perseguindo as ruas como o Batman (Robert Pattinson), causando medo nos cora\u00e7\u00f5es dos criminosos, levaram Bruce Wayne para as sombras de Gotham City.<\/em><\/p>\n<h5><em>Com apenas alguns aliados de confian\u00e7a<\/em><\/h5>\n<p><em>Com apenas alguns aliados de confian\u00e7a \u2013 Alfred Pennyworth (Andy Serkis), o tenente James Gordon (Jeffrey Wright) \u2013 entre a rede corrupta de funcion\u00e1rios e figuras de destaque da cidade, o solit\u00e1rio vigilante se estabeleceu como a \u00fanica personifica\u00e7\u00e3o da vingan\u00e7a entre os seus caros cidad\u00e3os.<\/em><\/p>\n<p><em>Quando um assassino tem como alvo a elite de Gotham com uma s\u00e9rie de maquina\u00e7\u00f5es s\u00e1dicas, uma trilha de pistas enigm\u00e1ticas envia o Maior Detetive do Mundo em uma investiga\u00e7\u00e3o sobre o submundo, onde ele encontra personagens como Selina Kyle\/Mulher-Gato (Zo\u00eb Kravitz), Oswald Cobblepot\/Pinguim (Colin Farrell), Carmine Falcone (John Turturro) e Edward Nashton\/Charada (Paul Dano).<\/em><\/p>\n<p><em>Conforme as evid\u00eancias come\u00e7am a chegar mais perto da verdade e a escala dos planos do perpetrador se torna clara, Batman deve forjar novos relacionamentos, desmascarar o culpado e fazer justi\u00e7a ao abuso de poder e \u00e0 corrup\u00e7\u00e3o que h\u00e1 muito tempo assola Gotham City.\u201d<\/em><\/p><\/blockquote>\n<p><strong>The Batman estreia nos cinemas em 4 de mar\u00e7o de 2022,<\/strong> contudo at\u00e9 l\u00e1 ainda teremos outras novidades. Ali\u00e1s, trar\u00e1 um roteiro assinado por <strong>Reeves e Mattson Tomlin (Power).<\/strong> Na ocasi\u00e3o, o <strong>Bruce Wayne de Pattinson vai enfrentar os vil\u00f5es Charada (Paul Dano), Mulher-Gato (Zoe Kravitz) e Pinguim (Colin Farrell). Assim, j\u00e1 no seu time, estar\u00e3o Alfred (Andy Serkis) e Comiss\u00e1rio Gordon (Jeffrey Wright). O elenco ainda conta com John Turturro, Peter Sarsgaard e Jayme Lawson.<\/strong><\/p><div id=\"combo-3484669279\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Fonte: <a href=\"https:\/\/twinfinite.net\/2021\/12\/the-batman-reboot-gets-new-japanese-trailer-teasing-riddles-murder-explosive-action\/\" target=\"_blank\" rel=\"noopener\"><strong>Twinfinite<\/strong><\/a><\/p>\n<p>Confira mais sobre o assunto:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/the-batman-sinopse-provoca-uma-viagem-ao-coracao-do-submundo-de-gotham\/\" target=\"_blank\" rel=\"noopener\"><strong>The Batman: Sinopse provoca uma viagem ao cora\u00e7\u00e3o do submundo de Gotham<\/strong><\/a><\/li>\n<\/ul>\n<div id=\"combo-4181894783\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Confira um pouco de Alfred, Mulher-Gato e Charada The Batman trar\u00e1 um elenco formid\u00e1vel e repleto de personagens conhecidos, ali\u00e1s, o trailer japon\u00eas do longa nos trouxe um pouco de Alfred, Mulher-Gato e Charada. Portanto, antes de mais nada, confira o trailer abaixo: Enfim, quem curtiu o trailer? Sinopse: Uma viagem ao cora\u00e7\u00e3o do submundo [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":127053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12310,9525,47,241],"tags":[34622,16899,14876,13242],"class_list":["post-140948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cinema","category-cinema-series-tv","category-destaque","category-todas","tag-alfred","tag-charada","tag-mulher-gato","tag-the-batman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Batman: Trailer Japon\u00eas \u00e9 revelado - Combo Infinito<\/title>\n<meta name=\"description\" content=\"The Batman trar\u00e1 um elenco formid\u00e1vel e repleto de personagens conhecidos, ali\u00e1s, o trailer japon\u00eas do longa nos trouxe um pouco de Alfred,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/the-batman-trailer-japones-e-revelado\/\" \/>\n<meta name=\"author\" content=\"Filipe Salom\u00e3o\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/the-batman-trailer-japones-e-revelado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Batman: Trailer Japon\u00eas \u00e9 revelado\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Batman: Trailer Japon\u00eas \u00e9 revelado - Combo Infinito","description":"The Batman trar\u00e1 um elenco formid\u00e1vel e repleto de personagens conhecidos, ali\u00e1s, o trailer japon\u00eas do longa nos trouxe um pouco de Alfred,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/the-batman-trailer-japones-e-revelado\/","author":"Filipe Salom\u00e3o","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/the-batman-trailer-japones-e-revelado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"The Batman: Trailer Japon\u00eas \u00e9 revelado"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/140948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=140948"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/140948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/127053"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=140948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=140948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=140948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}