{"id":141582,"date":"2021-12-28T13:38:46","date_gmt":"2021-12-28T16:38:46","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=141582"},"modified":"2021-12-28T13:38:46","modified_gmt":"2021-12-28T16:38:46","slug":"motoqueiro-fantasma-astro-de-the-walking-dead-pode-dar-vida-ao-protagonista-rumor","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/motoqueiro-fantasma-astro-de-the-walking-dead-pode-dar-vida-ao-protagonista-rumor\/","title":{"rendered":"Motoqueiro Fantasma: Astro de The Walking Dead pode dar vida ao protagonista \u2013 Rumor"},"content":{"rendered":"<h5 style=\"text-align: center;\">De um apocalipse para uma moto<\/h5>\n<p><strong>Motoqueiro Fantasma<\/strong> pode ter ganho um nome para uma nova produ\u00e7\u00e3o, de acordo com um novo rumor, teremos nada menos do que <strong>Norman Reedus<\/strong> no papel!<\/p><div id=\"combo-548836450\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Entretanto, ainda n\u00e3o etmos nada confirmado. Apesar de que o ator parece bem interessado no papel. Enfim, quem a\u00ed curtiria<strong> Norman Reedus<\/strong> no papel? Ali\u00e1s, quem gosta do personagem?<\/p>\n<p><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-141583\" src=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33.jpg\" alt=\"Norman Reedus motoqueiro fantasma\" width=\"896\" height=\"504\" data-wp-pid=\"141583\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2021\/12\/Norman-Reedus-Motoqueiro-Fantasma-33-150x84.jpg 150w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p>Abaixo temos muito mais sobre o Motoqueiro Fantasma<\/p>\n<h5>V\u00e1rios nomes<\/h5>\n<p>Vale lembrar que muitos nomes j\u00e1 carregaram a maldi\u00e7\u00e3o, entre eles temos:<\/p><div id=\"combo-4183759715\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<ul>\n<li>Johnny Blaze;<\/li>\n<li>Danny Ketch;<\/li>\n<li>Robbie Reyes;<\/li>\n<li>Frank Castle;<\/li>\n<\/ul>\n<h5>Origem<\/h5>\n<blockquote><p><em>\u201cO primeiro Motoqueiro Fantasma foi Johnny Blaze, criado pelo desenhista Mike Ploog e os escritores Roy Thomas e Gary Friedrich, e apareceu pela primeira vez em Marvel Spotlight #05 (agosto de 1972). Blaze, para salvar a vida de seu pai, fez um pacto com &#8220;Sat\u00e3&#8221; (que mais tarde foi revelado como sendo o dem\u00f4nio Mephisto) em troca de sua alma. \u00c0 noite, perto de maldades sendo cometidas, ou sobre extrema press\u00e3o, Blaze v\u00ea sua pr\u00f3pria carne ser consumida em fogo infernal, deixando-o com a apar\u00eancia de um esqueleto em chamas &#8211; eventualmente Blaze descobre que ele foi ligado ao dem\u00f4nio Zarathos. Ele conduz uma moto igualmente em chamas. Blaze estrelou a revista Ghost Rider de 1972 \u00e0 1983. Nota-se, por\u00e9m, que Blaze ainda \u00e9 o personagem mais conhecido ao usar o nome de Motoqueiro Fantasma, t\u00edtulo e cargo que utiliza at\u00e9 hoje.\u201d<\/em><\/p><\/blockquote>\n<p>Conforme as informa\u00e7\u00f5es, a franquia trar\u00e1 Johnny Blaze e sua hist\u00f3ria:<\/p>\n<blockquote><p><em>\u201cJohnny Blaze trabalha como dubl\u00ea e piloto de motocicleta. H\u00e1 muito tempo, ele fez um pacto com Mefisto para proteger as duas pessoas que mais amava: seu pai, Barton, e sua namorada de adolesc\u00eancia, Roxanne Simpson. Em troca, Johnny se transforma no Motoqueiro Fantasma, o justiceiro de alguns dem\u00f4nios bastante cru\u00e9is. For\u00e7ado a obedecer a Mefisto, Johnny decide enfrent\u00e1-lo de forma a usar sua maldi\u00e7\u00e3o para proteger pessoas inocentes.\u201d<\/em><\/p><\/blockquote>\n<p>Poderes e habilidades<\/p>\n<p>De acordo com a descri\u00e7\u00e3o, o Motoqueiro Fantasma tem os seguintes poderes e habilidades, entre outros:<\/p><div id=\"combo-3440557896\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<ul>\n<li>Quase Onipot\u00eancia<\/li>\n<li>Quase Onimagia<\/li>\n<li>Imortalidade<\/li>\n<li>Super For\u00e7a<\/li>\n<li>Quase Onisci\u00eancia<\/li>\n<li>Super Resist\u00eancia<\/li>\n<li>Regenera\u00e7\u00e3o<\/li>\n<li>Super Velocidade<\/li>\n<li>Produ\u00e7\u00e3o de Fogo (Normal e Infernal)<\/li>\n<li>Controle de Fogo (Normal e Infernal)<\/li>\n<\/ul>\n<p>Fonte: <a href=\"https:\/\/pt.ign.com\/ghost-rider-theater\/107330\/news\/ghost-rider-rumores-reforcam-norman-reedus-como-protagonista\" target=\"_blank\" rel=\"noopener\"><strong>IGN Portugal<\/strong><\/a><\/p>\n<p><strong>Confira mais sobre o assunto:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/o-livro-de-boba-fett-trailer-inedito-traz-novas-cenas-cheias-de-acao\/\" target=\"_blank\" rel=\"noopener\"><strong>O Livro de Boba Fett: Trailer in\u00e9dito traz novas cenas cheias de a\u00e7\u00e3o<\/strong><\/a><\/li>\n<\/ul>\n<div id=\"combo-2287471443\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>De um apocalipse para uma moto Motoqueiro Fantasma pode ter ganho um nome para uma nova produ\u00e7\u00e3o, de acordo com um novo rumor, teremos nada menos do que Norman Reedus no papel! Entretanto, ainda n\u00e3o etmos nada confirmado. Apesar de que o ator parece bem interessado no papel. Enfim, quem a\u00ed curtiria Norman Reedus no [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":141584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12310,9525,241],"tags":[11528,10007],"class_list":["post-141582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cinema","category-cinema-series-tv","category-todas","tag-motoqueiro-fantasma","tag-norman-reedus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motoqueiro Fantasma: Astro de The Walking Dead pode dar vida ao protagonista \u2013 Rumor - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Motoqueiro Fantasma pode ter ganho um nome para uma nova produ\u00e7\u00e3o, de acordo com um novo rumor, teremos nada menos do que Norman Reedus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/motoqueiro-fantasma-astro-de-the-walking-dead-pode-dar-vida-ao-protagonista-rumor\/\" \/>\n<meta name=\"author\" content=\"Filipe Salom\u00e3o\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/motoqueiro-fantasma-astro-de-the-walking-dead-pode-dar-vida-ao-protagonista-rumor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motoqueiro Fantasma: Astro de The Walking Dead pode dar vida ao protagonista \u2013 Rumor\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motoqueiro Fantasma: Astro de The Walking Dead pode dar vida ao protagonista \u2013 Rumor - Combo Infinito","description":"Motoqueiro Fantasma pode ter ganho um nome para uma nova produ\u00e7\u00e3o, de acordo com um novo rumor, teremos nada menos do que Norman Reedus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/motoqueiro-fantasma-astro-de-the-walking-dead-pode-dar-vida-ao-protagonista-rumor\/","author":"Filipe Salom\u00e3o","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/motoqueiro-fantasma-astro-de-the-walking-dead-pode-dar-vida-ao-protagonista-rumor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Motoqueiro Fantasma: Astro de The Walking Dead pode dar vida ao protagonista \u2013 Rumor"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/141582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=141582"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/141582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/141584"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=141582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=141582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=141582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}