{"id":14868,"date":"2014-11-12T16:40:51","date_gmt":"2014-11-12T18:40:51","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=14868"},"modified":"2014-11-12T16:42:02","modified_gmt":"2014-11-12T18:42:02","slug":"activision-revela-que-a-serie-call-of-duty-vendeu-quase-190-milhoes-de-unidades","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/activision-revela-que-a-serie-call-of-duty-vendeu-quase-190-milhoes-de-unidades\/","title":{"rendered":"Activision revela que a s\u00e9rie Call of Duty vendeu quase 190 milh\u00f5es de unidades"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-14874\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades.jpg\" alt=\"Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades\" width=\"896\" height=\"504\" data-wp-pid=\"14874\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2014\/11\/Activision-revela-que-a-serie-Call-of-Duty-vendeu-quase-190-milhoes-de-unidades-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a>A <strong>Activision<\/strong>, detentora da marca, anunciou que a s\u00e9rie <strong>Call of Duty<\/strong> foi reconhecida como a a franquia de <em>FPS<\/em> (First Person Shooter, ou tiro em primeira pessoa) que mais jogos vendeu, e isso se deve ao fato que eles atingiram a marca de 188.9 milh\u00f5es de unidades vendidas em todas as plataformas para as quais foram lan\u00e7adas at\u00e9 julho de 2014,\u00a0oui seja,\u00a0n\u00e3o est\u00e3o contando com as vendas de <strong>Advanced Warfare<\/strong>, portanto\u00a0esse n\u00famero vai ultrapassar os 190 e pode chegar tranquilamente at\u00e9 os 200.<\/p><div id=\"combo-401732614\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">Recentemente a s\u00e9rie foi considerada, pelo <em><strong>Guiness World Records 2015 Gamer&#8217;s Edition<\/strong><\/em>, como a melhor s\u00e9rie de videogames da hist\u00f3ria.<\/p>\n<p style=\"text-align: justify;\"><strong>Call of Duty<\/strong> surgiu originalmente em 2003 e desde ent\u00e3o conta com 21 jogos, expans\u00f5es e <em>spin-offs<\/em> inclu\u00eddos. O mais recente jogo, <strong>Call of Duty: Advanced Warfare<\/strong> j\u00e1 est\u00e1 \u00e0 venda. Eu particularmente sou f\u00e3 da\u00a0s\u00e9rie\u00a0<strong>Modern Warfare<\/strong>, e o meu preferido foi o primeiro.<\/p>\n<p style=\"text-align: justify;\"><strong>Veja tamb\u00e9m: <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/cod-advanced-warfare-e-4-vezes-mais-popular-nas-redes-sociais-do-que-cod-ghosts\/\" target=\"_blank\">Advanced Warfare \u00e9 4 vezes mais popular que Ghosts nas redes sociais<\/a><\/strong><\/p><div id=\"combo-4137411369\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">CoD trouxe um estilo diferenciado com um realismo absurdo para os videogames. O que a s\u00e9rie <strong>Half-Life<\/strong> mostrou\u00a0de fant\u00e1stico para gera\u00e7\u00e3o retrasada, Call of Duty, na minha opini\u00e3o, foi o nome que representou o\u00a0FPS da passada.<\/p>\n<p style=\"text-align: justify;\">Mesmo com o g\u00eanero e a f\u00f3rmula saturados dentro do mercado, \u00a0essa franquia ainda vende igual \u00e1gua, e gera um lucro monstruoso que deixam muitas concorrentes de queixo ca\u00eddo.<\/p>\n<p style=\"text-align: justify;\">Fala a verdade, desses 188.9 milh\u00f5es, quanto disso foi contribui\u00e7\u00e3o sua?<\/p><div id=\"combo-2262543143\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-829230494\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>A Activision, detentora da marca, anunciou que a s\u00e9rie Call of Duty foi reconhecida como a a franquia de FPS (First Person Shooter, ou tiro em primeira pessoa) que mais jogos vendeu, e isso se deve ao fato que eles atingiram a marca de 188.9 milh\u00f5es de unidades vendidas em todas as plataformas para as [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[241],"tags":[4007,369,5583,76,1124],"class_list":["post-14868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-todas","tag-advanced-warfare","tag-call-of-duty","tag-call-of-duty-melhor-serie-games","tag-cod","tag-fps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Activision revela que a s\u00e9rie Call of Duty vendeu quase 190 milh\u00f5es de unidades - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/activision-revela-que-a-serie-call-of-duty-vendeu-quase-190-milhoes-de-unidades\/\" \/>\n<meta name=\"author\" content=\"Alepitekus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/activision-revela-que-a-serie-call-of-duty-vendeu-quase-190-milhoes-de-unidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activision revela que a s\u00e9rie Call of Duty vendeu quase 190 milh\u00f5es de unidades\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activision revela que a s\u00e9rie Call of Duty vendeu quase 190 milh\u00f5es de unidades - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/activision-revela-que-a-serie-call-of-duty-vendeu-quase-190-milhoes-de-unidades\/","author":"Alepitekus","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/activision-revela-que-a-serie-call-of-duty-vendeu-quase-190-milhoes-de-unidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Activision revela que a s\u00e9rie Call of Duty vendeu quase 190 milh\u00f5es de unidades"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/14868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=14868"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/14868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/14874"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=14868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=14868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=14868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}