{"id":159403,"date":"2023-07-24T16:19:17","date_gmt":"2023-07-24T19:19:17","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=159403"},"modified":"2023-07-24T17:10:29","modified_gmt":"2023-07-24T20:10:29","slug":"xbox-series-x-s-novo-controle-e-vazado-na-internet","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/xbox-series-x-s-novo-controle-e-vazado-na-internet\/","title":{"rendered":"Xbox Series X\/S: Novo controle \u00e9 vazado na internet"},"content":{"rendered":"<h4 style=\"text-align: center;\">Microsoft deve lan\u00e7ar s\u00e9timo controle do Xbox neste ano<\/h4>\n<p>Tudo indica que o novo controle do<a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/xbox\" target=\"_blank\" rel=\"noopener\"><strong> Xbox Series X\/S<\/strong><\/a> vazou antes do an\u00fancio oficial da Microsoft durante o \u00faltimo final de semana.<\/p><div id=\"combo-2191253914\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com mais uma reportagem exclusiva do famoso leaker <a href=\"https:\/\/www.dealabs.com\/magazine\/manette-xbox-jemez-une-nouvelle-manette-xbox-sans-fil-devrait-sortir-tres-bientot-24690\" target=\"_blank\" rel=\"noopener\"><strong>Billbil-kun<\/strong>,<\/a> que possui um longo hist\u00f3rico confi\u00e1veis, o novo controle \u00e9 o <strong>Stormcloud Vapor<\/strong>. O controle, que tinha o codinome <strong>Jemez<\/strong>, possui lan\u00e7amento programado para o dia <strong>8 de agosto.<\/strong><\/p>\n<p>No entanto, o leaker disse que existe a possibilidade da altera\u00e7\u00e3o do planejamento inicial de lan\u00e7amento. Ou seja, da mesma forma que ocorreu com outros controles durante este ano.<\/p>\n<hr \/>\n<p><strong><a href=\"https:\/\/tinyurl.com\/teracombo\">Os melhores produtos do mercado! Confira as ofertas da Terabyte e monte j\u00e1 o seu PC Gamer<\/a><\/strong><\/p><div id=\"combo-3949232354\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<hr \/>\n<p>Cabe ressaltar que as primeiras informa\u00e7\u00f5es indicavam um novo controle tem\u00e1tico de Forza Motorsport. Por\u00e9m, considerando as varia\u00e7\u00f5es lan\u00e7adas pela Microsoft neste ano, tudo indica que o novo controle n\u00e3o est\u00e1 relacionado ao jogo de corrida, previsto para 10 de outubro.<\/p>\n<p>A Microsoft j\u00e1 lan\u00e7ou seis novos designs de controle do Xbox em 2023, o que significa que o controle Stormcloud Vapor provavelmente ser\u00e1 o s\u00e9timo. Em fevereiro, revelou e lan\u00e7ou o Stellar Shift azul-roxo, seguido pelo Velocity Green em mar\u00e7o.<\/p>\n<p>O m\u00eas de mar\u00e7o tamb\u00e9m contou com o lan\u00e7amento das edi\u00e7\u00f5es vermelha e azul do controle Xbox Elite Series 2. Por fim, em maio, lan\u00e7ou um Sunkissed Vibes com tema de p\u00eassego e azul pastel e, em junho, lan\u00e7ou o Starfield de edi\u00e7\u00e3o limitada.<\/p><div id=\"combo-1195570486\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-769941254\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Microsoft deve lan\u00e7ar s\u00e9timo controle do Xbox neste ano Tudo indica que o novo controle do Xbox Series X\/S vazou antes do an\u00fancio oficial da Microsoft durante o \u00faltimo final de semana. De acordo com mais uma reportagem exclusiva do famoso leaker Billbil-kun, que possui um longo hist\u00f3rico confi\u00e1veis, o novo controle \u00e9 o Stormcloud [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":159404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,12298,241,49,41590],"tags":[40,31],"class_list":["post-159403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-plataformas","category-todas","category-xbox","category-xbox-series","tag-microsoft","tag-xbox"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xbox Series X\/S: Novo controle \u00e9 vazado na internet<\/title>\n<meta name=\"description\" content=\"Tudo indica que o novo controle do Xbox Series X\/S vazou antes do an\u00fancio oficial da Microsoft durante o \u00faltimo final de semana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/xbox-series-x-s-novo-controle-e-vazado-na-internet\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/xbox-series-x-s-novo-controle-e-vazado-na-internet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xbox Series X\\\/S: Novo controle \u00e9 vazado na internet\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xbox Series X\/S: Novo controle \u00e9 vazado na internet","description":"Tudo indica que o novo controle do Xbox Series X\/S vazou antes do an\u00fancio oficial da Microsoft durante o \u00faltimo final de semana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/xbox-series-x-s-novo-controle-e-vazado-na-internet\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/xbox-series-x-s-novo-controle-e-vazado-na-internet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Xbox Series X\/S: Novo controle \u00e9 vazado na internet"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=159403"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/159404"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=159403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=159403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=159403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}