{"id":159546,"date":"2023-07-28T08:50:00","date_gmt":"2023-07-28T11:50:00","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=159546"},"modified":"2023-07-28T08:50:57","modified_gmt":"2023-07-28T11:50:57","slug":"pikmin-4-estabelece-grande-recorde-japao-em-sua-primeira-semana","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/pikmin-4-estabelece-grande-recorde-japao-em-sua-primeira-semana\/","title":{"rendered":"Pikmin 4 estabelece grande recorde no Jap\u00e3o em sua primeira semana"},"content":{"rendered":"<h4 style=\"text-align: center;\">Pikmin surpreende com grandes vendas no Jap\u00e3o<\/h4>\n<p>Tudo indica que os apelos de<strong> Shigeru Miyamoto<\/strong> para os japoneses comprarem <strong><a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/pikmin\" target=\"_blank\" rel=\"noopener\">Pikmin 4<\/a><\/strong> surtiram efeito entre os jogadores locais.<\/p><div id=\"combo-835604089\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com dados divulgados pela <strong><a href=\"https:\/\/www.famitsu.com\/news\/202307\/27311101.html\" target=\"_blank\" rel=\"noopener\">Famitsu<\/a><\/strong>, as vendas da primeira semana no Jap\u00e3o superaram os n\u00fameros obtidos pelos outros tr\u00eas jogos combinados. Ou seja, o melhor lan\u00e7amento da hist\u00f3ria da franquia em territ\u00f3rio japon\u00eas deixou para tr\u00e1s os demais jogos com muita folga.<\/p>\n<p>O gr\u00e1fico divulgado pelo site japon\u00eas mostra que as vendas de jogos f\u00edsicas (at\u00e9 dia 23 de julho) chegaram ao n\u00famero de<strong> 401.853<\/strong> c\u00f3pias vendidas. Al\u00e9m do recorde, o jogo ficou em primeiro lugar entre os jogos vendidos no Jap\u00e3o durante este per\u00edodo.<\/p>\n<p>Em compara\u00e7\u00e3o, com base nas informa\u00e7\u00f5es do gr\u00e1fico arquivado, o primeiro Pikmin vendeu <strong>101.299<\/strong> em sua primeira semana. O segundo 2 vendeu <strong>161.930<\/strong> e o terceiro vendeu apenas<strong> 92.720<\/strong>.<\/p><div id=\"combo-1322584320\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Tamb\u00e9m deve ser notado que esses gr\u00e1ficos contam apenas as vendas f\u00edsicas. A Nintendo n\u00e3o compartilhou informa\u00e7\u00f5es sobre vendas de c\u00f3pias digitais, indicando que os n\u00fameros reais s\u00e3o maiores do que os divulgados com as vendas f\u00edsicas.<\/p>\n<p>As vendas provavelmente se devem em parte a uma ampla campanha publicit\u00e1ria para o jogo que ocorreu em todo o Jap\u00e3o. O marketing bem sucedido trouxe uma quantidade consider\u00e1vel de jogadores novos para a franquia.<\/p>\n<div id=\"combo-3282628441\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Pikmin surpreende com grandes vendas no Jap\u00e3o Tudo indica que os apelos de Shigeru Miyamoto para os japoneses comprarem Pikmin 4 surtiram efeito entre os jogadores locais. De acordo com dados divulgados pela Famitsu, as vendas da primeira semana no Jap\u00e3o superaram os n\u00fameros obtidos pelos outros tr\u00eas jogos combinados. Ou seja, o melhor lan\u00e7amento [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":158973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,50,10258,12298,241],"tags":[39,70286],"class_list":["post-159546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-nintendo-2","category-nintendo-switch","category-plataformas","category-todas","tag-nintendo","tag-pikmin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pikmin 4 estabelece grande recorde no Jap\u00e3o em sua 1\u00aa semana<\/title>\n<meta name=\"description\" content=\"Tudo indica que os apelos de Shigeru Miyamoto para os japoneses comprarem Pikmin 4 surtiram efeito entre os jogadores locais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/pikmin-4-estabelece-grande-recorde-japao-em-sua-primeira-semana\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/pikmin-4-estabelece-grande-recorde-japao-em-sua-primeira-semana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pikmin 4 estabelece grande recorde no Jap\u00e3o em sua primeira semana\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pikmin 4 estabelece grande recorde no Jap\u00e3o em sua 1\u00aa semana","description":"Tudo indica que os apelos de Shigeru Miyamoto para os japoneses comprarem Pikmin 4 surtiram efeito entre os jogadores locais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/pikmin-4-estabelece-grande-recorde-japao-em-sua-primeira-semana\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/pikmin-4-estabelece-grande-recorde-japao-em-sua-primeira-semana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Pikmin 4 estabelece grande recorde no Jap\u00e3o em sua primeira semana"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=159546"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/158973"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=159546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=159546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=159546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}