{"id":159598,"date":"2023-07-31T12:19:17","date_gmt":"2023-07-31T15:19:17","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=159598"},"modified":"2023-07-31T13:54:44","modified_gmt":"2023-07-31T16:54:44","slug":"nintendo-planeja-lancar-sucessor-do-switch-em-2024-rumor","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/nintendo-planeja-lancar-sucessor-do-switch-em-2024-rumor\/","title":{"rendered":"Nintendo planeja lan\u00e7ar sucessor do Switch em 2024 &#8211; Rumor"},"content":{"rendered":"<h4 style=\"text-align: center;\">Empresa japonesa cada vez mais pr\u00f3xima de revelar seu novo console<\/h4>\n<p>Tudo indica que a <a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/nitnendo\" target=\"_blank\" rel=\"noopener\"><strong>Nintendo<\/strong> <\/a>planeja o lan\u00e7amento do seu console de <strong>pr\u00f3xima gera\u00e7\u00e3o (concorrente de PS5 e Series X)<\/strong>\u00a0para o ano de <strong>2024<\/strong>.<\/p><div id=\"combo-1073951218\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com informa\u00e7\u00f5es divulgadas pela <a href=\"https:\/\/www.videogameschronicle.com\/news\/sources-nintendo-switch-2-targets-2024-with-next-gen-console\/\" target=\"_blank\" rel=\"noopener\"><strong>VGC<\/strong><\/a>, a empresa lan\u00e7ar\u00e1 um novo hardware durante o<strong> segundo semestre<\/strong> de 2024. O objetivo consistiria em garantir um amplo estoque dispon\u00edvel no primeiro dia e evitar a escassez vista com o <strong>PS5<\/strong> e <strong>Xbox Series X\/S.<\/strong><\/p>\n<p>Al\u00e9m disso, kits de desenvolvimento para o pr\u00f3ximo console da Nintendo agora est\u00e3o com os principais est\u00fadios parceiros. Segundo o site, as informa\u00e7\u00f5es foram obtidas com &#8220;v\u00e1rias pessoas com conhecimento dos planos do pr\u00f3ximo console&#8221;.<\/p>\n<p>Embora os detalhes espec\u00edficos do console estejam sendo mantidos em sigilo, fontes indicam que o console tamb\u00e9m utilizar\u00e1 o modelo h\u00edbrido. Outro detalhe \u00e9 o plano de lan\u00e7ar o console com uma tela <strong>LCD,<\/strong> em vez do <strong>OLED<\/strong>, buscando reduzir custos.<\/p><div id=\"combo-4156845689\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>A medida consistira principalmente em aumentar o armazenamento necess\u00e1rio para jogos de maior fidelidade. O <strong>Switch<\/strong> atual vem com apenas 3<strong>2 GB<\/strong> de mem\u00f3ria interna, enquanto muitos jogos de PlayStation e Xbox da gera\u00e7\u00e3o atual t\u00eam mais de <strong>100 GB<\/strong>. Outros detalhes, como suporte de compatibilidade com vers\u00f5es anteriores para jogos Switch (f\u00edsicos e digitais), permanecem obscuros.<\/p>\n<p>A Nintendo disse que deseja converter o m\u00e1ximo poss\u00edvel da base de usu\u00e1rios de mais de <strong>100<\/strong> <strong>milh\u00f5es<\/strong> do Switch para seu pr\u00f3ximo sistema, embora algumas publisher terceirizados tenham expressado preocupa\u00e7\u00e3o de que o suporte legado para os jogos do Switch possa afetar negativamente as vendas de t\u00edtulos da pr\u00f3xima gera\u00e7\u00e3o.<\/p>\n<div id=\"combo-413804613\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Empresa japonesa cada vez mais pr\u00f3xima de revelar seu novo console Tudo indica que a Nintendo planeja o lan\u00e7amento do seu console de pr\u00f3xima gera\u00e7\u00e3o (concorrente de PS5 e Series X)\u00a0para o ano de 2024. De acordo com informa\u00e7\u00f5es divulgadas pela VGC, a empresa lan\u00e7ar\u00e1 um novo hardware durante o segundo semestre de 2024. O [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":159600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,47,12293,50,10258,12298,241],"tags":[39,13364],"class_list":["post-159598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-destaque","category-games","category-nintendo-2","category-nintendo-switch","category-plataformas","category-todas","tag-nintendo","tag-nintendo-switch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nintendo planeja lan\u00e7ar sucessor do Switch em 2024 - Rumor<\/title>\n<meta name=\"description\" content=\"Tudo indica que a Nintendo planeja o lan\u00e7amento do seu console de pr\u00f3xima gera\u00e7\u00e3o (concorrente de PS5 e Series X)\u00a0para o ano de 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/nintendo-planeja-lancar-sucessor-do-switch-em-2024-rumor\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/nintendo-planeja-lancar-sucessor-do-switch-em-2024-rumor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nintendo planeja lan\u00e7ar sucessor do Switch em 2024 &#8211; Rumor\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nintendo planeja lan\u00e7ar sucessor do Switch em 2024 - Rumor","description":"Tudo indica que a Nintendo planeja o lan\u00e7amento do seu console de pr\u00f3xima gera\u00e7\u00e3o (concorrente de PS5 e Series X)\u00a0para o ano de 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/nintendo-planeja-lancar-sucessor-do-switch-em-2024-rumor\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/nintendo-planeja-lancar-sucessor-do-switch-em-2024-rumor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Nintendo planeja lan\u00e7ar sucessor do Switch em 2024 &#8211; Rumor"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=159598"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/159600"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=159598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=159598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=159598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}