{"id":159661,"date":"2023-08-03T08:30:00","date_gmt":"2023-08-03T11:30:00","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=159661"},"modified":"2023-08-03T08:32:26","modified_gmt":"2023-08-03T11:32:26","slug":"xbox-permitira-jogadores-transmitirem-gameplay-diretamente-discord","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/xbox-permitira-jogadores-transmitirem-gameplay-diretamente-discord\/","title":{"rendered":"Xbox: Jogadores poder\u00e3o transmitir gameplay via Discord"},"content":{"rendered":"<h4 style=\"text-align: center;\">Microsoft segue realizando parcerias com o Discord<\/h4>\n<p>Em breve, o <a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/xbox\" target=\"_blank\" rel=\"noopener\"><strong>Xbox<\/strong> <\/a>permitir\u00e1 que os jogadores transmitam sua jogabilidade diretamente para o Discord, em mais uma novidade com a plataforma.<\/p><div id=\"combo-3232266604\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com post no blog oficial do <a href=\"https:\/\/news.xbox.com\/en-us\/2023\/08\/02\/stream-from-xbox-to-your-discord-friends\/\" target=\"_blank\" rel=\"noopener\"><strong>Xbox Wire<\/strong><\/a>, os jogadores poder\u00e3o transmitir jogos para seus amigos simplesmente escolhendo uma op\u00e7\u00e3o espec\u00edfica.<\/p>\n<hr \/>\n<p><strong>\u201cPara come\u00e7ar, voc\u00ea pode ingressar em canais de voz de seus servidores Discord diretamente de seu console quando sua conta Discord estiver vinculada.&#8221;<\/strong><\/p>\n<p><strong>\u201cPara experimentar, pressione o bot\u00e3o Xbox no seu controle para abrir o guia, v\u00e1 at\u00e9 Festas e bate-papos e selecione Discord. Em seguida, percorra os servidores Discord dispon\u00edveis, escolha um canal de voz e comece a transmitir.&#8221;<\/strong><\/p><div id=\"combo-3640781205\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><strong>&#8220;Estamos empolgados em ouvir seus coment\u00e1rios enquanto voc\u00ea experimenta e tamb\u00e9m empolgados com o que o futuro reserva para o Discord.\u201d<\/strong><\/p>\n<hr \/>\n<p>O recurso lan\u00e7ou com exclusividade para os membros do Insider nos modos Alpha Skip-Ahead e Alpha. Estes contemplados com a novidade providenciar\u00e3o feedbacks para a Microsoft ajustar poss\u00edveis problemas antes do lan\u00e7amento geral.<\/p>\n<p>No ano passado, a Microsoft adicionou a capacidade de ingressar nos canais de voz do Discord diretamente de um console Xbox. O Discord fundou em 2015 como plataforma para jogadores de videogame conversarem enquanto jogam online. Atualmente, possui mais de 150 milh\u00f5es de usu\u00e1rios mensais, com diversas comunidades.<\/p><div id=\"combo-2686490897\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<div id=\"combo-1288926101\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Microsoft segue realizando parcerias com o Discord Em breve, o Xbox permitir\u00e1 que os jogadores transmitam sua jogabilidade diretamente para o Discord, em mais uma novidade com a plataforma. De acordo com post no blog oficial do Xbox Wire, os jogadores poder\u00e3o transmitir jogos para seus amigos simplesmente escolhendo uma op\u00e7\u00e3o espec\u00edfica. \u201cPara come\u00e7ar, voc\u00ea [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":159662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,12298,241,49,8,41590],"tags":[40,31],"class_list":["post-159661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-plataformas","category-todas","category-xbox","category-xboxone","category-xbox-series","tag-microsoft","tag-xbox"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Xbox: Jogadores poder\u00e3o transmitir gameplay via Discord<\/title>\n<meta name=\"description\" content=\"Em breve, o Xbox permitir\u00e1 que os jogadores transmitam sua jogabilidade diretamente para o Discord, em mais uma novidade com a plataforma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/xbox-permitira-jogadores-transmitirem-gameplay-diretamente-discord\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/xbox-permitira-jogadores-transmitirem-gameplay-diretamente-discord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xbox: Jogadores poder\u00e3o transmitir gameplay via Discord\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Xbox: Jogadores poder\u00e3o transmitir gameplay via Discord","description":"Em breve, o Xbox permitir\u00e1 que os jogadores transmitam sua jogabilidade diretamente para o Discord, em mais uma novidade com a plataforma.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/xbox-permitira-jogadores-transmitirem-gameplay-diretamente-discord\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/xbox-permitira-jogadores-transmitirem-gameplay-diretamente-discord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Xbox: Jogadores poder\u00e3o transmitir gameplay via Discord"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=159661"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159661\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/159662"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=159661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=159661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=159661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}