{"id":159680,"date":"2023-08-03T15:08:06","date_gmt":"2023-08-03T18:08:06","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=159680"},"modified":"2023-08-03T16:13:57","modified_gmt":"2023-08-03T19:13:57","slug":"resident-evil-2-remake-alcanca-12-milhoes-de-vendas","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-2-remake-alcanca-12-milhoes-de-vendas\/","title":{"rendered":"Resident Evil 2 Remake alcan\u00e7a 12 milh\u00f5es de vendas, e ultrapassa RE7!"},"content":{"rendered":"<h4 style=\"text-align: center;\">Leon e Claire seguem rendendo muitos lucros \u00e0 Capcom<\/h4>\n<p>A <strong>Capcom<\/strong> comemora nesta semana os novos n\u00fameros alcan\u00e7ados pelo jogo<a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/resident-evil\" target=\"_blank\" rel=\"noopener\"> <strong>Resident Evil 2 Remake<\/strong><\/a>, outro grande sucesso da franquia.<\/p><div id=\"combo-1641450240\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com a empresa japonesa em seu <a href=\"https:\/\/www.capcom.co.jp\/ir\/english\/business\/million.html\" target=\"_blank\" rel=\"noopener\"><strong>relat\u00f3rio<\/strong> <strong>fiscal<\/strong><\/a> mais recente, o remake lan\u00e7ado em 2019 atingiu<strong> 12,9<\/strong> <strong>milh\u00f5es<\/strong> de unidades. Ou seja, mais de<strong> 700.000<\/strong> unidades foram vendidas no primeiro trimestre fiscal deste ano (abril a junho). Este \u00e9 um feito relevante, considerando o tempo de lan\u00e7amento do jogo.<\/p>\n<p>Al\u00e9m disso, os n\u00fameros atualizados mostram que<strong> RE2 Remake<\/strong> <strong>ultrapassou<\/strong> <strong>RE7<\/strong> (12,4 milh\u00f5es) na quantidade de unidades vendidas. Este \u00e9 o single mais vendido, pois os n\u00fameros de RE5 combinam todos os lan\u00e7amentos (incluindo a vers\u00e3o Gold), com 13,9 milh\u00f5es de c\u00f3pias.<\/p>\n<p>Enquanto isso<strong>, RE: Village<\/strong> j\u00e1 atingiu<strong> 8,3 milh\u00f5e<\/strong>s de unidades, acima dos 8 milh\u00f5es de unidades no in\u00edcio de junho. O remake d<strong>e RE3<\/strong> de 2020 est\u00e1 em<strong> 7,6 milh\u00f5es<\/strong> de unidades vendidas, acima dos 7 milh\u00f5es de unidades em 31 de mar\u00e7o.<\/p><div id=\"combo-1915005323\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Recentemente, a Capcom tamb\u00e9m anunciou que o remake de<strong> Resident Evil 4,<\/strong> lan\u00e7ado em mar\u00e7o, vendeu mais de <strong>5 milh\u00f5es<\/strong> de unidades. \u00c9 poss\u00edvel que este jogo consiga alcan\u00e7ar n\u00fameros maiores antes do t\u00e9rmino do atual ano fiscal.<\/p>\n<p>O retorno do investimento na franquia Resident Evil \u00e9 um dos grandes acertos da Capcom nos \u00faltimos anos, considerando o sucesso comercial e cr\u00edtico dos jogos.<\/p>\n<div id=\"combo-417963388\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Leon e Claire seguem rendendo muitos lucros \u00e0 Capcom A Capcom comemora nesta semana os novos n\u00fameros alcan\u00e7ados pelo jogo Resident Evil 2 Remake, outro grande sucesso da franquia. De acordo com a empresa japonesa em seu relat\u00f3rio fiscal mais recente, o remake lan\u00e7ado em 2019 atingiu 12,9 milh\u00f5es de unidades. Ou seja, mais de [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":159682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,36,5,241,49,8],"tags":[15417,3527],"class_list":["post-159680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-playstation","category-ps4","category-todas","category-xbox","category-xboxone","tag-resident-evil-3","tag-resident-evil-2-remake"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resident Evil 2 Remake alcan\u00e7a 12 milh\u00f5es de vendas<\/title>\n<meta name=\"description\" content=\"A Capcom comemora nesta semana os novos n\u00fameros alcan\u00e7ados pelo jogo Resident Evil 2 Remake, outro grande sucesso da franquia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-2-remake-alcanca-12-milhoes-de-vendas\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/resident-evil-2-remake-alcanca-12-milhoes-de-vendas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resident Evil 2 Remake alcan\u00e7a 12 milh\u00f5es de vendas, e ultrapassa RE7!\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resident Evil 2 Remake alcan\u00e7a 12 milh\u00f5es de vendas","description":"A Capcom comemora nesta semana os novos n\u00fameros alcan\u00e7ados pelo jogo Resident Evil 2 Remake, outro grande sucesso da franquia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-2-remake-alcanca-12-milhoes-de-vendas\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/resident-evil-2-remake-alcanca-12-milhoes-de-vendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Resident Evil 2 Remake alcan\u00e7a 12 milh\u00f5es de vendas, e ultrapassa RE7!"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=159680"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/159682"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=159680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=159680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=159680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}