{"id":159813,"date":"2023-08-09T09:51:42","date_gmt":"2023-08-09T12:51:42","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=159813"},"modified":"2023-08-09T09:51:43","modified_gmt":"2023-08-09T12:51:43","slug":"playstation-5-alcanca-41-milhoes-de-vendas","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/playstation-5-alcanca-41-milhoes-de-vendas\/","title":{"rendered":"PlayStation 5 alcan\u00e7a 41,7 milh\u00f5es de vendas"},"content":{"rendered":"<h4 style=\"text-align: center;\">PS5 segue no mesmo ritmo de vendas do PS4<\/h4>\n<p>A <strong>Sony<\/strong> atualizou nesta quarta-feira (9) os n\u00fameros envolvendo vendas do <a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/playstation-5\" target=\"_blank\" rel=\"noopener\"><strong>PlayStation 5<\/strong><\/a> no primeiro trimestre do ano fiscal de <strong>2023<\/strong>.<\/p><div id=\"combo-4073920367\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com o <a href=\"https:\/\/www.sony.com\/en\/SonyInfo\/IR\/library\/presen\/er\/pdf\/23q1_sonypre.pdf\" target=\"_blank\" rel=\"noopener\"><strong>relat\u00f3rio<\/strong> <strong>fiscal<\/strong><\/a> divulgado, a empresa confirmou que o console da atual gera\u00e7\u00e3o vendeu <strong>41,7 milh\u00f5es<\/strong> de unidades totais. Ou seja, considerando os n\u00fameros at\u00e9 30 de junho, o <strong>PS5<\/strong> adicionou mais<strong> 900 mil unidades<\/strong> vendidas em rela\u00e7\u00e3o ao \u00faltimo trimestre fiscal.<\/p>\n<p>Al\u00e9m disso, o <strong>PlayStation Network<\/strong> atingiu 108 milh\u00f5es de usu\u00e1rios ativos na \u00faltima atualiza\u00e7\u00e3o fiscal. Isso representa um aumento de cinco milh\u00f5es de usu\u00e1rios em rela\u00e7\u00e3o ao \u00faltimo ano.<\/p>\n<p>Por fim, as vendas de software para os consoles <strong>PS4<\/strong> e <strong>PS5<\/strong> chegaram a <strong>56,5<\/strong> milh\u00f5es no trimestre. Este n\u00famero \u00e9<strong> 9,3<\/strong> milh\u00f5es superior aos 47,2 milh\u00f5es registrados no ano fiscal anterior.<\/p><div id=\"combo-1997494204\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Destes n\u00fameros revelados, <strong>62%<\/strong> foram downloads digitais para software de jogo completo, uma queda de<strong> 7%<\/strong> ano a ano, e os t\u00edtulos exclusivos contribu\u00edram com 6,6 milh\u00f5es para as vendas totais, o mesmo que no ano passado.<\/p>\n<p>Por fim, no \u00faltimo trimestre, a Sony anunciou <strong>47,4 milh\u00f5es<\/strong> de assinantes do <strong>PlayStation<\/strong> <strong>Plus<\/strong> (com Extra e Premium representando 30% do total, com 14,1 milh\u00f5es). No entanto, n\u00e3o forneceu um n\u00famero atualizado para o primeiro trimestre do ano fiscal de 2023.<\/p>\n<div id=\"combo-942166893\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>PS5 segue no mesmo ritmo de vendas do PS4 A Sony atualizou nesta quarta-feira (9) os n\u00fameros envolvendo vendas do PlayStation 5 no primeiro trimestre do ano fiscal de 2023. De acordo com o relat\u00f3rio fiscal divulgado, a empresa confirmou que o console da atual gera\u00e7\u00e3o vendeu 41,7 milh\u00f5es de unidades totais. Ou seja, considerando [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":159292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,12298,36,20651,241],"tags":[7849,8274],"class_list":["post-159813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-plataformas","category-playstation","category-ps5","category-todas","tag-ps5","tag-sony"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PlayStation 5 alcan\u00e7a 41,7 milh\u00f5es de vendas<\/title>\n<meta name=\"description\" content=\"A Sony atualizou nesta quarta-feira (9) os n\u00fameros envolvendo vendas do PlayStation 5 no primeiro trimestre do ano fiscal de 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/playstation-5-alcanca-41-milhoes-de-vendas\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/playstation-5-alcanca-41-milhoes-de-vendas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PlayStation 5 alcan\u00e7a 41,7 milh\u00f5es de vendas\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PlayStation 5 alcan\u00e7a 41,7 milh\u00f5es de vendas","description":"A Sony atualizou nesta quarta-feira (9) os n\u00fameros envolvendo vendas do PlayStation 5 no primeiro trimestre do ano fiscal de 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/playstation-5-alcanca-41-milhoes-de-vendas\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/playstation-5-alcanca-41-milhoes-de-vendas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"PlayStation 5 alcan\u00e7a 41,7 milh\u00f5es de vendas"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=159813"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/159813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/159292"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=159813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=159813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=159813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}