{"id":160010,"date":"2023-08-16T11:14:21","date_gmt":"2023-08-16T14:14:21","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=160010"},"modified":"2023-08-16T11:14:56","modified_gmt":"2023-08-16T14:14:56","slug":"baldurs-gate-3-primeiro-patch-contara-com-mais-1-000-correcoes","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/baldurs-gate-3-primeiro-patch-contara-com-mais-1-000-correcoes\/","title":{"rendered":"Baldur&#8217;s Gate 3: Primeiro Patch contar\u00e1 com mais 1.000 corre\u00e7\u00f5es"},"content":{"rendered":"\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"h-o-patch-1-contara-com-os-creditos-aos-tradutores\"><strong>O Patch 1 contar\u00e1 com os cr\u00e9ditos aos tradutores<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a chegada do Hotfix 3, a <a href=\"https:\/\/twitter.com\/larianstudios\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Larian Studios<\/mark><\/a> j\u00e1 est\u00e1 empenhada em levar para <a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/baldurs-gate-3\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-green-cyan-color\">Baldur\u2019s Gate 3<\/mark><\/a> seu primeiro grande Patch, o qual contar\u00e1 com mais de mil corre\u00e7\u00f5es e ajustes.<\/p><div id=\"combo-23050497\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Contudo, antes disso, teremos um Hotfix #4, que ainda n\u00e3o tem data de estreia.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"twitter-tweet\"><blockquote class=\"twitter-tweet\" data-lang=\"pt\"><p lang=\"en\" dir=\"ltr\">We&#39;re all very enthused by your feedback. It&#39;s very rewarding. Our focus now is fixing any issues you report, but we are listening to suggestions. Current roadmap: a) Hotfix 4, b) Patch 1 (+1000 fixes and tweaks), c) Patch 2. The latter will already incorporate some requests.<\/p>&mdash; Swen Vincke @where? (@LarAtLarian) <a href=\"https:\/\/twitter.com\/LarAtLarian\/status\/1691479778488909827?ref_src=twsrc%5Etfw\">15 de agosto de 2023<\/a><\/blockquote><\/div>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, o Patch 1 contara tamb\u00e9m a presen\u00e7a dos cr\u00e9ditos para os in\u00fameros tradutores, inclusive do Portugu\u00eas do Brasil, que n\u00e3o tiveram os devidos cr\u00e9ditos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, um segundo patch j\u00e1 est\u00e1 em andamento, o qual contar\u00e1 com novas sugest\u00f5es e corre\u00e7\u00f5es vindas da comunidade.<\/p><div id=\"combo-4180073513\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Baldur&#8217;s Gate 3 no primeiro final de semana de sua estreia acumulou cerca de 10 milh\u00f5es de horas jogadas e registrou apenas 368 jogadores que conclu\u00edram a campanha principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, o t\u00edtulo se tornou o game de PC mais bem avaliado de todos os tempos e de 2023 com base no Metacritic e no Opencritic, superando, assim, The Legend of Zelda: Tears of the Kingdom com uma pontua\u00e7\u00e3o 97.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em suma, Baldur\u2019s Gate 3 j\u00e1 est\u00e1 dispon\u00edvel no PC desde o dia 3 de agosto e uma vers\u00e3o para PS5 chegar\u00e1 mercado em 6 de setembro com suporte a cross-save com o PC.<\/p><div id=\"combo-510418949\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-1502523190\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>O Patch 1 contar\u00e1 com os cr\u00e9ditos aos tradutores Ap\u00f3s a chegada do Hotfix 3, a Larian Studios j\u00e1 est\u00e1 empenhada em levar para Baldur\u2019s Gate 3 seu primeiro grande Patch, o qual contar\u00e1 com mais de mil corre\u00e7\u00f5es e ajustes. Contudo, antes disso, teremos um Hotfix #4, que ainda n\u00e3o tem data de estreia. [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":159718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,36,20651,241],"tags":[28919,84236,79],"class_list":["post-160010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-playstation","category-ps5","category-todas","tag-baldurs-gate-3","tag-larian-studios-2","tag-steam"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baldur&#039;s Gate 3: Primeiro Patch contar\u00e1 com mais 1.000 corre\u00e7\u00f5es<\/title>\n<meta name=\"description\" content=\"A Larian Studios revelou que o primeiro grande patch para Baldur&#039;s Gate 3 contar\u00e1 com mais de mil corre\u00e7\u00f5es e ajustes. Confira!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/baldurs-gate-3-primeiro-patch-contara-com-mais-1-000-correcoes\/\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Ant\u00f4nio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/baldurs-gate-3-primeiro-patch-contara-com-mais-1-000-correcoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baldur&#8217;s Gate 3: Primeiro Patch contar\u00e1 com mais 1.000 corre\u00e7\u00f5es\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baldur's Gate 3: Primeiro Patch contar\u00e1 com mais 1.000 corre\u00e7\u00f5es","description":"A Larian Studios revelou que o primeiro grande patch para Baldur's Gate 3 contar\u00e1 com mais de mil corre\u00e7\u00f5es e ajustes. Confira!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/baldurs-gate-3-primeiro-patch-contara-com-mais-1-000-correcoes\/","author":"Jo\u00e3o Ant\u00f4nio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/baldurs-gate-3-primeiro-patch-contara-com-mais-1-000-correcoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Baldur&#8217;s Gate 3: Primeiro Patch contar\u00e1 com mais 1.000 corre\u00e7\u00f5es"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/160010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=160010"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/160010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/159718"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=160010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=160010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=160010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}