{"id":163022,"date":"2023-12-17T09:30:00","date_gmt":"2023-12-17T12:30:00","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=163022"},"modified":"2023-12-17T15:43:17","modified_gmt":"2023-12-17T18:43:17","slug":"embracer-demite-funcionarios-da-3d-realms-estudio-de-duke-nukem","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/embracer-demite-funcionarios-da-3d-realms-estudio-de-duke-nukem\/","title":{"rendered":"Embracer demite funcion\u00e1rios da 3D Realms, est\u00fadio de Duke Nukem"},"content":{"rendered":"<p>A <a href=\"https:\/\/www.comboinfinito.com.br\/principal\/tag\/nintendo-switchhttps:\/\/www.comboinfinito.com.br\/principal\/tag\/embracer\"><strong>Embracer Group<\/strong> <\/a>realizou neste final de semana mais uma grande rodada de demiss\u00f5es, desta vez atingindo a <strong>3D Realms.<\/strong><\/p><div id=\"combo-2965437942\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>De acordo com<a href=\"https:\/\/twitter.com\/ziacko1\/status\/1735405748656701724\" target=\"_blank\" rel=\"noopener\"><strong> diversos funcion\u00e1rios<\/strong><\/a> do est\u00fadio, muitas pessoas perderam seus empregos nos \u00faltimos dias no est\u00fadio de <strong>Duke Nukem.<\/strong> Al\u00e9m disso, muitos demonstraram surpresa com a demiss\u00e3o d<strong>e Maichael Markie<\/strong>, <strong>compositor<\/strong> <strong>principal<\/strong> da 3D Realms e da Slipgate Ironworks.<\/p>\n<p>Posteriormente, o fundador da 3D,<strong> Scott Miller,<\/strong> escreveu em um post sobre relatos de v\u00e1rias demiss\u00f5es ocorrendo na sede. Ou seja, tudo indica que a Embracer n\u00e3o informou antecipadamente ao <strong>ex-chefe<\/strong> <strong>da 3D Realms sobre as demiss\u00f5es no est\u00fadio dinamarqu\u00eas.<\/strong><\/p>\n<p>Em comunicado enviado a imprensa norte-americano, a Embracer disse que<strong> &#8220;n\u00e3o comenta rumores ou especula\u00e7\u00f5es&#8221;.<\/strong> No entanto, ressaltaram novamente o &#8220;abrangente programa de reestrutura\u00e7\u00e3o&#8221;, o qual pode incluir &#8220;<strong>fechamento de est\u00fadios e encerramento de projetos&#8221;.<\/strong><\/p><div id=\"combo-3604781733\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><strong>O est\u00fadio de Miller surgiu em 1987 como Apogee Software <\/strong>antes de ser renomeado alguns anos depois. A 3D Realms possui maior notoriedade pela cria\u00e7\u00e3o da franquia Duke Nukem.<strong> A Sabre Interactive adquiriu o est\u00fadio, antes da Embracer Group absorver a Sabre.<\/strong><\/p>\n<p>Essas demiss\u00f5es s\u00e3o apenas as mais recentes para o Grupo Embracer somente neste ano, depois que um acordo no valor de<strong> US$2 bilh\u00f5es fracassou<\/strong>. No m\u00eas passado, a Embracer revelou que mais de 900 funcion\u00e1rios est\u00e3o demitidos como parte da reestrutura\u00e7\u00e3o.<\/p>\n<div id=\"combo-1441093407\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>A Embracer Group realizou neste final de semana mais uma grande rodada de demiss\u00f5es, desta vez atingindo a 3D Realms. De acordo com diversos funcion\u00e1rios do est\u00fadio, muitas pessoas perderam seus empregos nos \u00faltimos dias no est\u00fadio de Duke Nukem. Al\u00e9m disso, muitos demonstraram surpresa com a demiss\u00e3o de Maichael Markie, compositor principal da 3D [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":163023,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,12298,241],"tags":[84929,13627,77008,69271],"class_list":["post-163022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-plataformas","category-todas","tag-3d-realms","tag-duke-nukem","tag-embracer","tag-embracer-group"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Embracer demite pessoas da 3D Realms, est\u00fadio de Duke Nukem<\/title>\n<meta name=\"description\" content=\"A Embracer Group realizou neste final de semana mais uma grande rodada de demiss\u00f5es, desta vez atingindo a 3D Realms.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/embracer-demite-funcionarios-da-3d-realms-estudio-de-duke-nukem\/\" \/>\n<meta name=\"author\" content=\"Fabr\u00edcio Carvalho\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/embracer-demite-funcionarios-da-3d-realms-estudio-de-duke-nukem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Embracer demite funcion\u00e1rios da 3D Realms, est\u00fadio de Duke Nukem\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Embracer demite pessoas da 3D Realms, est\u00fadio de Duke Nukem","description":"A Embracer Group realizou neste final de semana mais uma grande rodada de demiss\u00f5es, desta vez atingindo a 3D Realms.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/embracer-demite-funcionarios-da-3d-realms-estudio-de-duke-nukem\/","author":"Fabr\u00edcio Carvalho","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/embracer-demite-funcionarios-da-3d-realms-estudio-de-duke-nukem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Embracer demite funcion\u00e1rios da 3D Realms, est\u00fadio de Duke Nukem"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/163022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=163022"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/163022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/163023"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=163022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=163022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=163022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}