{"id":182827,"date":"2026-09-02T14:48:13","date_gmt":"2026-09-02T17:48:13","guid":{"rendered":"https:\/\/www.comboinfinito.com.br\/principal\/?p=182827"},"modified":"2026-09-02T14:48:15","modified_gmt":"2026-09-02T17:48:15","slug":"square-enix-nega-rumores-venda-empresa","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/square-enix-nega-rumores-venda-empresa\/","title":{"rendered":"Square Enix responde a rumores e nega planos de vender a empresa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center\">Publisher se pronunciou ap\u00f3s especula\u00e7\u00f5es sobre uma poss\u00edvel aquisi\u00e7\u00e3o ganharem for\u00e7a e movimentarem suas a\u00e7\u00f5es no Jap\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Square Enix<\/strong> decidiu responder aos rumores que apontavam para uma poss\u00edvel venda da companhia. Em comunicado oficial, a publisher negou as informa\u00e7\u00f5es e afirmou que n\u00e3o existem planos para deixar de ser uma empresa de capital aberto.<\/p><div id=\"combo-4259534401\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">As especula\u00e7\u00f5es come\u00e7aram ap\u00f3s uma revista japonesa de neg\u00f3cios indicar que a companhia poderia passar por um processo para se tornar privada. Nesse cen\u00e1rio, uma aquisi\u00e7\u00e3o poderia resultar na retirada das a\u00e7\u00f5es da Square Enix do mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#x1f4a1; Ofertas de Games em M\u00eddia F\u00edsica e Digital<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma pausa r\u00e1pida na not\u00edcia: se voc\u00ea deseja garantir jogos com pre\u00e7os imperd\u00edveis em m\u00eddia f\u00edsica ou digital, n\u00e3o deixe de acessar o nosso grupo de ofertas, o <strong><a href=\"https:\/\/linktr.ee\/promocoesinfinitas\" target=\"_blank\" rel=\"noopener\">Promo\u00e7\u00f5es Infinitas<\/a><\/strong>.<\/p><div id=\"combo-1767141541\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/linktr.ee\/promocoesinfinitas\" target=\"_blank\" rel=\"noopener\">Entrar no Promo\u00e7\u00f5es Infinitas \u2192<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A publica\u00e7\u00e3o rapidamente teve reflexos no mercado, provocando uma valoriza\u00e7\u00e3o moment\u00e2nea das a\u00e7\u00f5es da empresa no Jap\u00e3o. Tamb\u00e9m surgiram discuss\u00f5es sobre poss\u00edveis interessados em uma eventual compra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sony e Microsoft apareceram entre os nomes citados nas especula\u00e7\u00f5es, mas nenhuma evid\u00eancia de negocia\u00e7\u00f5es entre essas empresas e a Square Enix foi apresentada.<\/p><div id=\"combo-3910487744\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Square Enix diz que informa\u00e7\u00f5es s\u00e3o falsas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diante da repercuss\u00e3o, a <strong>Square Enix<\/strong> resolveu se manifestar diretamente. A companhia declarou que \u201cn\u00e3o h\u00e1 verdade\u201d nas informa\u00e7\u00f5es sobre planos para deixar o mercado de a\u00e7\u00f5es, descartando o rumor que circulou nas \u00faltimas horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As especula\u00e7\u00f5es tamb\u00e9m ganharam espa\u00e7o devido ao atual momento da ind\u00fastria. Em 2026, a Electronic Arts concluiu uma aquisi\u00e7\u00e3o avaliada em US$ 55 bilh\u00f5es e passou a ser controlada por um cons\u00f3rcio de investidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Square Enix, por sua vez, vem enfrentando cobran\u00e7as de alguns acionistas. A 3D Investment Partners, fundo de Singapura e acionista da publisher, j\u00e1 criticou publicamente a administra\u00e7\u00e3o e os resultados financeiros da companhia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar desse cen\u00e1rio, at\u00e9 o momento n\u00e3o existe qualquer indica\u00e7\u00e3o oficial de uma negocia\u00e7\u00e3o para vender a Square Enix. Pelo contr\u00e1rio, a pr\u00f3pria empresa afirma que os relatos recentes n\u00e3o possuem fundamento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, comente o que voc\u00ea achou da not\u00edcia. Al\u00e9m disso, compartilhe com os amigos e n\u00e3o deixe de acompanhar as nossas\u00a0<a href=\"https:\/\/www.comboinfinito.com.br\/principal\/category\/noticias\/\" target=\"_blank\" rel=\"noopener\">\u00faltimas not\u00edcias<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.comboinfinito.com.br\/principal\/category\/games\/analises\/\" target=\"_blank\" rel=\"noopener\">an\u00e1lises de s\u00e9ries e jogos<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fonte:<\/strong> <a href=\"https:\/\/www.pushsquare.com\/news\/2026\/09\/square-enix-denies-rumours-of-being-bought-out\" target=\"_blank\" rel=\"noopener\">Push Square<\/a><\/p>\n<div id=\"combo-304466749\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Publisher se pronunciou ap\u00f3s especula\u00e7\u00f5es sobre uma poss\u00edvel aquisi\u00e7\u00e3o ganharem for\u00e7a e movimentarem suas a\u00e7\u00f5es no Jap\u00e3o A Square Enix decidiu responder aos rumores que apontavam para uma poss\u00edvel venda da companhia. Em comunicado oficial, a publisher negou as informa\u00e7\u00f5es e afirmou que n\u00e3o existem planos para deixar de ser uma empresa de capital aberto. [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":177558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,50,25,36,241,49],"tags":[87733,1285,40,8274,120],"class_list":["post-182827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-nintendo-2","category-pcgames","category-playstation","category-todas","category-xbox","tag-aquisicoes","tag-industria-de-games","tag-microsoft","tag-sony","tag-square-enix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Square Enix responde a rumores e nega planos de vender a empresa - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Square Enix afirma que rumores sobre uma poss\u00edvel venda e retirada de suas a\u00e7\u00f5es do mercado s\u00e3o falsos e nega planos de se tornar privada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/square-enix-nega-rumores-venda-empresa\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/square-enix-nega-rumores-venda-empresa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Square Enix responde a rumores e nega planos de vender a empresa\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Square Enix responde a rumores e nega planos de vender a empresa - Combo Infinito","description":"Square Enix afirma que rumores sobre uma poss\u00edvel venda e retirada de suas a\u00e7\u00f5es do mercado s\u00e3o falsos e nega planos de se tornar privada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/square-enix-nega-rumores-venda-empresa\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/square-enix-nega-rumores-venda-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Square Enix responde a rumores e nega planos de vender a empresa"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/182827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=182827"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/182827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/177558"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=182827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=182827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=182827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}