{"id":30683,"date":"2016-03-16T12:56:14","date_gmt":"2016-03-16T15:56:14","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=30683"},"modified":"2016-06-25T21:18:09","modified_gmt":"2016-06-26T00:18:09","slug":"nvidia-gameworks-sdk-3-1-traz-novas-tecnicas-de-simulacao-e-renderizacao","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/nvidia-gameworks-sdk-3-1-traz-novas-tecnicas-de-simulacao-e-renderizacao\/","title":{"rendered":"NVIDIA GameWorks SDK 3.1 traz novas t\u00e9cnicas de simula\u00e7\u00e3o e renderiza\u00e7\u00e3o"},"content":{"rendered":"<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia.jpg\" rel=\"attachment wp-att-30685\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-30685\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia.jpg\" alt=\"novas-tecnologias-nvidia\" width=\"896\" height=\"504\" data-wp-pid=\"30685\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/03\/novas-tecnologias-nvidia-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p>A <strong>NVIDIA<\/strong> anuncia a disponibilidade global do kit de desenvolvimento de software<strong> NVIDIA GameWorks (SDK) 3.1<\/strong>, que apresenta tr\u00eas t\u00e9cnicas gr\u00e1ficas inovadoras para sombras e ilumina\u00e7\u00e3o, assim como dois novos algoritmos de simula\u00e7\u00e3o f\u00edsica lan\u00e7ados como betas.<\/p><div id=\"combo-2458826659\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Tony Tamasi, vice-presidente s\u00eanior de conte\u00fado e tecnologia da NVIDIA, falou sobre o novo lan\u00e7amento da empresa.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201c\u00c9 a nossa paix\u00e3o por games que nos estimula a lidar com os problemas t\u00e9cnicos apresentados na simula\u00e7\u00e3o e renderiza\u00e7\u00e3o em tempo real. Nossas tecnologias do GameWorks for\u00e7am as barreiras do que \u00e9 poss\u00edvel em tempo real, permitindo aos desenvolvedores o fornecimento de games com simula\u00e7\u00f5es e efeitos especiais de ponta.\u201d<\/em><\/p>\n<\/blockquote>\n<p>As tr\u00eas novas t\u00e9cnicas de renderiza\u00e7\u00e3o do <strong>GameWorks<\/strong> para ilumina\u00e7\u00e3o e sombras incluem:<\/p>\n<ul>\n<li>Ilumina\u00e7\u00e3o Volum\u00e9trica NVIDIA: uma t\u00e9cnica de ilumina\u00e7\u00e3o avan\u00e7ada que simula como a luz se comporta conforme ela se espalha pelo ar e atmosfera. A Ilumina\u00e7\u00e3o Volum\u00e9trica NVIDIA foi primeiramente apresentada em Fallout 4.<\/li>\n<li>Sombras h\u00edbridas tra\u00e7adas de Frustum (HFTS &#8211; Hybrid Frustum Traced Shadows): um algoritmo para o desenho de sombras de alta fidelidade que transitam suavemente de sombras s\u00f3lidas pr\u00f3ximas ao objeto que obstrui a vista a sombras suaves em regi\u00f5es mais distantes. As HFTS apareceram pela primeira vez em Tom Clancy\u2019s The Division.<\/li>\n<li>Oclus\u00e3o de Ambiente Acelerada por Voxel (VXAO &#8211; Voxel Accelerated Ambient Occlusion) NVIDIA: o algoritmo de melhor qualidade da NVIDIA para oclus\u00e3o de ambiente em tempo real, a VXAO \u00e9 uma t\u00e9cnica de sombreamento que acrescenta profundidade e realismo a qualquer cena. Ela supera tecnologias antigas ao calcular as sombras em espa\u00e7os do mundo usando toda a geometria da cena, em oposi\u00e7\u00e3o \u00e0s t\u00e9cnicas de espa\u00e7o de tela que podem apenas sombrear a partir de geometria vis\u00edvel para a c\u00e2mera. A VXAO apareceu pela primeira vez em Rise of the Tomb Raider.<\/li>\n<\/ul>\n<p>O par de extens\u00f5es para a biblioteca do NVIDIA\u00ae PhysX\u00ae inclui:<\/p><div id=\"combo-565694680\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<ul>\n<li>NVIDIA PhysX-GRB: uma nova implementa\u00e7\u00e3o do popular SDK din\u00e2mico de corpo r\u00edgido PhysX da NVIDIA, usado em centenas de games. Esse pipeline f\u00edsico h\u00edbrido de CPU\/GPU melhora a performance em at\u00e9 6 vezes, de cargas de simula\u00e7\u00e3o moderadas a cargas intensas.<\/li>\n<li>NVIDIA Flow: um algoritmo din\u00e2mico de fluidos computacionais que simula e renderiza fluidos combust\u00edveis, como fogo e fuma\u00e7a. Diferente dos m\u00e9todos anteriores, o Flow n\u00e3o se limita \u00e0 simula\u00e7\u00e3o dos fluidos dentro de uma caixa delimitadora.<\/li>\n<\/ul>\n<p>Alexandre Ziebert, gerente de marketing t\u00e9cnico da NVIDIA, tamb\u00e9m falou sobre as novas tecnologias:<\/p>\n<blockquote><p><em>\u201cCom o novo kit de tecnologias GameWorks, desenvolvedores ter\u00e3o \u00e0 sua disposi\u00e7\u00e3o diversos recursos avan\u00e7ados para deixar a ilumina\u00e7\u00e3o dos cen\u00e1rios e f\u00edsica avan\u00e7ada de elementos interativos e n\u00e3o interativos da tela. Algumas delas j\u00e1 est\u00e3o dispon\u00edveis nos t\u00edtulos mais recentes para PC, como Tom Clancy\u2019s The Division e Rise of the Tomb Raider e, uma vez habilitadas, oferecem uma experi\u00eancia visual sem precedentes na atual gera\u00e7\u00e3o de games&#8221;.<\/em><\/p><\/blockquote>\n<p>A <strong>NVIDIA<\/strong> gera c\u00f3digos fonte para bibliotecas <strong>GameWorks<\/strong> selecionadas dispon\u00edveis aos desenvolvedores atrav\u00e9s do <em>GitHub<\/em>. O c\u00f3digo fonte para a Ilumina\u00e7\u00e3o Volum\u00e9trica NVIDIA e para a demonstra\u00e7\u00e3o do FaceWorks da NVIDIA est\u00e1 dispon\u00edvel no momento. O c\u00f3digo fonte para o NVIDIA HairWorks, NVIDIA HBAO+ e NVIDIA WaveWorks ser\u00e1 disponibilizado em breve.<\/p>\n<p>Mais informa\u00e7\u00f5es sobre o NVIDIA GameWorks est\u00e3o dispon\u00edveis em <strong><a href=\"https:\/\/developer.nvidia.com\/\" target=\"_blank\">https:\/\/developer.nvidia.com\/<\/a><\/strong>.<\/p><div id=\"combo-3351749249\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-976704107\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>A NVIDIA anuncia a disponibilidade global do kit de desenvolvimento de software NVIDIA GameWorks (SDK) 3.1, que apresenta tr\u00eas t\u00e9cnicas gr\u00e1ficas inovadoras para sombras e ilumina\u00e7\u00e3o, assim como dois novos algoritmos de simula\u00e7\u00e3o f\u00edsica lan\u00e7ados como betas. Tony Tamasi, vice-presidente s\u00eanior de conte\u00fado e tecnologia da NVIDIA, falou sobre o novo lan\u00e7amento da empresa. \u201c\u00c9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,9514],"tags":[329],"class_list":["post-30683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-tecnologia","tag-nvidia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NVIDIA GameWorks SDK 3.1 traz novas t\u00e9cnicas de simula\u00e7\u00e3o e renderiza\u00e7\u00e3o - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/nvidia-gameworks-sdk-3-1-traz-novas-tecnicas-de-simulacao-e-renderizacao\/\" \/>\n<meta name=\"author\" content=\"Ariel Souza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/nvidia-gameworks-sdk-3-1-traz-novas-tecnicas-de-simulacao-e-renderizacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NVIDIA GameWorks SDK 3.1 traz novas t\u00e9cnicas de simula\u00e7\u00e3o e renderiza\u00e7\u00e3o\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NVIDIA GameWorks SDK 3.1 traz novas t\u00e9cnicas de simula\u00e7\u00e3o e renderiza\u00e7\u00e3o - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/nvidia-gameworks-sdk-3-1-traz-novas-tecnicas-de-simulacao-e-renderizacao\/","author":"Ariel Souza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/nvidia-gameworks-sdk-3-1-traz-novas-tecnicas-de-simulacao-e-renderizacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"NVIDIA GameWorks SDK 3.1 traz novas t\u00e9cnicas de simula\u00e7\u00e3o e renderiza\u00e7\u00e3o"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/30683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=30683"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/30683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/30685"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=30683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=30683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=30683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}