{"id":34861,"date":"2016-05-25T19:12:31","date_gmt":"2016-05-25T22:12:31","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=34861"},"modified":"2016-05-25T19:12:31","modified_gmt":"2016-05-25T22:12:31","slug":"netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\/","title":{"rendered":"Netflix divulga as primeiras imagens da segunda temporada de Marco Polo"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p>[tps_header]<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-34880\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01.jpg\" alt=\"marco-polo-01\" width=\"896\" height=\"504\" data-wp-pid=\"34880\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p><div id=\"combo-2029440118\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">Ap\u00f3s uma primeira temporada interessant\u00edssima diretamente na <strong>Netflix<\/strong>, <strong>Marco Polo<\/strong> est\u00e1 j\u00e1 foi confirmado para a segunda temporada e ir\u00e1 continuar suas aventuras no come\u00e7o de julho. A s\u00e9rie \u00e9 exclusiva do servi\u00e7o de streaming mais famoso do mundo e promete altas doses de emo\u00e7\u00e3o.\u00a0Num mundo repleto de gan\u00e2ncia, trai\u00e7\u00f5es, intrigas sexuais e rivalidades, <strong>Marco Polo<\/strong> conta as aventuras do famoso explorador na corte de <em>Kublai Khan<\/em>, na China do s\u00e9culo XIII, como podemos ver nas primeiras fotos da pr\u00f3xima temporada.<\/p>\n<p style=\"text-align: justify;\">John Fusco, que escreveu o roteiro do filme indicado ao Oscar <em>Spirit: O Corcel Indom\u00e1vel<\/em>, \u00e9 o criador e produtor executivo, juntamente com Dan Minahan, que tem no curr\u00edculo trabalhos em <em>Homeland<\/em> e <em>Game of Thrones<\/em>. Completando o time de produtores executivos: Patrick Macmanus, Harvey Weinstein, Bob Weinstein e Elizabeth Sarnoff.<\/p>\n<p style=\"text-align: justify;\">Os dez epis\u00f3dios da segunda temporada trazem nomes da temporada anterior e novidades: Lorenzo Richelmy (Marco Polo), Michelle Yeoh (the Handmaiden), Benedict Wong (Kublai Khan), Joan Chen (Empress Chabi), Zhu Zhu (Kokachin), Tom Wu (Hundred Eyes), Olivia Cheng (Mei Lin), Claudia Kim (Khutulun), Rick Yune (Kaidu), Remy Hii (Prince Jingim), Mahesh Jadu (Ahmad) e Uli Latukefu (Byamba), entre outros.<\/p>\n<p style=\"text-align: justify;\">A segunda temporada de <strong>Marco Polo<\/strong> ser\u00e1 lan\u00e7ada globalmente na <strong>Netflix<\/strong> no dia 1\u00ba de julho de 2016.<\/p><div id=\"combo-3226793006\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">\u00a0[\/tps_header]<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-34888\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09.jpg\" alt=\"marco-polo-09\" width=\"896\" height=\"504\" data-wp-pid=\"34888\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-09-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-34887\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08.jpg\" alt=\"marco-polo-08\" width=\"896\" height=\"504\" data-wp-pid=\"34887\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-08-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34886\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07.jpg\" alt=\"marco-polo-07\" width=\"896\" height=\"504\" data-wp-pid=\"34886\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-07-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34885\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06.jpg\" alt=\"marco-polo-06\" width=\"896\" height=\"504\" data-wp-pid=\"34885\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-06-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34884\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05.jpg\" alt=\"marco-polo-05\" width=\"896\" height=\"504\" data-wp-pid=\"34884\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-05-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34883\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04.jpg\" alt=\"marco-polo-04\" width=\"896\" height=\"504\" data-wp-pid=\"34883\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-04-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34882\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03.jpg\" alt=\"marco-polo-03\" width=\"896\" height=\"504\" data-wp-pid=\"34882\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-03-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-34881\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02.jpg\" alt=\"marco-polo-02\" width=\"896\" height=\"504\" data-wp-pid=\"34881\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-02-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><!--nextpage--><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-34880\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01.jpg\" alt=\"marco-polo-01\" width=\"896\" height=\"504\" data-wp-pid=\"34880\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/05\/marco-polo-01-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<div id=\"combo-2532121227\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>[tps_header] \u00a0 Ap\u00f3s uma primeira temporada interessant\u00edssima diretamente na Netflix, Marco Polo est\u00e1 j\u00e1 foi confirmado para a segunda temporada e ir\u00e1 continuar suas aventuras no come\u00e7o de julho. A s\u00e9rie \u00e9 exclusiva do servi\u00e7o de streaming mais famoso do mundo e promete altas doses de emo\u00e7\u00e3o.\u00a0Num mundo repleto de gan\u00e2ncia, trai\u00e7\u00f5es, intrigas sexuais e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[11148,9499],"tags":[10931,9055],"class_list":["post-34861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-netflix","category-tv-series","tag-marco-polo","tag-netflix"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Netflix divulga as primeiras imagens da segunda temporada de Marco Polo - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\/\" \/>\n<link rel=\"next\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\/2\/\" \/>\n<meta name=\"author\" content=\"Ariel Souza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netflix divulga as primeiras imagens da segunda temporada de Marco Polo - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\/","next":"https:\/\/www.comboinfinito.com.br\/principal\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\/2\/","author":"Ariel Souza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/netflix-divulga-as-primeiras-imagens-da-segunda-temporada-de-marco-polo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/34861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=34861"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/34861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/34880"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=34861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=34861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=34861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}