{"id":47094,"date":"2016-10-31T15:59:45","date_gmt":"2016-10-31T17:59:45","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=47094"},"modified":"2016-10-31T15:59:45","modified_gmt":"2016-10-31T17:59:45","slug":"veja-como-estao-as-vendas-de-titanfall-2","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/veja-como-estao-as-vendas-de-titanfall-2\/","title":{"rendered":"Veja como est\u00e3o as vendas de Titanfall 2"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-47098\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas.jpg\" alt=\"titanfall-2-vendas\" width=\"896\" height=\"504\" data-wp-pid=\"47098\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/10\/titanfall-2-vendas-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Lan\u00e7ado no meio da guerra entre<strong> Battlefield 1<\/strong> e <strong>Call of Duty: Infinite Warfare<\/strong>, <strong>Titanfall 2<\/strong> e a<strong> Respawn Entertainment<\/strong>, sua desenvolvedora, possuem um desafio gigantesco pela frente: vender bem com uma estrat\u00e9gia de lan\u00e7amento question\u00e1vel por parte da <strong>EA Games<\/strong>.<\/p><div id=\"combo-3552978127\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">Isso porque <strong>Battlefield 1<\/strong> foi lan\u00e7ado h\u00e1 poucas semanas, <strong>Titanfall 2<\/strong> chegou na \u00faltima sexta-feira dia 28 de outubro e<strong> Infinite Warfare<\/strong> ser\u00e1 lan\u00e7ado na pr\u00f3xima sexta-feira tamb\u00e9m, dia 4 de novembro. Ent\u00e3o, no meio do tiroteio, ser\u00e1 que a <strong>Respawn<\/strong> est\u00e1 conseguindo vender bem o seu novo FPS?<\/p>\n<h2 style=\"text-align: justify;\"><strong>N\u00e3o chegou no p\u00f3dio<\/strong><\/h2>\n<p style=\"text-align: justify;\">Um dos mercados que \u00e9 utilizado para medir o n\u00famero de vendas de um game \u00e9 o brit\u00e2nico. A lista dos jogos mais vendidos da semana saiu hoje, e <strong>Titanfall 2<\/strong> estreou na quarta posi\u00e7\u00e3o. Os n\u00fameros ainda n\u00e3o contam as c\u00f3pias digitais, apenas as f\u00edsicas, mas j\u00e1 serve pra se ter uma ideia sobre como o t\u00edtulo da <strong>EA<\/strong> e <strong>Respawn<\/strong> pode se sair em n\u00famero de vendas. Definitivamente a quarta posi\u00e7\u00e3o n\u00e3o \u00e9 algo ruim, mas fica consideravelmente longe do que as duas empresas poderiam esperar de um jogo que recebeu cr\u00edticas muito positivas, at\u00e9 mais altas que as de <strong>Battlefield 1<\/strong>, o que \u00e9 um grande feito.<\/p>\n<p style=\"text-align: justify;\"><strong>Titanfall 2<\/strong> ficou atr\u00e1s do pr\u00f3prio<a href=\"http:\/\/www.comboinfinito.com.br\/principal\/analise-battlefield-1-uma-guerra-emocionante-e-memoravel\/\" target=\"_blank\"><strong> Battlefield 1<\/strong><\/a>, <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/?s=skyrim\" target=\"_blank\"><strong>The Elder Scrolls V: Skyrim Special Edition<\/strong><\/a> (mostrando que a estrat\u00e9gia da <strong>Bethesda<\/strong> pode estar dando certo, <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/bethesda-vs-imprensa-todo-mundo-perde-com-a-decisao-da-desenvolvedora\/\" target=\"_blank\"><strong>apesar de question\u00e1vel<\/strong><\/a>), e<strong><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/analise-fifa-17-mantem-a-lideranca-dos-jogos-de-futebol-com-boas-novidades\/\" target=\"_blank\"> FIFA 17<\/a>.<\/strong> A <strong>EA<\/strong> domina a lista das vendas, o que talvez amenize o fato de <strong>Titanfall<\/strong> <strong>2<\/strong> n\u00e3o ter estreado t\u00e3o bem assim.<\/p><div id=\"combo-3474352366\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<h2 style=\"text-align: justify;\"><strong>Audi\u00eancia mais ampla n\u00e3o foi o suficiente<\/strong><\/h2>\n<p style=\"text-align: justify;\"><strong>Titanfall 2<\/strong> foi lan\u00e7ado para<strong> PS4, Xbox One<\/strong> e <strong>PC<\/strong>, diferente do t\u00edtulo original, lan\u00e7ado em 2014 e que foi exclusivo dos consoles <strong>Xbox<\/strong> (<strong>360<\/strong> e <strong>One<\/strong>) e que tamb\u00e9m chegou ao PC. Na \u00e9poca, <strong>Titanfall<\/strong> estreou no primeiro lugar da mesma lista e se manteve na aclamada posi\u00e7\u00e3o por cinco semanas consecutivas.<\/p>\n<p style=\"text-align: justify;\">N\u00f3s j\u00e1 jogamos<strong> Titanfall 2<\/strong> e traremos nossa an\u00e1lise muito em breve, que sem d\u00favida ser\u00e1 bastante positiva. Fique ligado pra saber de todos os detalhes e se quiser, assista ao v\u00eddeo abaixo, que foi transmitido ao vivo durante o final de semana, direto do <a href=\"https:\/\/www.youtube.com\/channel\/UC_GqAJpzUzTkXzTIXBYXk1w?sub_confirmation=1\" target=\"_blank\">nosso canal no <strong>Youtube<\/strong><\/a>.<\/p>\n<p><iframe title=\"Titanfall 2 Ao Vivo\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/aA28j2OhW00?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-387733794\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Lan\u00e7ado no meio da guerra entre Battlefield 1 e Call of Duty: Infinite Warfare, Titanfall 2 e a Respawn Entertainment, sua desenvolvedora, possuem um desafio gigantesco pela frente: vender bem com uma estrat\u00e9gia de lan\u00e7amento question\u00e1vel por parte da EA Games. Isso porque Battlefield 1 foi lan\u00e7ado h\u00e1 poucas semanas, Titanfall 2 chegou na \u00faltima [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":47098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,36,5,241,49,8],"tags":[5292,6256,13421],"class_list":["post-47094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-playstation","category-ps4","category-todas","category-xbox","category-xboxone","tag-lancamentos","tag-titanfall-2","tag-titanfall-2-vendas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veja como est\u00e3o as vendas de Titanfall 2 - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/veja-como-estao-as-vendas-de-titanfall-2\/\" \/>\n<meta name=\"author\" content=\"Ariel Souza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/veja-como-estao-as-vendas-de-titanfall-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veja como est\u00e3o as vendas de Titanfall 2\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veja como est\u00e3o as vendas de Titanfall 2 - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/veja-como-estao-as-vendas-de-titanfall-2\/","author":"Ariel Souza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/veja-como-estao-as-vendas-de-titanfall-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Veja como est\u00e3o as vendas de Titanfall 2"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/47094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=47094"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/47094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/47098"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=47094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=47094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=47094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}