{"id":48117,"date":"2016-11-16T18:47:13","date_gmt":"2016-11-16T20:47:13","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=48117"},"modified":"2016-11-16T18:48:29","modified_gmt":"2016-11-16T20:48:29","slug":"jogo-misterioso-da-ubisoft-encontrado-dentro-de-watch-dogs-2-e-real","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/jogo-misterioso-da-ubisoft-encontrado-dentro-de-watch-dogs-2-e-real\/","title":{"rendered":"Jogo misterioso da Ubisoft encontrado dentro de Watch Dogs 2 \u00e9 real"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-48121\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer.jpg\" alt=\"ubisoft-pioneer\" width=\"896\" height=\"504\" data-wp-pid=\"48121\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/11\/ubisoft-pioneer-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Em uma das miss\u00f5es de <strong>Watch Dogs 2<\/strong> a <strong>Ubisoft<\/strong> teve a genial ideia de colocar um <em>easter egg<\/em> dos bons, em que devemos roubar o trailer de um poss\u00edvel novo jogo da companhia francesa. Pois bem, eis que segundo o site <strong>Kotaku<\/strong>, esse jogo pode ser algo que vai muito al\u00e9m da brincadeira.<\/p><div id=\"combo-2510740401\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">O site em quest\u00e3o \u00e9 conhecido por conseguir furos de reportagens e inclusive sofrer retalha\u00e7\u00e3o das produtoras de games por conta das informa\u00e7\u00f5es que vaza. Ent\u00e3o, podemos dar um voto de confian\u00e7a no que eles est\u00e3o dizendo, at\u00e9 porque tudo parece fazer sentido.<\/p>\n<p style=\"text-align: justify;\">O <strong>Kotaku<\/strong> diz que o trailer \u00e9 de um projeto chamado <strong>Pioneer<\/strong> (nome provis\u00f3rio), que seria um jogo de fic\u00e7\u00e3o cient\u00edfica. No entanto, algum problema parece ter acontecido na produ\u00e7\u00e3o do game, o que pode fazer com que qualquer informa\u00e7\u00e3o realmente vinda da <strong>Ubisoft<\/strong>, possa demorar bastante pra ser divulgada. A fonte do <strong>Kotaku<\/strong> falou sobre os motivos do projeto <strong>Pioneer<\/strong> estar na geladeira.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>&#8220;Era para que esse projeto fosse anunciado j\u00e1 no pr\u00f3ximo ano. Mas n\u00e3o ser\u00e1 anunciado t\u00e3o cedo, j\u00e1 que Pioneer est\u00e1 passando por uma reestrutura\u00e7\u00e3o. Quando decidiram fazer o easter egg em Watch Dogs 2, n\u00e3o sabiam que isso ia acontecer, ent\u00e3o agora ficou um inc\u00f4modo no ar.&#8221;<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Tudo indica que ficaremos sabendo logo de alguma coisa nova relacionada ao jogo, j\u00e1 que se essa informa\u00e7\u00e3o do <strong>Kotaku<\/strong> for verdadeira, jogou uma press\u00e3o pra cima da <strong>Ubisoft<\/strong>, que deve se posicionar e revelar o jogo de uma vez ou botar um pano por cima pra que a gente esque\u00e7a do projeto por um tempo. Veremos!<\/p><div id=\"combo-23385759\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p style=\"text-align: justify;\">Para saber do que se trata o misterioso jogo, voc\u00ea pode ver o trailer abaixo, direto de <strong>Watch Dogs 2<\/strong>.<\/p>\n<p><iframe title=\"NEW Unseen Ubisoft Sci-Fi Game Trailer *WITH SOUND*\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/pquADFwMYqg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-406456905\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Em uma das miss\u00f5es de Watch Dogs 2 a Ubisoft teve a genial ideia de colocar um easter egg dos bons, em que devemos roubar o trailer de um poss\u00edvel novo jogo da companhia francesa. Pois bem, eis que segundo o site Kotaku, esse jogo pode ser algo que vai muito al\u00e9m da brincadeira. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":48121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,36,5,49,8],"tags":[13548,13547,33,4379],"class_list":["post-48117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-playstation","category-ps4","category-xbox","category-xboxone","tag-jogo-misterioso","tag-pioneer","tag-ubisoft","tag-watch-dogs-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jogo misterioso da Ubisoft encontrado dentro de Watch Dogs 2 \u00e9 real - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/jogo-misterioso-da-ubisoft-encontrado-dentro-de-watch-dogs-2-e-real\/\" \/>\n<meta name=\"author\" content=\"Ariel Souza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/jogo-misterioso-da-ubisoft-encontrado-dentro-de-watch-dogs-2-e-real\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jogo misterioso da Ubisoft encontrado dentro de Watch Dogs 2 \u00e9 real\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jogo misterioso da Ubisoft encontrado dentro de Watch Dogs 2 \u00e9 real - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/jogo-misterioso-da-ubisoft-encontrado-dentro-de-watch-dogs-2-e-real\/","author":"Ariel Souza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/jogo-misterioso-da-ubisoft-encontrado-dentro-de-watch-dogs-2-e-real\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Jogo misterioso da Ubisoft encontrado dentro de Watch Dogs 2 \u00e9 real"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/48117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=48117"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/48117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/48121"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=48117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=48117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=48117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}