{"id":52201,"date":"2017-01-25T13:28:44","date_gmt":"2017-01-25T15:28:44","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=52201"},"modified":"2017-01-25T13:36:22","modified_gmt":"2017-01-25T15:36:22","slug":"dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\/","title":{"rendered":"Dragon Ball Xenoverse 2 receber\u00e1 deus da destrui\u00e7\u00e3o como novo personagem"},"content":{"rendered":"<p>[tps_header]<\/p><div id=\"combo-2293063319\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-52203\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52203\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p>A <strong>Bandai Namco<\/strong> anunciou novos detalhes do pr\u00f3ximo pacote de DLC que via chegar \u00e0 <strong>Dragon Ball Xenoverse 2<\/strong>. Aproveitando a estreia da nova saga do anime, em que os 12 universos v\u00e3o colidir no maior torneio j\u00e1 visto na hist\u00f3ria de <strong>Dragon Ball,<\/strong> o <strong>DB Super Pack 2<\/strong> vai adicionar<em> Champa<\/em> e <em>Vados<\/em> como personagens jog\u00e1veis.<\/p>\n<p>Al\u00e9m do deus da destrui\u00e7\u00e3o e seu anjo, um novo cen\u00e1rio do pr\u00f3prio torneio dos 12 universos ser\u00e1 adicionado ao jogo. Personagens customiz\u00e1veis\u00a0ter\u00e3o novos ataques e roupas.<\/p>\n<p>A desenvolvedora ainda promete mais conte\u00fado gratuito chegando junto com o DLC pago, incluindo novas roupas, acess\u00f3rios adicionais e ataques. A <strong>Bandai Namco<\/strong> diz para esperarmos, j\u00e1 que nas pr\u00f3ximas semanas novas informa\u00e7\u00f5es ser\u00e3o divulgadas. Veja imagens dos novos personagens abaixo:<\/p><div id=\"combo-1019768015\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>[\/tps_header]<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-52206\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52206\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-01-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-52205\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52205\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-02-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-52204\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52204\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-03-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p><!--nextpage--> <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-52203\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52203\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/xenoverse-2-novos-personagens-img-04-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[tps_footer]<\/p>\n<p>No dia 5 de fevereiro vai come\u00e7ar a nova saga de Dragon Ball Super, trazendo diversos combatentes lutando entre si para decidir quem \u00e9 o mais forte de todos eles. Muitos personagens novos ser\u00e3o inseridos na saga, e ser\u00e1 interessante ver alguns deles serem adicionados \u00e0 <strong>Xenoverse 2<\/strong> no futuro.<\/p><div id=\"combo-172646742\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Esse tipo de conte\u00fado, seguindo o anime, poder\u00e1 dar uma vida bem maior \u00e0 Xenoverse 2. Fique ligado que qualquer novidade traremos em primeira m\u00e3o para voc\u00eas! Para saber tudo que o novo pacote de DLC vai trazer com mais detalhes, acesse a p\u00e1gina oficial da Bandai Namco no Facebook, <a href=\"https:\/\/www.facebook.com\/BandaiNamcoUS\/posts\/10154884920230629\" target=\"_blank\"><strong>clicando aqui<\/strong><\/a>.<\/p>\n<p>Dragon Ball Xenoverse 2 foi lan\u00e7ado no dia 26 de outubro para <strong>PS4, Xbox One<\/strong> e <strong>PC<\/strong>. O jogo tamb\u00e9m ser\u00e1 lan\u00e7ado para o <strong>Nintendo Switch<\/strong>, logo que o console foi lan\u00e7ado.<\/p>\n<p>[\/tps_footer]<\/p>\n<p>&nbsp;<\/p>\n<div id=\"combo-2178364483\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>[tps_header] A Bandai Namco anunciou novos detalhes do pr\u00f3ximo pacote de DLC que via chegar \u00e0 Dragon Ball Xenoverse 2. Aproveitando a estreia da nova saga do anime, em que os 12 universos v\u00e3o colidir no maior torneio j\u00e1 visto na hist\u00f3ria de Dragon Ball, o DB Super Pack 2 vai adicionar Champa e Vados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,50,10258,25,12298,36,5,241,49,8],"tags":[11251,8262,11444],"class_list":["post-52201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-nintendo-2","category-nintendo-switch","category-pcgames","category-plataformas","category-playstation","category-ps4","category-todas","category-xbox","category-xboxone","tag-dragon-ball","tag-dragon-ball-3ds","tag-dragon-ball-xenoverse-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dragon Ball Xenoverse 2 receber\u00e1 deus da destrui\u00e7\u00e3o como novo personagem - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\/\" \/>\n<link rel=\"next\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\/2\/\" \/>\n<meta name=\"author\" content=\"Ariel Souza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dragon Ball Xenoverse 2 receber\u00e1 deus da destrui\u00e7\u00e3o como novo personagem - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\/","next":"https:\/\/www.comboinfinito.com.br\/principal\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\/2\/","author":"Ariel Souza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/dragon-ball-xenoverse-2-recebera-deus-da-destruicao-como-novo-personagem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/52201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=52201"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/52201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/52203"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=52201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=52201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=52201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}