{"id":52542,"date":"2017-01-30T11:51:39","date_gmt":"2017-01-30T13:51:39","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=52542"},"modified":"2017-01-30T11:51:39","modified_gmt":"2017-01-30T13:51:39","slug":"deus-ex-franquia-entra-na-geladeira-da-square-enix-apos-baixo-retorno-e-outros-projetos","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/deus-ex-franquia-entra-na-geladeira-da-square-enix-apos-baixo-retorno-e-outros-projetos\/","title":{"rendered":"Deus EX: Franquia entra na geladeira da Square Enix ap\u00f3s baixo retorno e outros projetos"},"content":{"rendered":"<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-52545\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52545\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/deus-ex-na-geladeira-da-square-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p><strong>Deus EX: Mankind Divided<\/strong> foi uma investida da<strong> Square Enix \/ Eidos<\/strong> para tentar popularizar ainda mais a franquia<strong> Deus Ex<\/strong>, que \u00e9 velha de guerra no mundo dos games, mas nunca foi um jogo para a massa. Reconhecidamente uma franquia de alta qualidade desde os prim\u00f3rdios do jogo de 2000, o primeiro dessa grande saga, ainda falta o sucesso comercial exigido pelo mercado, para que a franquia se torne algo de primeiro escal\u00e3o dentro da <strong>Square<\/strong>.<\/p><div id=\"combo-2033290614\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>No entanto, as baixas vendas de <strong>Mankind Divided<\/strong> for\u00e7am a <strong>Square Enix<\/strong> a deixar a franquia de lado um pouco mais do que eles gostariam. De acordo com o site <strong>Eurogamer<\/strong>,<strong> Deus Ex<\/strong> n\u00e3o vai retornar t\u00e3o cedo por diversos motivos, al\u00e9m do insucesso comercial do \u00faltimo jogo. O principal por\u00e9m tamb\u00e9m \u00e9 o fato da <strong>Eidos<\/strong> estar envolvida com diversos outros projetos de grande import\u00e2ncia, como o pr\u00f3ximo <strong>Tomb Raider.<\/strong><\/p>\n<p>A\u00ed voc\u00ea se pergunta: &#8220;<em>Mas Tomb Raider n\u00e3o \u00e9 um jogo desenvolvido pela Crystal Dynamics?&#8221;<\/em>. Voc\u00ea tem toda raz\u00e3o, mas a <strong>Eidos<\/strong> est\u00e1 envolvida com <strong>Shadow of the Tomb Raider <\/strong>(nome n\u00e3o confirmado)\u00a0e em ajudar a<strong> Crystal Dynamics<\/strong> com projetos envolvendo a parceria da <strong>Marvel<\/strong> e <strong>Square<\/strong>, que se uniram para criar o universo de jogos da casa das ideias. Com isso, <strong>Deus Ex<\/strong> acaba ficando em terceiro plano, principalmente por se tratar de um jogo que exige uma aten\u00e7\u00e3o e esfor\u00e7os muito grandes e retorno baixo, se comparado com o potencial dos demais projetos que a <strong>Eidos<\/strong> est\u00e1 envolvida.<\/p>\n<h2><strong>Mas afinal, o que est\u00e1 rolando dentro da Square Enix?<\/strong><\/h2>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-52389\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"52389\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/01\/Project-Avengers-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p>Com a parceria da <strong>Marvel<\/strong> com a <strong>Square<\/strong>, podemos esperar que a <strong>Crystal Dynamics<\/strong> e a <strong>Eidos<\/strong> acabem focadas em projetos referentes \u00e0 esta parceria, levando em conta que os dois est\u00fadios s\u00e3o os bra\u00e7os mais fortes da <strong>Square<\/strong> no ocidente, junto com a <strong>IO Interactive<\/strong>, respons\u00e1vel por <strong>Hitman<\/strong>. Resumidamente, a <strong>Square<\/strong> agora possui muitos jogos para trabalhar e pouca m\u00e3o de obra, o que pode fazer com que projetos vindos dela mesma, tenham que esperar um pouco mais.<\/p><div id=\"combo-2637276338\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Vale lembrar que estamos falando da<strong> Square Enix<\/strong> do ocidente, o que n\u00e3o deve influenciar em projetos da <strong>Square Enix<\/strong> do Jap\u00e3o, respons\u00e1vel por jogos como <strong>Final Fantasy VII<\/strong> e <strong>Kingodom Hearts 3.<\/strong><\/p>\n<h2><strong>O que houve de errado com Mankind Divided?<\/strong><\/h2>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-33291\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"33291\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2016\/04\/deus-x-mankind-divided-trailer-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p><strong>Deus Ex: Mankind Divided<\/strong> \u00e9, sem d\u00favida alguma, um jogo excelente, como voc\u00ea pode ver em nossa an\u00e1lise. No entanto, h\u00e1 a n\u00edtida impress\u00e3o que muito do que poderia ter sido mostrado pela hist\u00f3ria, ficou para o terceiro jogo, para uma poss\u00edvel conclus\u00e3o de uma trilogia envolvendo<em> Adam Jensen<\/em>, e com isso, o final de <strong>Mankind Divided<\/strong> se fechou de maneira muito abrupta, o que desagradou muita gente e tirou alguns pontos nas an\u00e1lises de alguns ve\u00edculos.<\/p>\n<p>O site <strong>Eurogamer<\/strong> sup\u00f5e que a <strong>Eidos<\/strong> possa deixar de lado o terceiro jogo e concluir a saga atrav\u00e9s de algum conte\u00fado expansivo, como um quadrinho ou filme, mas ainda tudo isso \u00e9 um rumor e podemos esperar sim por um terceiro jogo da nova saga. Vale lembrar que tudo que a gente v\u00ea na hist\u00f3ria de <strong>Deus Ex<\/strong> com<em> Adam Jensen<\/em> se passa anos antes dos primeiros jogos da franquia, o que abre possibilidade para novas hist\u00f3rias independentemente do que vimos nos \u00faltimos jogos.<\/p><div id=\"combo-1231044121\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Por enquanto, aos f\u00e3s resta aguardar por novas informa\u00e7\u00f5es e que a<strong> Square Enix<\/strong> saiba lidar com a demanda de projetos que tem agora.<strong> Deus Ex: Mankind Divided<\/strong> foi lan\u00e7ado no dia 23 de agosto de 2016 para <strong>PC<\/strong>, <strong>PS4<\/strong> e <strong>Xbox One<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe title=\"Deus Ex Mankind Divided - O Come\u00e7o do Jogo | ComboPlay\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/Fx6XhJCRDV4?start=1040&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<hr \/>\n<p><strong>Fonte: <a href=\"http:\/\/eurogamer-pt.digidip.net\/visit?url=http%3A%2F%2Fwww.eurogamer.net%2Farticles%2F2017-01-30-dont-expect-another-deus-ex-game-anytime-soon&amp;ppref=http%3A%2F%2Fwww.eurogamer.pt%2F\" target=\"_blank\">Eurogamer<\/a><\/strong><\/p>\n<div id=\"combo-3676754692\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Deus EX: Mankind Divided foi uma investida da Square Enix \/ Eidos para tentar popularizar ainda mais a franquia Deus Ex, que \u00e9 velha de guerra no mundo dos games, mas nunca foi um jogo para a massa. Reconhecidamente uma franquia de alta qualidade desde os prim\u00f3rdios do jogo de 2000, o primeiro dessa grande [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":52545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,36,5,241,49,8],"tags":[349,298,14157,1901,7659,194],"class_list":["post-52542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-playstation","category-ps4","category-todas","category-xbox","category-xboxone","tag-crystal-dynamics","tag-deus-ex","tag-deus-ex-3","tag-eidos","tag-novo-deus-ex","tag-square"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deus EX: Franquia entra na geladeira da Square Enix ap\u00f3s baixo retorno e outros projetos - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/deus-ex-franquia-entra-na-geladeira-da-square-enix-apos-baixo-retorno-e-outros-projetos\/\" \/>\n<meta name=\"author\" content=\"Ariel Souza\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/deus-ex-franquia-entra-na-geladeira-da-square-enix-apos-baixo-retorno-e-outros-projetos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deus EX: Franquia entra na geladeira da Square Enix ap\u00f3s baixo retorno e outros projetos\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deus EX: Franquia entra na geladeira da Square Enix ap\u00f3s baixo retorno e outros projetos - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/deus-ex-franquia-entra-na-geladeira-da-square-enix-apos-baixo-retorno-e-outros-projetos\/","author":"Ariel Souza","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/deus-ex-franquia-entra-na-geladeira-da-square-enix-apos-baixo-retorno-e-outros-projetos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Deus EX: Franquia entra na geladeira da Square Enix ap\u00f3s baixo retorno e outros projetos"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/52542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=52542"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/52542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/52545"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=52542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=52542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=52542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}