{"id":60361,"date":"2017-05-18T14:34:32","date_gmt":"2017-05-18T17:34:32","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=60361"},"modified":"2017-05-18T14:34:32","modified_gmt":"2017-05-18T17:34:32","slug":"o-mago-das-mentiras-filme-da-hbo-com-robert-de-niro-e-michelle-pfeiffer-estreia-dia-20","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/o-mago-das-mentiras-filme-da-hbo-com-robert-de-niro-e-michelle-pfeiffer-estreia-dia-20\/","title":{"rendered":"O Mago das Mentiras: Filme da HBO com Robert de Niro e Michelle Pfeiffer estreia dia 20"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-60467\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"60467\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/05\/o-mago-das-mentiras-hbo-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em>Com dire\u00e7\u00e3o de Barry Levinson e roteiro de Sam Levinson, o longa vai ao ar \u00e0s 22h no canal HBO<\/em><\/p><div id=\"combo-1858370824\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Em 2008, o investidor e consultor financeiro Bernie Madoff ocupou as manchetes do mundo todo quando foi preso por ter cometido uma das maiores fraudes financeiras da hist\u00f3ria dos Estados Unidos. Com estreia no dia 20 de maio, \u00e0s 22h, a produ\u00e7\u00e3o da <strong>HBO Films O Mago das Mentiras<\/strong>\u00a0revela como funcionavam os investimentos no esquema de pir\u00e2mide de Bernie Madoff \u2013 suas fraudes, mentiras e trapa\u00e7as \u2013 e como sua mulher e seus filhos foram arrastados para o foco desse esc\u00e2ndalo.<\/p>\n<p><strong>Robert De Niro<\/strong> (ganhador do Oscar por Touro Indom\u00e1vel e O Poderoso Chef\u00e3o 2) estrela a sua primeira produ\u00e7\u00e3o da HBO como o patriarca Bernie Madoff. Tamb\u00e9m no seu primeiro trabalho na HBO,<strong> Michelle Pfeiffer<\/strong> (ganhadora do Globo de Ouro por Susie e os Baker Boys) interpreta Ruth Madoff, esposa de Bernie e parceira involunt\u00e1ria dos acontecimentos que levaram \u00e0 fal\u00eancia centenas de institui\u00e7\u00f5es e pessoas, bem como Bernie Madoff, e \u00e0 destrui\u00e7\u00e3o da sua fam\u00edlia.<\/p>\n<p>O filme tem dire\u00e7\u00e3o de <strong>Barry Levinson, <\/strong>o<strong>\u00a0<\/strong>roteiro \u00e9 de <strong>Sam Levinson, John Burnham Schwartz<\/strong> e Samuel Baum. O filme foi baseado no livro de Diana B. Henriques, que ficou na lista dos best-sellers do The New York Times em 2011.<\/p><div id=\"combo-2525559664\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Entre os protagonistas est\u00e3o ainda <em>Alessandro Nivola<\/em>, <em>Nathan Darrow, Kristen Connolly, Catherine Hooper, Hank Azaria<\/em> e<em> Diana B. Henriques.<\/em><\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Novo-Lateral-3 --><\/p>\n<p style=\"text-align: center;\"><em>Publicidade<\/em><\/p>\n<p><ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-client=\"ca-pub-1938377543971449\" data-ad-slot=\"7363221612\" data-ad-format=\"auto\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p><iframe title=\"O Mago Das Mentiras | HBO\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/yRZG2BRpGPQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-3186043789\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Com dire\u00e7\u00e3o de Barry Levinson e roteiro de Sam Levinson, o longa vai ao ar \u00e0s 22h no canal HBO Em 2008, o investidor e consultor financeiro Bernie Madoff ocupou as manchetes do mundo todo quando foi preso por ter cometido uma das maiores fraudes financeiras da hist\u00f3ria dos Estados Unidos. Com estreia no dia [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":60467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12311,241,9499],"tags":[10914,14814],"class_list":["post-60361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-tv-series","category-todas","category-tv-series","tag-hbo","tag-o-mago-das-mentiras"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Mago das Mentiras: Filme da HBO com Robert de Niro e Michelle Pfeiffer estreia dia 20 - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/o-mago-das-mentiras-filme-da-hbo-com-robert-de-niro-e-michelle-pfeiffer-estreia-dia-20\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/o-mago-das-mentiras-filme-da-hbo-com-robert-de-niro-e-michelle-pfeiffer-estreia-dia-20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Mago das Mentiras: Filme da HBO com Robert de Niro e Michelle Pfeiffer estreia dia 20\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Mago das Mentiras: Filme da HBO com Robert de Niro e Michelle Pfeiffer estreia dia 20 - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/o-mago-das-mentiras-filme-da-hbo-com-robert-de-niro-e-michelle-pfeiffer-estreia-dia-20\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/o-mago-das-mentiras-filme-da-hbo-com-robert-de-niro-e-michelle-pfeiffer-estreia-dia-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"O Mago das Mentiras: Filme da HBO com Robert de Niro e Michelle Pfeiffer estreia dia 20"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/60361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=60361"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/60361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/60467"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=60361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=60361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=60361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}