{"id":70226,"date":"2017-10-25T23:12:34","date_gmt":"2017-10-26T01:12:34","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=70226"},"modified":"2017-10-25T23:12:34","modified_gmt":"2017-10-26T01:12:34","slug":"game-of-thrones-existe-um-episodio-secreto-e-ele-nao-e-nada-bom-pra-jon-snow","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/game-of-thrones-existe-um-episodio-secreto-e-ele-nao-e-nada-bom-pra-jon-snow\/","title":{"rendered":"Game of Thrones: Existe um epis\u00f3dio secreto e ele n\u00e3o \u00e9 nada bom pra Jon Snow"},"content":{"rendered":"<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-70258\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"70258\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/game-of-thrones-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<h5 style=\"text-align: center;\">Game of Thrones possui um epis\u00f3dio secreto e ningu\u00e9m sabia. Nem Jon Snow, que n\u00e3o sabe de nada.<\/h5>\n<p>Como voc\u00ea controla <em>Jon Snow<\/em>? um guerreiro mestre aliado com drag\u00f5es? F\u00e1cil! \u00c9 s\u00f3 amea\u00e7ar liberar o piloto nunca revelado do <strong>Game of Thrones<\/strong>! Ao que parece, existe um epis\u00f3dio piloto da s\u00e9rie que foi filmado mas nunca revelado ou publicado, e que, segundo o ator que d\u00e1 vida a Jon Snow,<strong> Kit Harington<\/strong>, ele era tremendamente mau.<\/p><div id=\"combo-542564318\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Ent\u00e3o, por que Harington est\u00e1 t\u00e3o assustado? Bem, al\u00e9m do epis\u00f3dio ser &#8220;doloroso&#8221; para assistir, durante uma entrevista ao <strong>The Guardian<\/strong>, o ator revelou que usava uma peruca e n\u00e3o tinha a sua barba caracter\u00edstica, sem falar no ambiente, que n\u00e3o tinha nada a ver com o que a s\u00e9rie apresenta agora.\u00a0Harrington tamb\u00e9m acrescentou que toda a equipe n\u00e3o tinha certeza de como o sucesso da s\u00e9rie poderia ser.<\/p>\n<blockquote><p><em>&#8220;Estava cheio de erros, n\u00e3o parecia certo, n\u00e3o tinha o ambiente certo, era completamente diferente.&#8221;<\/em><\/p>\n<p><em>&#8220;N\u00f3s n\u00e3o sab\u00edamos se estava indo bem, e n\u00f3s n\u00e3o sab\u00edamos se isso seria bom. Mas era a HBO, e era a TV americana, ent\u00e3o sent\u00edamos\u00a0em um grande neg\u00f3cio&#8221;.<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<p>At\u00e9 hoje, acrescentou Harington, muitas pessoas n\u00e3o viram o piloto original, embora\u00a0disse ainda que os showrunners <strong>D.B. Weiss<\/strong> e <strong>David Benioff\u00a0<\/strong>usem a filmagem como uma esp\u00e9cie de chantagem de brincadeira contra o ator, caso ele os chateie demais:<\/p><div id=\"combo-1699714413\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<blockquote><p><em>&#8220;Eles dizem que se eu os irritar, v\u00e3o publicar o epis\u00f3dio no YouTube. \u00c0s vezes, enviam-me prints como amea\u00e7a.&#8221;<\/em><\/p><\/blockquote>\n<p>Nesse piloto gravado em 2009, as atrizes que interpretam Daenerys e Catelyn Stark eram diferentes. Algumas coisas s\u00e3o mais pr\u00f3ximas do livro, mas o ritmo \u00e9 totalmente diferente visto na tela.<\/p>\n<p>O ator acrescentou que acredita que a s\u00e9rie est\u00e1 terminando no momento certo, especialmente em reflex\u00e3o sobre o que fez seus come\u00e7os t\u00e3o especiais:<\/p>\n<blockquote><p><em>&#8220;Eu n\u00e3o gostaria de continuar por mais um ano, mas se tivesse terminado no ano passado, n\u00e3o teria sentido o suficiente. Talvez o ano mais especial tenha sido o primeiro. N\u00e3o est\u00e1vamos sendo reconhecidos na rua, n\u00e3o sab\u00edamos o que est\u00e1vamos fazendo, est\u00e1vamos\u00a0nos divertindo&#8221;.<\/em><\/p><\/blockquote>\n<p><strong>Game of Thrones<\/strong> vai retornar com a \u00faltima temporada somente em 2019.<\/p><div id=\"combo-294231719\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-1217947606\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Game of Thrones possui um epis\u00f3dio secreto e ningu\u00e9m sabia. Nem Jon Snow, que n\u00e3o sabe de nada. Como voc\u00ea controla Jon Snow? um guerreiro mestre aliado com drag\u00f5es? F\u00e1cil! \u00c9 s\u00f3 amea\u00e7ar liberar o piloto nunca revelado do Game of Thrones! Ao que parece, existe um epis\u00f3dio piloto da s\u00e9rie que foi filmado mas [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":70258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12311,241,9499],"tags":[3686,10329,10328,17125],"class_list":["post-70226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-tv-series","category-todas","category-tv-series","tag-game-of-thrones","tag-jon-snow","tag-kit-harington","tag-the-guardian"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Game of Thrones: Existe um epis\u00f3dio secreto e ele n\u00e3o \u00e9 nada bom pra Jon Snow - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/game-of-thrones-existe-um-episodio-secreto-e-ele-nao-e-nada-bom-pra-jon-snow\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/game-of-thrones-existe-um-episodio-secreto-e-ele-nao-e-nada-bom-pra-jon-snow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Game of Thrones: Existe um epis\u00f3dio secreto e ele n\u00e3o \u00e9 nada bom pra Jon Snow\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Game of Thrones: Existe um epis\u00f3dio secreto e ele n\u00e3o \u00e9 nada bom pra Jon Snow - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/game-of-thrones-existe-um-episodio-secreto-e-ele-nao-e-nada-bom-pra-jon-snow\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/game-of-thrones-existe-um-episodio-secreto-e-ele-nao-e-nada-bom-pra-jon-snow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Game of Thrones: Existe um epis\u00f3dio secreto e ele n\u00e3o \u00e9 nada bom pra Jon Snow"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/70226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=70226"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/70226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/70258"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=70226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=70226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=70226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}