{"id":70983,"date":"2017-11-07T19:11:31","date_gmt":"2017-11-07T21:11:31","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=70983"},"modified":"2017-11-07T19:11:31","modified_gmt":"2017-11-07T21:11:31","slug":"wb-games-anuncia-beta-aberto-de-injustice-2-para-pc","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-beta-aberto-de-injustice-2-para-pc\/","title":{"rendered":"WB Games anuncia data do beta aberto de Injustice 2 para PC"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/assets.vg247.com\/current\/\/2017\/01\/injustice_2_superman_artwork_crop_1.jpg\" alt=\"Injustice 2 para PC\" width=\"2462\" height=\"1416\" \/><\/p>\n<h5 style=\"text-align: center;\"><strong><em>Vers\u00e3o de Injustice 2 para PC est\u00e1 chegando!<\/em><\/strong><\/h5>\n<p>A <strong>Warner Bros<\/strong> anunciou a data de lan\u00e7amento e o in\u00edcio do beta aberto de <strong>Injustice 2<\/strong> para PC. Originalmente desenvolvido pela <strong>NetherRealm Studios<\/strong>, a adapta\u00e7\u00e3o do game para PCs est\u00e1 sendo feita pela <strong>QLOC<\/strong>.\u00a0Os f\u00e3s j\u00e1 podem participar do seu Beta aberto.<\/p><div id=\"combo-1338920638\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>O beta aberto estar\u00e1 dispon\u00edvel at\u00e9 o dia 10 de novembro. Na fase de testes, \u00e9 poss\u00edvel jogar apenas o modo multiplayer online 1v1. J\u00e1 a\u00a0vers\u00e3o final do game chega no dia 14, pr\u00f3xima ter\u00e7a-feira, e contar\u00e1 com o mesmo conte\u00fado dispon\u00edvel nos consoles.<\/p>\n<p>Injustice 2 possui uma enorme lista de Super-her\u00f3is e Supervil\u00f5es da DC. O jogo permite aos jogadores construir e utilizar uma vers\u00e3o personalizada de seus personagens DC favoritos. Assim como na vers\u00e3o para os consoles, ser\u00e1 poss\u00edvel participar de batalhas em um modo hist\u00f3ria, al\u00e9m de participar de guildas online &#8211; tudo para ganhar equipamentos raros e valiosos para personalizar completamente seus personagens.<\/p>\n<p><strong>Ed Boon<\/strong>, diretor criativo da NeatherRealm Studios, chegou a demonstrar interesse em desenvolver tamb\u00e9m uma vers\u00e3o do game para o <strong>Nintendo Switch<\/strong>, mas ainda n\u00e3o h\u00e1 nenhuma confirma\u00e7\u00e3o.<\/p><div id=\"combo-2707578795\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>O jogo est\u00e1 atualmente dispon\u00edvel para <strong>PlayStation 4<\/strong> e <strong>Xbox One<\/strong>. Leia a nossa an\u00e1lise completa sobre o jogo <a href=\"http:\/\/www.comboinfinito.com.br\/principal\/analise-injustice-2-com-muito-conteudo-jogo-consegue-ser-melhor-do-que-prometia\/\" target=\"_blank\" rel=\"noopener\"><strong>clicando aqui<\/strong><\/a>!<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<p><iframe title=\"Injustice 2: Story Trailer\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/9hklKfEEsxc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-1715935876\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Vers\u00e3o de Injustice 2 para PC est\u00e1 chegando! A Warner Bros anunciou a data de lan\u00e7amento e o in\u00edcio do beta aberto de Injustice 2 para PC. Originalmente desenvolvido pela NetherRealm Studios, a adapta\u00e7\u00e3o do game para PCs est\u00e1 sendo feita pela QLOC.\u00a0Os f\u00e3s j\u00e1 podem participar do seu Beta aberto. O beta aberto estar\u00e1 [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":59303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,241],"tags":[41,11843,5889,17278,3252],"class_list":["post-70983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-todas","tag-injustice","tag-injustice-2","tag-netherrealm-studios","tag-qloc","tag-warner-bros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WB Games anuncia data do beta aberto de Injustice 2 para PC - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Vers\u00e3o de Injustice 2 para PC est\u00e1 chegando! A Warner Bros anunciou a data de lan\u00e7amento e o in\u00edcio do beta aberto de Injustice 2 para PC\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-beta-aberto-de-injustice-2-para-pc\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/wb-games-anuncia-beta-aberto-de-injustice-2-para-pc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WB Games anuncia data do beta aberto de Injustice 2 para PC\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WB Games anuncia data do beta aberto de Injustice 2 para PC - Combo Infinito","description":"Vers\u00e3o de Injustice 2 para PC est\u00e1 chegando! A Warner Bros anunciou a data de lan\u00e7amento e o in\u00edcio do beta aberto de Injustice 2 para PC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-beta-aberto-de-injustice-2-para-pc\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-beta-aberto-de-injustice-2-para-pc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"WB Games anuncia data do beta aberto de Injustice 2 para PC"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/70983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=70983"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/70983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/59303"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=70983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=70983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=70983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}