{"id":71412,"date":"2017-11-17T13:02:39","date_gmt":"2017-11-17T15:02:39","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=71412"},"modified":"2017-11-17T13:02:39","modified_gmt":"2017-11-17T15:02:39","slug":"yu-gi-oh-duel-links-chega-ao-pc-steam-em-17-de-novembro","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/yu-gi-oh-duel-links-chega-ao-pc-steam-em-17-de-novembro\/","title":{"rendered":"Yu-Gi-Oh! Duel Links chega ao PC-Steam em 17 de novembro"},"content":{"rendered":"<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-71464 size-full\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links.jpg\" alt=\"Yu-Gi-Oh! Duel Links\" width=\"896\" height=\"504\" data-wp-pid=\"71464\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/11\/yugi-oh-duel-links-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<h5 style=\"text-align: center;\">Yu-Gi-Oh! Duel Links vai invadir o seu PC<\/h5>\n<p>A <strong>Konami\u00a0<\/strong>anuncia hoje que seu popular jogo m\u00f3vel<strong> Yu-Gi-Oh! Duel Links<\/strong> estar\u00e1 dispon\u00edvel gratuitamente para<strong>\u00a0PC<\/strong>\u00a0em 17 de novembro de 2017.<\/p><div id=\"combo-1823572629\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Baseado no jogo de cartas colecion\u00e1veis Yu-Gi-Oh! oficial, o <em>Yu-Gi-Oh! Duel Links<\/em> deu vida ao conhecido jogo em dispositivos m\u00f3veis e agora proporcionar\u00e1 a experi\u00eancia em PC. Os duelistas podem despertar o esp\u00edrito de Yami Yugi, Seto Kaiba e outros personagens em uma competitiva batalha de cartas. Na vers\u00e3o para PC, os jogadores poder\u00e3o recuperar suas pontua\u00e7\u00f5es da vers\u00e3o m\u00f3vel do jogo e duelar uns contra os outros jogadores das plataformas m\u00f3vel e PC.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<p>Desde seu lan\u00e7amento internacional em janeiro deste ano, o game j\u00e1 alcan\u00e7ou mais de 55 milh\u00f5es de downloads, chegando ao topo do ranking de aplicativos gratuitos na <strong>App Store<\/strong> e na <strong>Google Play.<\/strong><\/p><div id=\"combo-2762456598\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>A <strong>Konami<\/strong> lan\u00e7ou o primeiro jogo de console em 1998, e a s\u00e9rie, inclusive o jogo de cartas colecion\u00e1veis, ainda \u00e9 apreciada por in\u00fameros f\u00e3s do mundo todo. A empresa continua a desenvolver e distribuir uma s\u00e9rie de conte\u00fado de Yu-Gi-Oh! para levar a divers\u00e3o e emo\u00e7\u00e3o da s\u00e9rie mundialmente.<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=w4OvglAiI5c<\/p>\n<div id=\"combo-2174842694\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Yu-Gi-Oh! Duel Links vai invadir o seu PC A Konami\u00a0anuncia hoje que seu popular jogo m\u00f3vel Yu-Gi-Oh! Duel Links estar\u00e1 dispon\u00edvel gratuitamente para\u00a0PC\u00a0em 17 de novembro de 2017. Baseado no jogo de cartas colecion\u00e1veis Yu-Gi-Oh! oficial, o Yu-Gi-Oh! Duel Links deu vida ao conhecido jogo em dispositivos m\u00f3veis e agora proporcionar\u00e1 a experi\u00eancia em PC. [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":71464,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,241],"tags":[174,54,79,14084],"class_list":["post-71412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-todas","tag-konami","tag-pc","tag-steam","tag-yu-gi-oh-duel-links"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yu-Gi-Oh! Duel Links chega ao PC-Steam em 17 de novembro - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Yu-Gi-Oh! Duel Links \u00e9 um jogo baseado em um dos animes de maiores sucessos dos \u00faltimos tempos, Yu-Gi-Oh! Agora, o game estar\u00e1 dispon\u00edvel no PC-Steam\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/yu-gi-oh-duel-links-chega-ao-pc-steam-em-17-de-novembro\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/yu-gi-oh-duel-links-chega-ao-pc-steam-em-17-de-novembro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yu-Gi-Oh! Duel Links chega ao PC-Steam em 17 de novembro\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yu-Gi-Oh! Duel Links chega ao PC-Steam em 17 de novembro - Combo Infinito","description":"Yu-Gi-Oh! Duel Links \u00e9 um jogo baseado em um dos animes de maiores sucessos dos \u00faltimos tempos, Yu-Gi-Oh! Agora, o game estar\u00e1 dispon\u00edvel no PC-Steam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/yu-gi-oh-duel-links-chega-ao-pc-steam-em-17-de-novembro\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/yu-gi-oh-duel-links-chega-ao-pc-steam-em-17-de-novembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Yu-Gi-Oh! Duel Links chega ao PC-Steam em 17 de novembro"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/71412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=71412"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/71412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/71464"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=71412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=71412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=71412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}