{"id":73505,"date":"2017-12-19T00:43:38","date_gmt":"2017-12-19T02:43:38","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=73505"},"modified":"2017-12-19T00:43:38","modified_gmt":"2017-12-19T02:43:38","slug":"premiado-jogo-brasileiro-distortions-chega-dia-15-de-fevereiro","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/premiado-jogo-brasileiro-distortions-chega-dia-15-de-fevereiro\/","title":{"rendered":"Premiado jogo brasileiro, Distortions, chega dia 15 de fevereiro"},"content":{"rendered":"<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-69617 size-full\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4.jpg\" alt=\"Distortions\" width=\"896\" height=\"504\" data-wp-pid=\"69617\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2017\/10\/distortions-gameplay-4-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<h5 style=\"text-align: center;\"><em><strong>Distortions<\/strong> ter\u00e1 pr\u00e9-venda com experi\u00eancias e itens exclusivos \u00e0 partir de 8 de feveiro<\/em><\/h5>\n<p>A espera para o lan\u00e7amento de <a href=\"https:\/\/www.distortions.co\/\" target=\"_blank\" rel=\"noopener\"><strong>Distortions<\/strong><\/a> agora tem contagem regressiva definida. O premiado jogo independente brasileiro desenvolvido pela <strong>Among Giants<\/strong> ser\u00e1 lan\u00e7ado oficialmente no dia 15 de fevereiro de 2017.<\/p><div id=\"combo-2249907168\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Haver\u00e1 tamb\u00e9m uma pr\u00e9-venda limitada que come\u00e7ar\u00e1 no dia 8 de fevereiro.\u00a0Quem adquirir uma c\u00f3pia do game durante esse per\u00edodo ter\u00e1 acesso a uma experi\u00eancia exclusiva, que ser\u00e1 divulgada em breve. Al\u00e9m disso, ter\u00e1 a trilha sonora completa do jogo, novas roupas e um violino especial para a Menina. Essa experi\u00eancia inclui tamb\u00e9m o acesso ao <strong>Dev Room<\/strong>, sala onde os jogadores podem testar todas as mec\u00e2nicas e conhecer mais sobre o game.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<p>Vencedor do pr\u00eamio de Melhor Jogo Brasileiro de 2017 e de Melhor Jogo no Voto Popular no BIG Festival, o Distortions atraiu a aten\u00e7\u00e3o de milhares de jogadores. Somente em 2017, Distortions recebeu 6 pr\u00eamios nacionais e internacionais como o t\u00edtulo de <em>Melhor Ideia Original<\/em> no<strong> AZPlay Bilbao<\/strong> e o cobi\u00e7ado <em>Best of #BGS10<\/em> da <strong>Gamespot<\/strong>, sendo o \u00fanico jogo brasileiro a ter recebido esse pr\u00eamio at\u00e9 hoje.<\/p><div id=\"combo-1189789627\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Distortions ser\u00e1 lan\u00e7ado para<strong> PC<\/strong> pela<strong> Steam<\/strong> e <strong>Windows Store.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=65BmSrq7CQU<\/p>\n<div id=\"combo-2747701742\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Distortions ter\u00e1 pr\u00e9-venda com experi\u00eancias e itens exclusivos \u00e0 partir de 8 de feveiro A espera para o lan\u00e7amento de Distortions agora tem contagem regressiva definida. O premiado jogo independente brasileiro desenvolvido pela Among Giants ser\u00e1 lan\u00e7ado oficialmente no dia 15 de fevereiro de 2017. Haver\u00e1 tamb\u00e9m uma pr\u00e9-venda limitada que come\u00e7ar\u00e1 no dia 8 [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":69617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,241],"tags":[15364,15363,54,79,14384],"class_list":["post-73505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-todas","tag-among-giants","tag-distortions","tag-pc","tag-steam","tag-windows-store"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premiado jogo brasileiro, Distortions, chega dia 15 de fevereiro - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Distortions \u00e9 o jogo independente brasileiro que j\u00e1 foi bastante premiado. \u00c9 um game desenvolvido pela Among Giants e traz uma proposta interessante...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/premiado-jogo-brasileiro-distortions-chega-dia-15-de-fevereiro\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/premiado-jogo-brasileiro-distortions-chega-dia-15-de-fevereiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premiado jogo brasileiro, Distortions, chega dia 15 de fevereiro\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premiado jogo brasileiro, Distortions, chega dia 15 de fevereiro - Combo Infinito","description":"Distortions \u00e9 o jogo independente brasileiro que j\u00e1 foi bastante premiado. \u00c9 um game desenvolvido pela Among Giants e traz uma proposta interessante...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/premiado-jogo-brasileiro-distortions-chega-dia-15-de-fevereiro\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/premiado-jogo-brasileiro-distortions-chega-dia-15-de-fevereiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Premiado jogo brasileiro, Distortions, chega dia 15 de fevereiro"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/73505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=73505"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/73505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/69617"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=73505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=73505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=73505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}