{"id":74416,"date":"2018-01-10T13:04:35","date_gmt":"2018-01-10T15:04:35","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=74416"},"modified":"2018-01-10T13:04:35","modified_gmt":"2018-01-10T15:04:35","slug":"ces-2018-nvidia-anuncia-nova-geracao-de-monitores-em-formato-grande","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/ces-2018-nvidia-anuncia-nova-geracao-de-monitores-em-formato-grande\/","title":{"rendered":"CES 2018: NVIDIA anuncia nova gera\u00e7\u00e3o de monitores em formato grande"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-74516\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes.jpg\" alt=\"\" width=\"896\" height=\"504\" data-wp-pid=\"74516\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes-300x169.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes-768x432.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes-360x203.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes-790x444.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/nvidia-monitores-grandes-800x450.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/p>\n<h5 style=\"text-align: center;\"><strong><em>&#8220;BFGDs&#8221; integram as tecnologias NVIDIA G-SYNC e SHIELD para entregar experi\u00eancia de PC Gaming no primeiro monitor grande para PC<\/em><\/strong><\/h5>\n<p>A<strong> NVIDIA<\/strong> d\u00e1 ao<strong> PC Gaming<\/strong> um salto para uma tela grande, com a introdu\u00e7\u00e3o da tecnologia<strong> NVIDIA BFGD \u2013 Big Format Gaming Display<\/strong> (em portugu\u00eas: tela para games em formato grande).<\/p><div id=\"combo-1041300981\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Criados em conjunto com os parceiros de hardware da <strong>Acer<\/strong>, <strong>ASUS<\/strong> e a <strong>HP<\/strong>, os BFGDs integram uma tela 4K HDR com alta frequ\u00eancia de 120Hz e tecnologia NVIDIA G-SYNC, juntamente com o SHIELD, o dispositivo de transmiss\u00e3o via streaming mais avan\u00e7ado do mundo.<\/p>\n<p>Matt Wuebbling, diretor de marketing da GeForce na NVIDIA, comentou:<\/p>\n<blockquote><p><em>&#8220;Os jogadores de PC esperam um alto desempenho e tempos de resposta instant\u00e2neos, mas, at\u00e9 agora, eles foram amplamente limitados \u00e0s telas de desktop tradicionais. BFGDs mudam isso. Com a tecnologia mais recente da NVIDIA incorporada a essas novas telas, os jogadores de PC podem agora experimentar seus t\u00edtulos favoritos em toda a gl\u00f3ria e baixa lat\u00eancia que merecem&#8221;.<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p><div id=\"combo-639765747\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<h5><strong>No cora\u00e7\u00e3o da BFGD: G-SYNC HDR<\/strong><\/h5>\n<p>No cora\u00e7\u00e3o de BFGDs est\u00e1 a mais recente tecnologia G-SYNC HDR que sincroniza a taxa de atualiza\u00e7\u00e3o da tela com a do jogo em cada momento. Esta tecnologia de atualiza\u00e7\u00e3o vari\u00e1vel de quadros oferece uma experi\u00eancia de jogo imersiva altamente responsiva, suave e incompar\u00e1vel a qualquer tela desse tamanho. A tecnologia n\u00e3o sofre com efeito Tearing, que s\u00e3o rupturas verticais causadas pela falta de sincronismo vertical. Al\u00e9m disso, a tela de 4K HDR possui uma luz de fundo direta, com 1000-nits de lumin\u00e2ncia de pico e gama de cores DCI-P3 para obter a m\u00e1xima qualidade visual.<\/p>\n<h5><strong>Jogos de lat\u00eancia ultra baixa<\/strong><\/h5>\n<p>Nada \u00e9 mais importante para os jogadores do que uma jogabilidade responsiva. A tecnologia G-SYNC traz aos BFGDs a mesma lat\u00eancia ultra-baixa encontrada nos monitores de jogos de desktop. O G-SYNC para o BFGD est\u00e1 dispon\u00edvel para quem joga diretamente no <strong>PC, Android<\/strong>, ou durante o uso da tecnologia <strong>GameStream<\/strong> a partir de um PC ou notebook para jogos.<\/p>\n<h5><strong>Streaming de tela grande<\/strong><\/h5>\n<p>A integra\u00e7\u00e3o do SHIELD baseada em Android TV em BFGDs permite aos jogadores mudar facilmente entre jogos e outras formas de entretenimento. O controle remoto e controle de jogos SHIELD permite uma f\u00e1cil navega\u00e7\u00e3o e acesso a todos os maiores aplicativos de streaming do mundo, incluindo<strong> Netflix, Amazon Video, YouTube<\/strong>\u00a0e <strong>Hulu.<\/strong><\/p><div id=\"combo-2351639794\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Com suporte para o <em>Assistente do Google<\/em>, toda a experi\u00eancia pode ser controlada simplesmente usando sua voz. A tecnologia HDR G-SYNC tamb\u00e9m suporta a reprodu\u00e7\u00e3o de v\u00eddeo em framerates nativos, incluindo formatos populares como 23.976, 24 e 25 FPS. Isso sincroniza a taxa de atualiza\u00e7\u00e3o da tela \u00e0 taxa de quadros real da fonte do v\u00eddeo, eliminando a interpola\u00e7\u00e3o e apresentando o conte\u00fado do v\u00eddeo como foi idealizado pelo diretor.<\/p>\n<p><iframe title=\"BIG FORMAT GAMING DISPLAYS with NVIDIA G-SYNC\u2122 and SHIELD\u2122 BUILT-IN\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/XkReO19HXJU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-822697054\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &#8220;BFGDs&#8221; integram as tecnologias NVIDIA G-SYNC e SHIELD para entregar experi\u00eancia de PC Gaming no primeiro monitor grande para PC A NVIDIA d\u00e1 ao PC Gaming um salto para uma tela grande, com a introdu\u00e7\u00e3o da tecnologia NVIDIA BFGD \u2013 Big Format Gaming Display (em portugu\u00eas: tela para games em formato grande). Criados em [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":74516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[9514,241],"tags":[18164,18148,329,54,6673],"class_list":["post-74416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","category-todas","tag-bfgd-g-sync-hdr","tag-ces-2018","tag-nvidia","tag-pc","tag-pc-gaming"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CES 2018: NVIDIA anuncia nova gera\u00e7\u00e3o de monitores em formato grande - Combo Infinito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/ces-2018-nvidia-anuncia-nova-geracao-de-monitores-em-formato-grande\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/ces-2018-nvidia-anuncia-nova-geracao-de-monitores-em-formato-grande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CES 2018: NVIDIA anuncia nova gera\u00e7\u00e3o de monitores em formato grande\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CES 2018: NVIDIA anuncia nova gera\u00e7\u00e3o de monitores em formato grande - Combo Infinito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/ces-2018-nvidia-anuncia-nova-geracao-de-monitores-em-formato-grande\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/ces-2018-nvidia-anuncia-nova-geracao-de-monitores-em-formato-grande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"CES 2018: NVIDIA anuncia nova gera\u00e7\u00e3o de monitores em formato grande"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/74416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=74416"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/74416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/74516"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=74416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=74416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=74416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}