{"id":75476,"date":"2018-01-24T17:33:17","date_gmt":"2018-01-24T19:33:17","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=75476"},"modified":"2018-01-24T17:33:17","modified_gmt":"2018-01-24T19:33:17","slug":"lords-mobile-nova-atualizacao-chega-ao-brasil-com-muitas-novidades","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/lords-mobile-nova-atualizacao-chega-ao-brasil-com-muitas-novidades\/","title":{"rendered":"Lords Mobile: Nova atualiza\u00e7\u00e3o chega ao Brasil com muitas novidades"},"content":{"rendered":"<h5><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-75477\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile.jpg\" alt=\"\" width=\"896\" height=\"503\" data-wp-pid=\"75477\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile-300x168.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile-768x431.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile-360x202.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile-790x443.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/Lords-Mobile-800x449.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a><\/h5>\n<h5 style=\"text-align: center;\"><strong><em>Jogo de estrat\u00e9gia para celulares Lords Mobile traz ao Brasil a maior atualiza\u00e7\u00e3o de sua hist\u00f3ria<\/em><\/strong><\/h5>\n<p><strong>Lords Mobile<\/strong>, um MMO 3D de estrat\u00e9gia em tempo real, traz a sua maior e mais recente atualiza\u00e7\u00e3o para o Brasil. Agora os jogadores podem formar pactos com monstros m\u00e1gicos, encontrados pelo mundo, e utiliz\u00e1-los como poderosos guerreiros em seus ex\u00e9rcitos.<\/p><div id=\"combo-2791010907\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Com mais de 90 milh\u00f5es de jogadores ativos no mundo, Lords Mobile est\u00e1 dispon\u00edvel gratuitamente totalmente em portugu\u00eas para <strong>Android<\/strong> e<strong> iOS.<\/strong><\/p>\n<p>Silvio Junior, Country Manager da IGG no Brasil, conta como o Brasil entrou no mapa da IGG:<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p><div id=\"combo-3736355159\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u201cMuito antes de iniciarmos a opera\u00e7\u00e3o por aqui, Lordes e Ladies brasileiros j\u00e1 se aventuravam nos servidores mundiais. Todos enfrentando de igual para igual jogadores de todo o mundo. Gra\u00e7as a ado\u00e7\u00e3o em massa dos jogadores brasileiros, mesmo sem termos feito nenhum tipo de promo\u00e7\u00e3o em grande escala, a IGG decidiu investir no pa\u00eds. A opera\u00e7\u00e3o conta com equipe de suporte, comunidade e desenvolvimento de neg\u00f3cios e marketing. E 2018 promete muito mais! \u201d<\/em><\/p><\/blockquote>\n<p>Al\u00e9m dos elementos de estrat\u00e9gia, gerenciamento e constru\u00e7\u00e3o de cidades, o jogo possui gameplay tamb\u00e9m focado em her\u00f3is individuais, que atuam em fun\u00e7\u00f5es espec\u00edficas como guerreiros, arqueiros, magos e curandeiros. Estes her\u00f3is podem ser equipados, melhorados, e enviados para miss\u00f5es especiais, onde ir\u00e3o adquirir experi\u00eancia, itens e medalhas.<\/p>\n<p><iframe title=\"Lords Mobile - Official Trailer\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/tD50K-NvNSM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-1998111151\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Jogo de estrat\u00e9gia para celulares Lords Mobile traz ao Brasil a maior atualiza\u00e7\u00e3o de sua hist\u00f3ria Lords Mobile, um MMO 3D de estrat\u00e9gia em tempo real, traz a sua maior e mais recente atualiza\u00e7\u00e3o para o Brasil. Agora os jogadores podem formar pactos com monstros m\u00e1gicos, encontrados pelo mundo, e utiliz\u00e1-los como poderosos guerreiros em [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":75477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,18,16,12293,12294,12298,241],"tags":[8273,13874,96,13873],"class_list":["post-75476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-android","category-apple-ios","category-games","category-mobile","category-plataformas","category-todas","tag-android","tag-igg","tag-ios","tag-lords-mobile"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lords Mobile: Nova atualiza\u00e7\u00e3o chega ao Brasil com muitas novidades - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Lords Mobile, um MMO 3D de estrat\u00e9gia em tempo real, com elementos de RPG, desenvolvido e publicado pela empresa IGG, de Singapura, ganhou sua maior atualiza\u00e7\u00e3o para o Brasil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/lords-mobile-nova-atualizacao-chega-ao-brasil-com-muitas-novidades\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/lords-mobile-nova-atualizacao-chega-ao-brasil-com-muitas-novidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lords Mobile: Nova atualiza\u00e7\u00e3o chega ao Brasil com muitas novidades\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lords Mobile: Nova atualiza\u00e7\u00e3o chega ao Brasil com muitas novidades - Combo Infinito","description":"Lords Mobile, um MMO 3D de estrat\u00e9gia em tempo real, com elementos de RPG, desenvolvido e publicado pela empresa IGG, de Singapura, ganhou sua maior atualiza\u00e7\u00e3o para o Brasil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/lords-mobile-nova-atualizacao-chega-ao-brasil-com-muitas-novidades\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/lords-mobile-nova-atualizacao-chega-ao-brasil-com-muitas-novidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Lords Mobile: Nova atualiza\u00e7\u00e3o chega ao Brasil com muitas novidades"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/75476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=75476"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/75476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/75477"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=75476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=75476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=75476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}