{"id":75531,"date":"2018-01-28T13:20:32","date_gmt":"2018-01-28T15:20:32","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=75531"},"modified":"2018-01-28T13:20:32","modified_gmt":"2018-01-28T15:20:32","slug":"brasil-game-show-lanca-segunda-edicao-de-seu-livro-com-historia-completa-do-evento","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/brasil-game-show-lanca-segunda-edicao-de-seu-livro-com-historia-completa-do-evento\/","title":{"rendered":"BGS lan\u00e7a segunda edi\u00e7\u00e3o de seu livro com a hist\u00f3ria completa do evento"},"content":{"rendered":"<h5 style=\"text-align: center;\"><strong><em><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-75536\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro.jpg\" alt=\"\" width=\"896\" height=\"503\" data-wp-pid=\"75536\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro.jpg 896w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro-300x168.jpg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro-768x431.jpg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro-180x101.jpg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro-360x202.jpg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro-790x443.jpg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/01\/BGS-O-livro-800x449.jpg 800w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/a>\u00a0<\/em><\/strong><strong><em>Obra destaca a participa\u00e7\u00e3o de grandes \u00eddolos, bastidores da cria\u00e7\u00e3o do evento e sua evolu\u00e7\u00e3o<\/em><\/strong><\/h5>\n<p style=\"text-align: left;\">A<strong> BGS<\/strong> j\u00e1 se consolidou como o maior evento de games da Am\u00e9rica Latina e um dos principais do mundo. Em dez edi\u00e7\u00f5es, mais de 1,5 milh\u00e3o de visitantes passaram pela feira e puderam curtir milhares de jogos, atra\u00e7\u00f5es e ver grandes nomes da ind\u00fastria mundial.<\/p><div id=\"combo-1240885482\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Para reviver ou conhecer os momentos dessa feira, a BGS lan\u00e7a a edi\u00e7\u00e3o especial \u201c<strong>Brasil Game Show \u2013 o Livro\u201d<\/strong>.\u00a0Publicado pela <strong>Editora Europa<\/strong>, o livro conta com cap\u00edtulos sobre as dez edi\u00e7\u00f5es, textos em portugu\u00eas e ingl\u00eas, capa dura e diagrama\u00e7\u00e3o totalmente reformulada. Em edi\u00e7\u00e3o limitada, a nova obra j\u00e1 est\u00e1 dispon\u00edvel para compra pelo site<strong> www.brasilgameshow.com.br.<\/strong><\/p>\n<p>O livro tamb\u00e9m traz a hist\u00f3ria do empreendedorismo de <strong>Marcelo Tavares. <\/strong>O\u00a0criador da feira e um dos maiores colecionadores de games do Brasil comenta sobre o livro.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em>O artigo continua abaixo<\/em><\/p><div id=\"combo-2061839874\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"Middle1\"><\/div>\n<p>&nbsp;<\/p>\n<blockquote><p><em> \u201cNosso objetivo \u00e9 compartilhar n\u00e3o apenas os principais momentos do evento, mas tamb\u00e9m alguns epis\u00f3dios marcantes da hist\u00f3ria da ind\u00fastria no pa\u00eds. Nesta obra, o leitor acompanhar\u00e1 a primeira parte de um caminho longo que est\u00e1 longe de terminar.\u00a0A 11\u00aa edi\u00e7\u00e3o promete ser ainda melhor do que a \u00faltima e o come\u00e7o de um novo cap\u00edtulo\u201d<\/em><\/p><\/blockquote>\n<p>O primeiro lote de ingressos j\u00e1 est\u00e1 \u00e0 venda. At\u00e9 08\/02 \u00e9 poss\u00edvel adquiri-los com desconto de 50%. Mais informa\u00e7\u00f5es podem ser adquiridas no site oficial.<\/p>\n<p>Confira mais sobre o livro no v\u00eddeo abaixo:<\/p>\n<p><iframe title=\"NOVO LIVRO OFICIAL DA BRASIL GAME SHOW\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/IWTpfeQt1Mo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<div id=\"combo-2093499161\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0Obra destaca a participa\u00e7\u00e3o de grandes \u00eddolos, bastidores da cria\u00e7\u00e3o do evento e sua evolu\u00e7\u00e3o A BGS j\u00e1 se consolidou como o maior evento de games da Am\u00e9rica Latina e um dos principais do mundo. Em dez edi\u00e7\u00f5es, mais de 1,5 milh\u00e3o de visitantes passaram pela feira e puderam curtir milhares de jogos, atra\u00e7\u00f5es e [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":75536,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,5144,12293,241],"tags":[242,18498,18499],"class_list":["post-75531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-brasilgameshow","category-games","category-todas","tag-bgs","tag-brasil-game-show-o-livro","tag-marcelo-tavares"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BGS lan\u00e7a segunda edi\u00e7\u00e3o de seu livro com a hist\u00f3ria completa do evento - Combo Infinito<\/title>\n<meta name=\"description\" content=\"\u201cBrasil Game Show \u2013 o Livro\u201d j\u00e1 est\u00e1 \u00e0 venda! Obra destaca a participa\u00e7\u00e3o de grandes \u00eddolos do universo dos games na BGS, bastidores da cria\u00e7\u00e3o do evento e sua evolu\u00e7\u00e3o ano a ano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/brasil-game-show-lanca-segunda-edicao-de-seu-livro-com-historia-completa-do-evento\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/brasil-game-show-lanca-segunda-edicao-de-seu-livro-com-historia-completa-do-evento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BGS lan\u00e7a segunda edi\u00e7\u00e3o de seu livro com a hist\u00f3ria completa do evento\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BGS lan\u00e7a segunda edi\u00e7\u00e3o de seu livro com a hist\u00f3ria completa do evento - Combo Infinito","description":"\u201cBrasil Game Show \u2013 o Livro\u201d j\u00e1 est\u00e1 \u00e0 venda! Obra destaca a participa\u00e7\u00e3o de grandes \u00eddolos do universo dos games na BGS, bastidores da cria\u00e7\u00e3o do evento e sua evolu\u00e7\u00e3o ano a ano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/brasil-game-show-lanca-segunda-edicao-de-seu-livro-com-historia-completa-do-evento\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/brasil-game-show-lanca-segunda-edicao-de-seu-livro-com-historia-completa-do-evento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"BGS lan\u00e7a segunda edi\u00e7\u00e3o de seu livro com a hist\u00f3ria completa do evento"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/75531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=75531"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/75531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/75536"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=75531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=75531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=75531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}