{"id":78786,"date":"2018-03-12T23:38:54","date_gmt":"2018-03-13T02:38:54","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=78786"},"modified":"2018-03-12T23:38:54","modified_gmt":"2018-03-13T02:38:54","slug":"wb-games-anuncia-pre-cadastro-para-game-mobile-de-westworld","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-pre-cadastro-para-game-mobile-de-westworld\/","title":{"rendered":"WB Games anuncia pr\u00e9-cadastro para game mobile de Westworld"},"content":{"rendered":"<h5 style=\"text-align: center;\"><strong><em>O jogo baseado no seriado Westworld chega em abril deste ano<\/em><\/strong><\/h5>\n<p>A<strong> Warner Bros<\/strong>\u00a0anunciou hoje o pr\u00e9-cadastro para <strong>Westworld<\/strong>, seu pr\u00f3ximo jogo mobile baseado na s\u00e9rie original da <strong>HBO<\/strong>. Produzido pela <strong>WB Games San Francisco<\/strong> em colabora\u00e7\u00e3o com a <strong>Kilter Films<\/strong>, <strong>Westworld<\/strong> \u00e9 desenvolvido pela <strong>Behavior Interactive<\/strong>. O jogo ser\u00e1 lan\u00e7ado em abril para dispositivos <strong>iOS<\/strong> e <strong>Android<\/strong>.<\/p><div id=\"combo-2370221461\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>As equipes respons\u00e1veis pelo desenvolvimento do game est\u00e3o trabalhando junto aos produtores e escritores de <strong>Westworld<\/strong> para oferecer um jogo que aumente e complemente a hist\u00f3ria do seriado. No game, voc\u00ea assumir\u00e1 o papel de um estagi\u00e1rio da <em>Delos<\/em>, ao qual foi concedido acesso ao Delos Park Training Simulation (DPTS). No controle total da simula\u00e7\u00e3o, voc\u00ea assumir\u00e1 todas as opera\u00e7\u00f5es do parque <strong>Westworld<\/strong>. O jogador ter\u00e1 de operar a fabrica\u00e7\u00e3o e manuten\u00e7\u00e3o dos anfitri\u00f5es androides e a responsabilidade de deixar os convidados satisfeitos com a experi\u00eancia.<\/p>\n<p><strong>Jonathan Knight<\/strong>, vice-presidente da Studio Head, comentou:<\/p>\n<blockquote><p><em>&#8220;Este jogo \u00e9 uma oportunidade para dar aos jogadores uma maneira nova e emocionante de interagir com os temas que a s\u00e9rie explora. Mal podemos esperar para que os f\u00e3s entrem no jogo para desenvolverem sua pr\u00f3pria estrat\u00e9gia e controlarem seu pr\u00f3prio parque&#8221;.<\/em><\/p><\/blockquote>\n<p>Os jogadores que fizerem o pr\u00e9-registro v\u00e3o receber b\u00f4nus no lan\u00e7amento do game.<\/p><div id=\"combo-308167640\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>&nbsp;<\/p>\n<p><iframe title=\"Westworld - Mobile game - Teaser trailer ufficiale\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/FSUdA3G7sNg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-1567644150\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>O jogo baseado no seriado Westworld chega em abril deste ano A Warner Bros\u00a0anunciou hoje o pr\u00e9-cadastro para Westworld, seu pr\u00f3ximo jogo mobile baseado na s\u00e9rie original da HBO. Produzido pela WB Games San Francisco em colabora\u00e7\u00e3o com a Kilter Films, Westworld \u00e9 desenvolvido pela Behavior Interactive. O jogo ser\u00e1 lan\u00e7ado em abril para dispositivos [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":48058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,18,16,12293,12294,12298,241],"tags":[8273,10914,96,37,848,12973],"class_list":["post-78786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-android","category-apple-ios","category-games","category-mobile","category-plataformas","category-todas","tag-android","tag-hbo","tag-ios","tag-warner","tag-warner-games","tag-westworld"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WB Games anuncia pr\u00e9-cadastro para game mobile de Westworld - Combo Infinito<\/title>\n<meta name=\"description\" content=\"A Warner Bros\u00a0anuncia hoje o pr\u00e9-cadastro para Westworld, seu pr\u00f3ximo jogo mobile baseado na s\u00e9rie original da HBO. O jogo ser\u00e1 lan\u00e7ado em 2018 para dispositivos iOS e Android.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-pre-cadastro-para-game-mobile-de-westworld\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/wb-games-anuncia-pre-cadastro-para-game-mobile-de-westworld\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WB Games anuncia pr\u00e9-cadastro para game mobile de Westworld\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WB Games anuncia pr\u00e9-cadastro para game mobile de Westworld - Combo Infinito","description":"A Warner Bros\u00a0anuncia hoje o pr\u00e9-cadastro para Westworld, seu pr\u00f3ximo jogo mobile baseado na s\u00e9rie original da HBO. O jogo ser\u00e1 lan\u00e7ado em 2018 para dispositivos iOS e Android.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-pre-cadastro-para-game-mobile-de-westworld\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/wb-games-anuncia-pre-cadastro-para-game-mobile-de-westworld\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"WB Games anuncia pr\u00e9-cadastro para game mobile de Westworld"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/78786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=78786"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/78786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/48058"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=78786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=78786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=78786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}