{"id":80318,"date":"2018-04-10T08:40:10","date_gmt":"2018-04-10T11:40:10","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=80318"},"modified":"2018-04-10T08:40:10","modified_gmt":"2018-04-10T11:40:10","slug":"primeiro-mouse-da-hyperx-com-iluminacao-rgb-ja-esta-disponivel-no-brasil","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/primeiro-mouse-da-hyperx-com-iluminacao-rgb-ja-esta-disponivel-no-brasil\/","title":{"rendered":"Primeiro mouse da HyperX com ilumina\u00e7\u00e3o RGB j\u00e1 est\u00e1 dispon\u00edvel no Brasil"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em>Pulsefie Surge traz ilumina\u00e7\u00e3o RGB e resolu\u00e7\u00e3o personaliz\u00e1vel de at\u00e9 16.000 DPIs com sensor Pixart 3389<\/em><\/h5>\n<p>Os jogadores brasileiros acabam de ganhar uma nova op\u00e7\u00e3o de perif\u00e9rico de alta performance para ter mais precis\u00e3o, velocidade e conforto durante as partidas. \u00c9 o<strong> HyperX Pulsefire Surge,<\/strong> segundo mouse da <strong>HyperX\u00a0<\/strong>e o primeiro da marca com tecnologia RGB.<\/p><div id=\"combo-3125873111\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>O novo perif\u00e9rico tem switches Omron com vida \u00fatil de mais de 50 milh\u00f5es de cliques, excelente velocidade de resposta e muito resistente. Al\u00e9m disso, conta com ilumina\u00e7\u00e3o RGB que pode ser personalizada com o software <em>HyperX NGenuity<\/em>. Antes mesmo de seu lan\u00e7amento, o Pulsefire Surge conquistou o prestigiado pr\u00eamio Red Dot 2018 pelo seu design.<\/p>\n<p>O Pulsefire Surge vem com cinco configura\u00e7\u00f5es nativas de DPI que podem ser customizadas para at\u00e9 16.000 pontos por polegada, personalizando a prefer\u00eancia e o estilo individual dos jogadores. A mem\u00f3ria interna do mouse permite que o usu\u00e1rio personalize e salve, no pr\u00f3prio perif\u00e9rico, at\u00e9 tr\u00eas perfis de ilumina\u00e7\u00e3o. Al\u00e9m disso, \u00e9 poss\u00edvel escolher e programar o desempenho do sensor, as macros e a ilumina\u00e7\u00e3o em LED.<\/p>\n<p>Por fim, o Pulsefire Surge foi projetado para dar conforto ao usu\u00e1rio mesmo em longas sess\u00f5es de jogos. Al\u00e9m disso, tem um cabo tran\u00e7ado flex\u00edvel que possibilita movimentos mais suaves e garante maior durabilidade. O mouse tamb\u00e9m possui um design sim\u00e9trico confort\u00e1vel com grandes skates de deslizamento aprimorado que se adaptam bem a qualquer superf\u00edcie.<\/p><div id=\"combo-975061175\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<h5><strong>Disponibilidade<\/strong><\/h5>\n<p>O mouse j\u00e1 est\u00e1 \u00e0 venda com exclusividade de 30 dias no KaBuM! por R$ 299,90. O perif\u00e9rico tem garantia de dois anos, suporte t\u00e9cnico local gratuito e confiabilidade da marca.<\/p>\n<p><iframe title=\"Mouse Gaming RGB - HyperX Pulsefire Surge\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/uWaMmGoWuT4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<div id=\"combo-1351349860\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Pulsefie Surge traz ilumina\u00e7\u00e3o RGB e resolu\u00e7\u00e3o personaliz\u00e1vel de at\u00e9 16.000 DPIs com sensor Pixart 3389 Os jogadores brasileiros acabam de ganhar uma nova op\u00e7\u00e3o de perif\u00e9rico de alta performance para ter mais precis\u00e3o, velocidade e conforto durante as partidas. \u00c9 o HyperX Pulsefire Surge, segundo mouse da HyperX\u00a0e o primeiro da marca com tecnologia [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":80321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[9514,241],"tags":[11176,19572,54],"class_list":["post-80318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","category-todas","tag-hyper-x","tag-hyper-x-pulsefire-surge","tag-pc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primeiro mouse da HyperX com ilumina\u00e7\u00e3o RGB j\u00e1 est\u00e1 dispon\u00edvel no Brasil - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Jogadores brasileiros acabam de ganhar uma nova op\u00e7\u00e3o de perif\u00e9rico de alta performance para ter mais precis\u00e3o, velocidade e conforto durante as partidas. \u00c9 o HyperX Pulsefire Surge, segundo mouse da HyperX\u00a0e o primeiro da marca com tecnologia RGB.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/primeiro-mouse-da-hyperx-com-iluminacao-rgb-ja-esta-disponivel-no-brasil\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/primeiro-mouse-da-hyperx-com-iluminacao-rgb-ja-esta-disponivel-no-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primeiro mouse da HyperX com ilumina\u00e7\u00e3o RGB j\u00e1 est\u00e1 dispon\u00edvel no Brasil\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primeiro mouse da HyperX com ilumina\u00e7\u00e3o RGB j\u00e1 est\u00e1 dispon\u00edvel no Brasil - Combo Infinito","description":"Jogadores brasileiros acabam de ganhar uma nova op\u00e7\u00e3o de perif\u00e9rico de alta performance para ter mais precis\u00e3o, velocidade e conforto durante as partidas. \u00c9 o HyperX Pulsefire Surge, segundo mouse da HyperX\u00a0e o primeiro da marca com tecnologia RGB.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/primeiro-mouse-da-hyperx-com-iluminacao-rgb-ja-esta-disponivel-no-brasil\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/primeiro-mouse-da-hyperx-com-iluminacao-rgb-ja-esta-disponivel-no-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Primeiro mouse da HyperX com ilumina\u00e7\u00e3o RGB j\u00e1 est\u00e1 dispon\u00edvel no Brasil"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/80318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=80318"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/80318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/80321"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=80318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=80318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=80318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}