{"id":94761,"date":"2018-12-05T10:21:03","date_gmt":"2018-12-05T12:21:03","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=94761"},"modified":"2018-12-05T10:21:03","modified_gmt":"2018-12-05T12:21:03","slug":"oex-game-anuncia-gamepad-origin-gd100-controle-bluetooth-para-jogos-de-celular","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/oex-game-anuncia-gamepad-origin-gd100-controle-bluetooth-para-jogos-de-celular\/","title":{"rendered":"OEX Game anuncia Gamepad Origin GD100, controle bluetooth para jogos de celular"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em><strong>Controle bluetooth foi desenvolvido para jogos de celular<\/strong><\/em><\/h5>\n<p>A<strong> OEX Game<\/strong>, marca de acess\u00f3rios especializada no mercado de jogos, anuncia o lan\u00e7amento do<strong> Gamepad Origin GD100<\/strong>. O\u00a0controle conta com bluetooth desenvolvido para jogadores que buscam por mais conforto e precis\u00e3o em suas experi\u00eancias com games para <strong>Android<\/strong> e <strong>PC<\/strong>.<\/p><div id=\"combo-3442549623\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<h5><strong>Experi\u00eancia de console no Android:<\/strong><\/h5>\n<p>Sua conex\u00e3o bluetooth 2.4GHz, gatilhos, direcionais digitais, alavancas anal\u00f3gicas, e bot\u00f5es responsivos no formato ABXY; proporcionam nos jogos para Android a experi\u00eancia definitiva de um gamepad de console;Deste modo, evitam que jogadas ou progressos sejam perdidos por conta de respostas lentas ou imprecisas das telas Touch Screen. Al\u00e9m disso, o toque final, com acabamento emborrachado, garante mais ader\u00eancia, conforto, e uma pegada mais firme.<\/p>\n<p>Por fim, o controle tamb\u00e9m conta com um suporte para ser acoplado em smartphones, uma alternativa pr\u00e1tica para quem gosta de jogar games de corrida, luta, plataforma, e competitivos online. Assim, apesar de focar na experi\u00eancia de jogo mais completa para usu\u00e1rios de Android, as conex\u00f5es USB e Bluetooth do Origin GD100 tamb\u00e9m garantem sua compatibilidade com PCs, onde ele \u00e9 capaz de operar nas fun\u00e7\u00f5es de controle ou mouse.<\/p>\n<p><strong>Caracter\u00edsticas gerais do Gamepad Origin GD100:<\/strong><br \/>\n\u2022 Conex\u00e3o Bluetooth<br \/>\n\u2022 Frequ\u00eancia: 2.4GHZ<br \/>\n\u2022 Controle sem fio para Android (compat\u00edvel com PC)<br \/>\n\u2022 Opera em duas fun\u00e7\u00f5es: controle ou mouse<br \/>\n\u2022 Acabamento emborrachado<br \/>\n\u2022 Bateria de l\u00edtio embutida: 3.7V\/300mA<br \/>\n\u2022 Recarreg\u00e1vel via USB (cabo incluso)<br \/>\n\u2022 Possui LED indicador de carga<br \/>\n\u2022 4 bot\u00f5es superiores (2 gatilhos), alavancas e padr\u00e3o de bot\u00f5es ABXY<br \/>\n\u2022 Suporte incluso para acoplar o gamepad em smartphones Android<br \/>\n\u2022 Peso: 165g<br \/>\n\u2022 02 Anos de Garantia<\/p><div id=\"combo-900758510\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Por fim, o modelo est\u00e1 dispon\u00edvel nas principais lojas do pa\u00eds pelo pre\u00e7o sugerido de R$159,00<\/p>\n<div id=\"combo-2842475247\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Controle bluetooth foi desenvolvido para jogos de celular A OEX Game, marca de acess\u00f3rios especializada no mercado de jogos, anuncia o lan\u00e7amento do Gamepad Origin GD100. O\u00a0controle conta com bluetooth desenvolvido para jogadores que buscam por mais conforto e precis\u00e3o em suas experi\u00eancias com games para Android e PC. Experi\u00eancia de console no Android: Sua [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":94764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,18,12293,12294,25,12298,241],"tags":[24079,24078,24077],"class_list":["post-94761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-android","category-games","category-mobile","category-pcgames","category-plataformas","category-todas","tag-controle-bluetooth-oex-game","tag-gamepad-origin-gd100","tag-oex-game"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OEX Game anuncia Gamepad Origin GD100, controle bluetooth para jogos de celular - Combo Infinito<\/title>\n<meta name=\"description\" content=\"A OEX Game anuncia o lan\u00e7amento do Gamepad Origin GD100, o\u00a0controle com bluetooth desenvolvido para jogadores de Android e PC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/oex-game-anuncia-gamepad-origin-gd100-controle-bluetooth-para-jogos-de-celular\/\" \/>\n<meta name=\"author\" content=\"Julia Braz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/oex-game-anuncia-gamepad-origin-gd100-controle-bluetooth-para-jogos-de-celular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OEX Game anuncia Gamepad Origin GD100, controle bluetooth para jogos de celular\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OEX Game anuncia Gamepad Origin GD100, controle bluetooth para jogos de celular - Combo Infinito","description":"A OEX Game anuncia o lan\u00e7amento do Gamepad Origin GD100, o\u00a0controle com bluetooth desenvolvido para jogadores de Android e PC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/oex-game-anuncia-gamepad-origin-gd100-controle-bluetooth-para-jogos-de-celular\/","author":"Julia Braz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/oex-game-anuncia-gamepad-origin-gd100-controle-bluetooth-para-jogos-de-celular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"OEX Game anuncia Gamepad Origin GD100, controle bluetooth para jogos de celular"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/94761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=94761"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/94761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/94764"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=94761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=94761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=94761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}