{"id":95952,"date":"2018-12-24T17:10:17","date_gmt":"2018-12-24T19:10:17","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=95952"},"modified":"2018-12-24T17:58:36","modified_gmt":"2018-12-24T19:58:36","slug":"novo-mega-man-x-esta-sendo-feito-por-fas-confira-o-primeiro-trailer","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/novo-mega-man-x-esta-sendo-feito-por-fas-confira-o-primeiro-trailer\/","title":{"rendered":"Novo Mega Man X est\u00e1 sendo feito por f\u00e3s; Confira o primeiro trailer!"},"content":{"rendered":"<h5 style=\"text-align: center;\">F\u00e3s de Mega Man X apresentam um novo projeto independente<\/h5>\n<p>Em Outubro tivemos o retorno oficial de <strong>Mega Man<\/strong> em sua vers\u00e3o cl\u00e1ssica com o 11\u00ba t\u00edtulo numerado da franquia. Apesar de muitos terem gostado do game, o maior desejo de retorno dos f\u00e3s ainda gira em torno da saga X.<\/p><div id=\"combo-1889323248\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Sabendo disso, f\u00e3s da franquia da <strong>Capcom<\/strong> se reuniram e criaram o pr\u00f3prio projeto baseado em <strong>Mega Man X<\/strong>. Nomeado <strong>Maverick Hunter X: Giga Mission<\/strong>, o game explora o que seria uma nova adapta\u00e7\u00e3o, utilizando a base do <strong>Game Boy Color<\/strong>. Confira:<\/p>\n<p><iframe title=\"Maverick Hunter X: Giga Mission PV01 - Mega Man X 25th Anniversary Fan Project\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/Br9h6I-VrQI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>Como exibido, o projeto possui uma certa \u00eanfase nos confrontos do game, e na capacidade de utilizar aliados. H\u00e1 v\u00e1rios personagens dispon\u00edveis como auxiliares, e o dano pode vir bem a calhar nos confrontos. O projeto em si celebra o anivers\u00e1rio de <strong>25 anos<\/strong> da s\u00e9rie Mega Man X.<\/p>\n<p>Outro detalhe impressionante \u00e9 a arte dos personagens feita pelos f\u00e3s. O t\u00edtulo transmite uma certa credibilidade, e isso porque se aproxima bastante do que seria um projeto real da Capcom &#8211; anos atr\u00e1s. Mas dado o fato de que se trata de um projeto independente, pode ser que o t\u00edtulo nem veja a luz do dia&#8230;<\/p><div id=\"combo-1358418017\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Acima de tudo, nos resta aguardar por novidades ao longo do pr\u00f3ximo ano. Dado o porte do projeto, pode ser que ainda tenha um longo caminho pela frente. Em todo caso, \u00e9 sempre bom revisitar a s\u00e9rie Mega Man X.<\/p>\n<hr \/>\n<p>Fonte: <a href=\"https:\/\/www.youtube.com\/watch?v=Br9h6I-VrQI\" target=\"_blank\" rel=\"noopener\"><strong>YouTube<\/strong><\/a><\/p>\n<div id=\"combo-3267991740\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>F\u00e3s de Mega Man X apresentam um novo projeto independente Em Outubro tivemos o retorno oficial de Mega Man em sua vers\u00e3o cl\u00e1ssica com o 11\u00ba t\u00edtulo numerado da franquia. Apesar de muitos terem gostado do game, o maior desejo de retorno dos f\u00e3s ainda gira em torno da saga X. Sabendo disso, f\u00e3s da [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":95954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,22989,50,25,12298,36,241,49],"tags":[52,7946,10562,10315,17634,24549,24554,24553,24548,24550,21574,21575,21576,21577,21578,24551,21580,24552,24556,24555,21570],"class_list":["post-95952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-instagram","category-nintendo-2","category-pcgames","category-plataformas","category-playstation","category-todas","category-xbox","tag-capcom","tag-mega-man","tag-mega-man-11","tag-mega-man-capcom","tag-mega-man-x","tag-mega-man-x-fan-mande","tag-mega-man-x-reboot","tag-mega-man-x-remake","tag-mega-man-x-zero","tag-mega-man-x1","tag-mega-man-x2","tag-mega-man-x3","tag-mega-man-x4","tag-mega-man-x5","tag-mega-man-x6","tag-mega-man-x7","tag-mega-man-x8","tag-mega-man-x9","tag-new-mega-man-x","tag-novo-mega-man-x","tag-zero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novo Mega Man X est\u00e1 sendo feito por f\u00e3s; Confira o primeiro trailer! - Combo Infinito<\/title>\n<meta name=\"description\" content=\"F\u00e3s de Mega Man X est\u00e3o criando seu pr\u00f3prio projeto que parece promissor. Confira mais detalhes sobre Maverick Hunter X: Giga Mission.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/novo-mega-man-x-esta-sendo-feito-por-fas-confira-o-primeiro-trailer\/\" \/>\n<meta name=\"author\" content=\"Guru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/novo-mega-man-x-esta-sendo-feito-por-fas-confira-o-primeiro-trailer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novo Mega Man X est\u00e1 sendo feito por f\u00e3s; Confira o primeiro trailer!\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novo Mega Man X est\u00e1 sendo feito por f\u00e3s; Confira o primeiro trailer! - Combo Infinito","description":"F\u00e3s de Mega Man X est\u00e3o criando seu pr\u00f3prio projeto que parece promissor. Confira mais detalhes sobre Maverick Hunter X: Giga Mission.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/novo-mega-man-x-esta-sendo-feito-por-fas-confira-o-primeiro-trailer\/","author":"Guru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/novo-mega-man-x-esta-sendo-feito-por-fas-confira-o-primeiro-trailer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Novo Mega Man X est\u00e1 sendo feito por f\u00e3s; Confira o primeiro trailer!"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/95952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=95952"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/95952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/95954"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=95952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=95952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=95952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}