{"id":96026,"date":"2018-12-28T14:38:54","date_gmt":"2018-12-28T16:38:54","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=96026"},"modified":"2018-12-28T14:38:54","modified_gmt":"2018-12-28T16:38:54","slug":"star-wars-revelado-quem-e-o-pai-de-darth-vader","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/star-wars-revelado-quem-e-o-pai-de-darth-vader\/","title":{"rendered":"Star Wars: Revelado quem \u00e9 o \u201cpai\u201d de Darth Vader!"},"content":{"rendered":"<h5 style=\"text-align: center;\">O mist\u00e9rio por tr\u00e1s do nascimento de Darth Vader \u00e9 revelado em HQ de Star Wars<\/h5>\n<p>Conhecido por muitos como o maior conquistador gal\u00e1tico do Imp\u00e9rio, <strong>Darth Vader<\/strong> &#8211; ou Anakin Skywalker &#8211; foi o Jedi e Lord Sith mais promissor de toda saga <strong>Star Wars<\/strong>. Desde sua introdu\u00e7\u00e3o, o personagem ficou conhecido pelas cenas mais ic\u00f4nicas dos filmes. Al\u00e9m disso, a trama por tr\u00e1s de sua mudan\u00e7a revelada com o tempo foi uma das trajet\u00f3rias mais acompanhadas nos cinemas.<\/p><div id=\"combo-1510987125\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Entretanto, o nascimento de Skywalker permaneceu um mist\u00e9rio sem solu\u00e7\u00e3o &#8211; at\u00e9 o momento. Um novo quadrinho da saga can\u00f4nica de Vader enfim revelou o que houve por tr\u00e1s do dia em que Anakin foi concebido. Confira a imagem:<\/p>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-96028\" src=\"http:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader.jpeg\" alt=\"\" width=\"963\" height=\"482\" data-wp-pid=\"96028\" srcset=\"https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader.jpeg 963w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader-300x150.jpeg 300w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader-768x384.jpeg 768w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader-180x90.jpeg 180w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader-360x180.jpeg 360w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader-790x395.jpeg 790w, https:\/\/www.comboinfinito.com.br\/principal\/wp-content\/uploads\/2018\/12\/Star-Wars-Darth-Vader-800x400.jpeg 800w\" sizes=\"(max-width: 963px) 100vw, 963px\" \/><\/a><\/p>\n<p>Como exibido, Vader estava em seu castelo em <strong>Mustafar<\/strong>, tentando acessar a For\u00e7a atrav\u00e9s da poderosa conex\u00e3o do planeta com o Lado Negro. Ao avan\u00e7ar nas barreiras da conex\u00e3o, Vader se depara com momentos de sua vida, at\u00e9 sua estadia no castelo. Dentre estes momentos temos um em espec\u00edfico, que mostra a presen\u00e7a de <strong>Darth Sidious<\/strong> envolvendo <strong>Shmi Skywalker<\/strong>. Com isso, o antes conhecido como Senador Palpatine &#8220;<em>abra\u00e7a<\/em>&#8221; a m\u00e3e de Anakin com uma esp\u00e9cie de &#8220;<em>aura<\/em>&#8220;. Foi revelado ent\u00e3o que essa aura seria a concentra\u00e7\u00e3o das &#8220;<em>c\u00e9lulas Midi-Chlorians<\/em>&#8221; que resultaram no nascimento de Vader.<\/p>\n<p>Durante um dos epis\u00f3dios, a m\u00e3e de Skywalker conta a Qui-Gon Jin que o garoto n\u00e3o tinha um pai. Entretanto, o Jedi definiu que a concentra\u00e7\u00e3o das c\u00e9lulas de Anakin era maior do que qualquer outra j\u00e1 sentida.<\/p><div id=\"combo-1779275820\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Isso pode influenciar no entendimento do porque Skywalker ter sido t\u00e3o suscet\u00edvel ao lado negro da For\u00e7a. Como seria esperado de um &#8220;<em>her\u00f3i<\/em>&#8220;, o futuro de Anakin poderia ter terminado de outra maneira. Caso o mesmo tivesse sido fruto de outra concep\u00e7\u00e3o, seu caminho poderia estar mais inclinado ao outro lado.<\/p>\n<hr \/>\n<p>Fonte: <a href=\"https:\/\/comicbook.com\/starwars\/2018\/12\/21\/star-wars-darth-vader-anakin-skywalker-father-palpatine\/\" target=\"_blank\" rel=\"noopener\"><strong>ComicBook<\/strong><\/a><\/p>\n<div id=\"combo-3382122479\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>O mist\u00e9rio por tr\u00e1s do nascimento de Darth Vader \u00e9 revelado em HQ de Star Wars Conhecido por muitos como o maior conquistador gal\u00e1tico do Imp\u00e9rio, Darth Vader &#8211; ou Anakin Skywalker &#8211; foi o Jedi e Lord Sith mais promissor de toda saga Star Wars. Desde sua introdu\u00e7\u00e3o, o personagem ficou conhecido pelas cenas [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":96029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12312,9622,12313,241],"tags":[24622,24626,24627,24628,24629,24630,24631,24632,24624,24625,24636,9902,24634,24637,2791,24623,20668,16618,24635,24633],"class_list":["post-96026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-hq-manga","category-anime-hq-manga","category-quadrinhos","category-todas","tag-assistir-star-wars","tag-assistir-star-wars-episodio-1","tag-assistir-star-wars-episodio-2","tag-assistir-star-wars-episodio-3","tag-assistir-star-wars-episodio-4","tag-assistir-star-wars-episodio-5","tag-assistir-star-wars-episodio-6","tag-assistir-star-wars-episodio-7","tag-assistir-star-wars-os-ultimos-jedi","tag-assistir-star-wars-ultimos-jedi","tag-darth-sidious","tag-darth-vader","tag-ordem-de-star-wars","tag-palpatine","tag-star-wars","tag-star-wars-darth-vader","tag-star-wars-episodio","tag-star-wars-episodio-ix","tag-star-wars-ordem-de-lancamento","tag-star-wars-ordem-dos-filmes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Star Wars: Revelado quem \u00e9 o \u201cpai\u201d de Darth Vader! - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Quadrinho canone de Star Wars revela como Darth Vader realmente surgiu. Confira mais detalhes sobre o nascimento de um dos maiores vil\u00f5es do cinema!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/star-wars-revelado-quem-e-o-pai-de-darth-vader\/\" \/>\n<meta name=\"author\" content=\"Guru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/star-wars-revelado-quem-e-o-pai-de-darth-vader\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Star Wars: Revelado quem \u00e9 o \u201cpai\u201d de Darth Vader!\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Star Wars: Revelado quem \u00e9 o \u201cpai\u201d de Darth Vader! - Combo Infinito","description":"Quadrinho canone de Star Wars revela como Darth Vader realmente surgiu. Confira mais detalhes sobre o nascimento de um dos maiores vil\u00f5es do cinema!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/star-wars-revelado-quem-e-o-pai-de-darth-vader\/","author":"Guru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/star-wars-revelado-quem-e-o-pai-de-darth-vader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Star Wars: Revelado quem \u00e9 o \u201cpai\u201d de Darth Vader!"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/96026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=96026"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/96026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/96029"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=96026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=96026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=96026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}