{"id":96441,"date":"2019-01-09T03:00:48","date_gmt":"2019-01-09T05:00:48","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=96441"},"modified":"2019-01-09T10:49:30","modified_gmt":"2019-01-09T12:49:30","slug":"vingadores-ultimato-samuel-l-jackson-revela-grandioso-spoiler-do-filme","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/vingadores-ultimato-samuel-l-jackson-revela-grandioso-spoiler-do-filme\/","title":{"rendered":"Vingadores Ultimato: Samuel L. Jackson revela GRANDIOSO SPOILER do filme"},"content":{"rendered":"<h5 style=\"text-align: center;\">Aviso: Esta not\u00edcia pode conter um spoiler caprichado de Vingadores Ultimato, por cortesia de Samuel L. Jackson<\/h5>\n<p>Estamos cada vez mais pr\u00f3ximos da chegada de <strong>Vingadores: Ultimato<\/strong>, mas continuamos distantes de entender o que poder\u00e1 ocorrer no longa. H\u00e1 diversas teorias que apontam finais tr\u00e1gicos e boa parte delas envolve a famigerada viagem no tempo.<\/p><div id=\"combo-1814421019\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Por\u00e9m, Samuel L. Jackson parece ter perdido as estribeiras, e &#8220;<em>sem querer querendo<\/em>&#8221; revelou um poss\u00edvel spoiler monumental de Ultimato.<\/p>\n<p>De acordo com o ator ao conversar com o <strong>Entertainment Tonight<\/strong> sobre a <strong>Capit\u00e3 Marvel<\/strong>, ela \u00e9 &#8220;<em>uma das poucas pessoas no universo Marvel que pode viajar no tempo<\/em>&#8220;. Sim, ele disse isso em uma entrevista, e voc\u00ea confere o relato completo abaixo.<\/p>\n<blockquote><p>&#8220;<em>Ela \u00e9 basicamente a personagem mais forte &#8211; em termos de algu\u00e9m que tem o poder de fazer as coisas &#8211; no universo Marvel. Ent\u00e3o, para Carol Danvers se tornar essa pessoa, e para Brie<\/em> [Larson] <em>se tornar essa pessoa, ser\u00e1 uma coisa explosiva. Quero dizer, os Vingadores est\u00e3o enfrentando algumas disputas muito, muito pesadas no momento &#8211; n\u00f3s vimos isso em Guerra Infinita &#8211; ent\u00e3o agora sabemos que precisamos de algo t\u00e3o poderoso quanto Thanos. E em algum momento, n\u00f3s descobriremos o qu\u00e3o poderosa ela \u00e9 e todas as coisas que ela \u00e9 capaz. Ela \u00e9 uma das poucas pessoas no universo Marvel que pode viajar no tempo, ent\u00e3o&#8230;<\/em>&#8220;<\/p><\/blockquote>\n<p>Isso foi, em suma, Samuel L. Jackson confirmando que a Capit\u00e3 Marvel ter\u00e1 rela\u00e7\u00e3o com a viagem no tempo de Vingadores Ultimato. Al\u00e9m disso, tamb\u00e9m abre margem para especularmos que ela ir\u00e1 atr\u00e1s do Capit\u00e3o Am\u00e9rica, ou eles tentar\u00e3o encontra-la. N\u00e3o somente isso, como ao dizer que &#8220;eles precisam de algo t\u00e3o poderoso quanto Thanos&#8221; citando-a, sugere que veremos um embate feroz entre ambos no pr\u00f3ximo longa.<\/p><div id=\"combo-159841942\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Apesar de Mark Ruffalo previamente ter divulgado um &#8220;<em>spoiler falso<\/em>&#8220;, esse n\u00e3o parece ser o caso de Jackson.<\/p>\n<p>Vingadores: Ultimato chegar\u00e1 aos cinemas no dia <strong>25 de Abril<\/strong> deste ano.<\/p>\n<hr \/>\n<p>Fonte: <a href=\"https:\/\/www.comicbookmovie.com\/avengers\/avengers_endgame\/captain-marvel-star-samuel-l-jackson-may-have-dropped-a-major-spoiler-for-avengers-endgame-a165698\" target=\"_blank\" rel=\"noopener\"><strong>ComicBook<\/strong><\/a><\/p><div id=\"combo-810893216\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-994801448\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Aviso: Esta not\u00edcia pode conter um spoiler caprichado de Vingadores Ultimato, por cortesia de Samuel L. Jackson Estamos cada vez mais pr\u00f3ximos da chegada de Vingadores: Ultimato, mas continuamos distantes de entender o que poder\u00e1 ocorrer no longa. H\u00e1 diversas teorias que apontam finais tr\u00e1gicos e boa parte delas envolve a famigerada viagem no tempo. [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":96442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12310,9525,22989,241],"tags":[24869,24935,24816,23047,23484,23613,23588,24205,12956,24934,23485,24932,24933,12634,333,335,24220],"class_list":["post-96441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cinema","category-cinema-series-tv","category-instagram","category-todas","tag-assistir-capita-marvel","tag-assistir-capita-marvel-dublado","tag-assistir-vingadores-dublado","tag-assistir-vingadores-guerra-infinita","tag-assistir-vingadores-guerra-infinita-dublado","tag-assistir-vingadores-guerra-infinita-online","tag-assistir-vingadores-online","tag-avengers-endgame","tag-avengers-infinity-war","tag-baixar-capita-marvel","tag-baixar-vingadores","tag-baixar-vingadores-guerra-infinita","tag-baixar-vingadores-guerra-infinita-dublado","tag-capita-marvel","tag-marvel","tag-vingadores","tag-vingadores-ultimato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vingadores Ultimato: Samuel L. Jackson revela GRANDIOSO SPOILER do filme - Combo Infinito<\/title>\n<meta name=\"description\" content=\"O ator Samuel L. Jackson, que interpreta Nick Fury no universo cinematogr\u00e1fico da Marvel, pode ter revelado um grande spoiler de Vingadores: Ultimato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/vingadores-ultimato-samuel-l-jackson-revela-grandioso-spoiler-do-filme\/\" \/>\n<meta name=\"author\" content=\"Guru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/vingadores-ultimato-samuel-l-jackson-revela-grandioso-spoiler-do-filme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vingadores Ultimato: Samuel L. Jackson revela GRANDIOSO SPOILER do filme\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vingadores Ultimato: Samuel L. Jackson revela GRANDIOSO SPOILER do filme - Combo Infinito","description":"O ator Samuel L. Jackson, que interpreta Nick Fury no universo cinematogr\u00e1fico da Marvel, pode ter revelado um grande spoiler de Vingadores: Ultimato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/vingadores-ultimato-samuel-l-jackson-revela-grandioso-spoiler-do-filme\/","author":"Guru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/vingadores-ultimato-samuel-l-jackson-revela-grandioso-spoiler-do-filme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Vingadores Ultimato: Samuel L. Jackson revela GRANDIOSO SPOILER do filme"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/96441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=96441"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/96441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/96442"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=96441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=96441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=96441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}