{"id":96794,"date":"2019-01-17T14:44:39","date_gmt":"2019-01-17T16:44:39","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=96794"},"modified":"2019-01-17T14:44:39","modified_gmt":"2019-01-17T16:44:39","slug":"veja-o-primeiro-trailer-impressionante-de-john-wick-3","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/veja-o-primeiro-trailer-impressionante-de-john-wick-3\/","title":{"rendered":"Veja o primeiro trailer IMPRESSIONANTE de John Wick 3"},"content":{"rendered":"<h5 style=\"text-align: center;\">Keanu Reeves vai \u00e0 guerra no primeiro trailer oficial de John Wick 3<\/h5>\n<p>Desde que lan\u00e7ado seu primeiro filme, <strong>John Wick<\/strong> se destacou pela qualidade visual de suas cenas de a\u00e7\u00e3o e uma trama cativante. O personagem interpretado por <strong>Keanu Reeves<\/strong> logo se tornou popular entre o p\u00fablico. Consequentemente, j\u00e1 estamos a caminho do terceiro longa da jornada do ex-assassino.<\/p><div id=\"combo-3671298556\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Hoje (17), foi divulgado o primeiro trailer de <strong>John Wick Cap\u00edtulo 3: Parabellum<\/strong>. Confira:<\/p>\n<p>https:\/\/www.youtube.com\/watch?v=RnNEza1f_iU<\/p>\n<p>Pelo que vimos, n\u00e3o h\u00e1 escapat\u00f3ria para John. O assassino se encontra encurralado no meio de uma guerra, onde ele est\u00e1 &#8220;<em>sozinho<\/em>&#8221; no pr\u00f3prio lado. Ap\u00f3s ter sido expulso, e com a Ordem atr\u00e1s de sua cabe\u00e7a, s\u00f3 lhe restou fugir para o mais longe poss\u00edvel. Entretanto, n\u00e3o parece que o assassino se manter\u00e1 distante de todo o problema que est\u00e1 enfrentando.<\/p><div id=\"combo-1371473474\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>Pelo que vimos, a personagem de <strong>Halle Berry<\/strong> ser\u00e1 uma aliada importante no vindouro longa. Mas como sabemos, nem mesmo John se d\u00e1 ao luxo de confiar nos profissionais do ramo. O que sugere uma poss\u00edvel alian\u00e7a, por exemplo, \u00e9 o fato de que ambos possuem um la\u00e7o pr\u00e9vio. O filme tamb\u00e9m ir\u00e1 explorar partes do passado de John, e segundo o diretor, o protagonista &#8220;<em>sofrer\u00e1<\/em>&#8221; com isso.<\/p>\n<p>John Wick 3 chegar\u00e1 aos cinemas no dia <strong>17 de Maio<\/strong> deste ano.<\/p>\n<hr \/>\n<p>Fonte: <a href=\"https:\/\/www.youtube.com\/watch?v=RnNEza1f_iU\" target=\"_blank\" rel=\"noopener\"><strong>YouTube<\/strong><\/a><\/p><div id=\"combo-1766646317\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-448442311\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>Keanu Reeves vai \u00e0 guerra no primeiro trailer oficial de John Wick 3 Desde que lan\u00e7ado seu primeiro filme, John Wick se destacou pela qualidade visual de suas cenas de a\u00e7\u00e3o e uma trama cativante. O personagem interpretado por Keanu Reeves logo se tornou popular entre o p\u00fablico. Consequentemente, j\u00e1 estamos a caminho do terceiro [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":96796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12310,9525,241],"tags":[24612,24613,24614,24862,24891,14312,22389,16662,24615,25093,13769,20154],"class_list":["post-96794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-cinema","category-cinema-series-tv","category-todas","tag-assistir-john-wick","tag-assistir-john-wick-2","tag-assistir-john-wick-3","tag-assistir-john-wick-dublado","tag-assistir-john-wick-online","tag-john-wick","tag-john-wick-2","tag-john-wick-3","tag-john-wick-3-lancamento","tag-john-wick-assistir","tag-keanu-reeves","tag-novo-john-wick"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veja o primeiro trailer IMPRESSIONANTE de John Wick 3 - Combo Infinito<\/title>\n<meta name=\"description\" content=\"Foi divulgado um novo trailer excepcional de John Wick 3. Confira o v\u00eddeo com diversos destaques e detalhes sobre o vindouro longa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/veja-o-primeiro-trailer-impressionante-de-john-wick-3\/\" \/>\n<meta name=\"author\" content=\"Guru\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/veja-o-primeiro-trailer-impressionante-de-john-wick-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veja o primeiro trailer IMPRESSIONANTE de John Wick 3\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veja o primeiro trailer IMPRESSIONANTE de John Wick 3 - Combo Infinito","description":"Foi divulgado um novo trailer excepcional de John Wick 3. Confira o v\u00eddeo com diversos destaques e detalhes sobre o vindouro longa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/veja-o-primeiro-trailer-impressionante-de-john-wick-3\/","author":"Guru","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/veja-o-primeiro-trailer-impressionante-de-john-wick-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"Veja o primeiro trailer IMPRESSIONANTE de John Wick 3"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/96794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=96794"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/96794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/96796"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=96794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=96794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=96794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}