{"id":97171,"date":"2019-01-25T16:28:45","date_gmt":"2019-01-25T18:28:45","guid":{"rendered":"http:\/\/www.comboinfinito.com.br\/principal\/?p=97171"},"modified":"2019-01-25T16:28:45","modified_gmt":"2019-01-25T18:28:45","slug":"a-plague-tale-innocence-ganha-data-de-lancamento-e-novidades","status":"publish","type":"post","link":"https:\/\/www.comboinfinito.com.br\/principal\/a-plague-tale-innocence-ganha-data-de-lancamento-e-novidades\/","title":{"rendered":"A Plague Tale: Innocence ganha data de lan\u00e7amento e novidades"},"content":{"rendered":"<h5 style=\"text-align: center;\"><em>A Plague Tale: Innocence j\u00e1 tem data para chegar<\/em><\/h5>\n<p><a href=\"http:\/\/www.comboinfinito.com.br\/principal\/a-plague-tale-innocence-ganha-novas-imagens-com-visual-surpreendente-confira\/\" target=\"_blank\" rel=\"noopener\">O pouco comentado <strong>A Plague Tale: Innocence<\/strong><\/a> FINALMENTE ganhou sua devida aten\u00e7\u00e3o. Durante um recente v\u00eddeo, a <strong>Focus Home Interactive<\/strong> juntamente com a <strong>Asobo Studio<\/strong> revelaram mais detalhes sobre o t\u00edtulo e sua data de lan\u00e7amento.<\/p><div id=\"combo-1944310230\" class=\"combo-paragrafo-1-2 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>A princ\u00edpio, o v\u00eddeo se trata de um di\u00e1rio de desenvolvimento onde conhecemos os bastidores. Detalhes do game s\u00e3o revelados e os desenvolvedores explicam todo o contexto da aventura. O jogo se passar\u00e1 na <strong>Fran\u00e7a<\/strong> do S\u00e9culo 14 \u2013 o \u00e1pice da <strong>Peste Negra<\/strong>. Assim, neste cen\u00e1rio ca\u00f3tico, a hist\u00f3ria ir\u00e1 se concentrar em uma Jovem, <strong>Am\u00edcia<\/strong>, e seu irm\u00e3o, <strong>Hugo<\/strong>, que tentam sobreviver mediante a decad\u00eancia Francesa e as consequ\u00eancias da Peste Negra.<\/p>\n<p>Al\u00e9m da hist\u00f3ria, detalhes sobre o <em>gameplay<\/em> tamb\u00e9m foram revelados.\u00a0 Durante a jornada voc\u00ea poder\u00e1 encontrar outras crian\u00e7as onde as mesmas os ajudar\u00e3o na cria\u00e7\u00e3o de novas armas. Sobretudo, vale destacar, que o mais atrativo em A Plague Tale: Innocence \u00e9 sua atmosfera densa e a presen\u00e7a dos famigerados ratos, causadores da Peste.<\/p>\n<p>Sem mais delongas, confira o v\u00eddeo.<\/p><div id=\"combo-1054619012\" class=\"combo-paragrafo-3 combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<p>&nbsp;<\/p>\n<p><iframe title=\"A Plague Tale Webseries | Ep1 \u2013 Roots of Innocence\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/tArvEdvXg08?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>Em suma, A Plague Tale: Innocence chegar\u00e1 ao <strong>PS4<\/strong>, <strong>Xbox One<\/strong> e <strong>PC<\/strong> em 14 de Maio de 2019. Se n\u00e3o viu nada sobre o game confira o <em>gameplay<\/em> de 15 minutos do game abaixo e tire suas conclus\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe title=\"[GAMESCOM 2018] A  Plague Tale: Innocence - Uncut Gameplay Trailer\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/djmHcNBe1Z4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<p>Afinal, gostou do que viu? Deixe sua opini\u00e3o nos coment\u00e1rios.<\/p>\n<p>Fonte: <a href=\"https:\/\/www.youtube.com\/channel\/UCaLdl0827np4QVPESo794og\" target=\"_blank\" rel=\"noopener\"><strong>Youtube<\/strong><\/a><\/p><div id=\"combo-3307850348\" class=\"combo-conteudo combo-entity-placement\"><div style=\" margin: 10px auto;\">\r\n  <div style=\"text-align: center; \">\r\n    <span style=\"font-size: 10px; \">- PUBLICIDADE -<\/span>\r\n  <\/div>\r\n  <div class=\"pubad\" data-pos=\"LMR\" style=\"margin:0 auto; text-align: center; width: 336px; height: 280px;\"><\/div>\r\n<\/div><\/div>\n<div id=\"combo-2010323633\" class=\"combo-depois-do-conteudo combo-entity-placement\"><div id=\"target-outbrain\"><\/div>\r\n<!--OUTBRAIN-->\r\n<script type=\"text\/javascript\">\r\n\/*smartfeed*\/\r\ndocument.getElementById(\"target-outbrain\").insertAdjacentHTML('afterEnd','<div class=\"OUTBRAIN\" data-src='+ location.href +' data-widget-id=\"GS_4\"style =\"width:80%;margin:auto;\"><\/div>');\r\n<\/script>\r\n<script type=\"text\/javascript\" async=\"async\" src=\"\/\/widgets.outbrain.com\/outbrain.js\"><\/script>\r\n<!--OUTBRAIN--> <\/div>","protected":false},"excerpt":{"rendered":"<p>A Plague Tale: Innocence j\u00e1 tem data para chegar O pouco comentado A Plague Tale: Innocence FINALMENTE ganhou sua devida aten\u00e7\u00e3o. Durante um recente v\u00eddeo, a Focus Home Interactive juntamente com a Asobo Studio revelaram mais detalhes sobre o t\u00edtulo e sua data de lan\u00e7amento. A princ\u00edpio, o v\u00eddeo se trata de um di\u00e1rio de [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":95211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[12309,12293,25,12298,36,5,241,49,8],"tags":[15457,14132,1671,25300,25299,25298],"class_list":["post-97171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-games","category-pcgames","category-plataformas","category-playstation","category-ps4","category-todas","category-xbox","category-xboxone","tag-a-plague-tale-innocence","tag-focus-home","tag-focus-home-interactive","tag-historia-da-peste-negra","tag-peste-negra","tag-plague-tale-innocence"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Plague Tale: Innocence ganha data de lan\u00e7amento e novidades<\/title>\n<meta name=\"description\" content=\"O t\u00e3o pouco comentado A Plague Tale: Innocence FINALMENTE ganhou sua devida aten\u00e7\u00e3o. Durante um recente v\u00eddeo revelou sua data de lan\u00e7amento.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comboinfinito.com.br\/principal\/a-plague-tale-innocence-ganha-data-de-lancamento-e-novidades\/\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Ant\u00f4nio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/a-plague-tale-innocence-ganha-data-de-lancamento-e-novidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.comboinfinito.com.br\\\/principal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Plague Tale: Innocence ganha data de lan\u00e7amento e novidades\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Plague Tale: Innocence ganha data de lan\u00e7amento e novidades","description":"O t\u00e3o pouco comentado A Plague Tale: Innocence FINALMENTE ganhou sua devida aten\u00e7\u00e3o. Durante um recente v\u00eddeo revelou sua data de lan\u00e7amento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comboinfinito.com.br\/principal\/a-plague-tale-innocence-ganha-data-de-lancamento-e-novidades\/","author":"Jo\u00e3o Ant\u00f4nio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comboinfinito.com.br\/principal\/a-plague-tale-innocence-ganha-data-de-lancamento-e-novidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comboinfinito.com.br\/principal\/"},{"@type":"ListItem","position":2,"name":"A Plague Tale: Innocence ganha data de lan\u00e7amento e novidades"}]}]}},"_links":{"self":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/97171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/comments?post=97171"}],"version-history":[{"count":0,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/posts\/97171\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media\/95211"}],"wp:attachment":[{"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/media?parent=97171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/categories?post=97171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comboinfinito.com.br\/principal\/wp-json\/wp\/v2\/tags?post=97171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}